{"id":41080,"date":"2023-05-10T18:49:43","date_gmt":"2023-05-10T16:49:43","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=41080"},"modified":"2023-05-10T18:49:46","modified_gmt":"2023-05-10T16:49:46","slug":"hr-operations-support-cat-8-h-f","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/hr-operations-support-cat-8-h-f\/","title":{"rendered":"HR Operations Support (Cat 8): (H\/F)"},"content":{"rendered":"\n<p>Description:<\/p>\n\n\n\n<p>HR Operations Support (Cat 8): Externe\/Interne<br>(H\/F)<\/p>\n\n\n\n<p>Sous la supervision de l&rsquo;Administration,<br>Compensation and Benefits Supervisor, le HR<br>Operations Support aura pour missions:<\/p>\n\n\n\n<ul><li>D&rsquo;interagir avec les soci\u00e9t\u00e9s de mise \u00e0<br>disposition du personnel et les Op\u00e9rateurs de<br>t\u00e9l\u00e9phonie ;<\/li><li>D&rsquo;assurer la gestion des dotations sociales ;<\/li><li>D&rsquo;assurer la gestion des missions (d\u00e9placement<br>professionnels) du personnel ;<\/li><li>D&rsquo;assurer le suivi des cong\u00e9s et absences<br>du personnel ;<\/li><li>D&rsquo;assurer la gestion des tableaux de bord RH.<\/li><\/ul>\n\n\n\n<p>Que Ferez-vous?<\/p>\n\n\n\n<ol><li>Assister le HRBP dans le recrutement des<br>ressources en partenariat avec les soci\u00e9t\u00e9s de mise<br>\u00e0 disposition;<\/li><li>Assurer la gestion courante de la main d&rsquo;\u0153uvre<br>temporaire selon les proc\u00e9dures et la<br>r\u00e8glementation en vigueur ;<\/li><li>V\u00e9rifier la conformit\u00e9 des factures des soci\u00e9t\u00e9s<br>de mise \u00e0 disposition et transmettre pour validation<br>au sup\u00e9rieur hi\u00e9rarchique ;<\/li><\/ol>\n\n\n\n<ol start=\"4\"><li>Faire les commandes des dotations mensuelles<br>au personnel et faire le suivi des stocks;<\/li><li>Imprimer les bons de sortie pour dotation et<br>soumettre \u00e0 la signature de la hi\u00e9rarchie ;<\/li><li>Assurer la gestion de la flotte t\u00e9l\u00e9phonique en<br>assurant les incorporations, les retraits et les<br>modifications \u00e0 faire chez les partenaires ;<\/li><li>Assurer la gestion administrative des missions<br>(d\u00e9placements professionnels) du personnel en<br>\u00e9tablissant les ordres de missions, les fiches de<br>frais;<\/li><li>Recevoir les demandes de cong\u00e9s, v\u00e9rifier la<br>coh\u00e9rence des informations et \u00e9tablir les lettres de<br>cong\u00e9s apr\u00e8s validation de la hi\u00e9rarchie ;<\/li><li>Assurer la gestion des tickets de cantine : faire la<br>commande des carnets et g\u00e9rer les stocks ;<\/li><li>Elaborer les tableaux de suivi des principaux<br>indicateur RH (heures suppl\u00e9mentaires sur Masse<br>Salariale, turn-over, absent\u00e9isme, headcount) et faire<br>les reportings.<\/li><\/ol>\n\n\n\n<p>Quel sera votre Apport ?<\/p>\n\n\n\n<p>Comp\u00e9tences : BAC+2 OU BAC+3 en Sciences<br>de Gestion, RH ou Sciences Sociales et une<br>exp\u00e9rience d&rsquo;au moins 2 ans dans la gestion<br>administrative du personnel<\/p>\n\n\n\n<p>Exigences particuli\u00e8res :<\/p>\n\n\n\n<p>e Connaissances informatiques notamment, le<br>traitement de texte, les tableurs, les bases de<br>donn\u00e9es ;<\/p>\n\n\n\n<p>e Respect des d\u00e9lais, rigueur, efficacit\u00e9,<\/p>\n\n\n\n<p>e Respect des d\u00e9lais, rigueur, efficacit\u00e9,<br>int\u00e9grit\u00e9, discr\u00e9tion, orient\u00e9 r\u00e9sultats ;<br>e Bonne maitrise de l&rsquo;anglais et du fran\u00e7ais.<\/p>\n\n\n\n<p>Comment Postuler :<\/p>\n\n\n\n<p>Envoyez vos CVs \u00e0 l&rsquo;adresse :<br>https:\/\/ats.talenteo.com\/job-<br>apply\/7e5b83c677fd595b8ae7<\/p>\n\n\n\n<p>Date de Cl\u00f4ture de r\u00e9ception des dossiers:<br>17\/05\/2023<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Description: HR Operations Support (Cat 8): Externe\/Interne(H\/F) Sous la supervision de l&rsquo;Administration,Compensation and Benefits Supervisor, le HROperations Support aura pour missions: D&rsquo;interagir avec les soci\u00e9t\u00e9s&#8230;<\/p>\n","protected":false},"author":63,"comment_status":"open","ping_status":"closed","template":"","categories":[20],"tags":[],"villes":[2714],"contrats":[234],"diplomes":[248],"louma_meta":{"emploi_title":"HR Operations Support (Cat 8): Externe\/Interne (H\/F)","emplois_employeur":5282,"emplois_date_publication":"2023-05-10","emplois_heure_publication":"","emplois_date_cloture":"2023-05-17","emplois_heure_cloture":"","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"https:\/\/ats.talenteo.com\/job- apply\/7e5b83c677fd595b8ae7"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/41080"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=41080"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/41080\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/5283"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=41080"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=41080"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=41080"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=41080"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=41080"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=41080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}