{"id":40949,"date":"2023-05-05T14:43:27","date_gmt":"2023-05-05T12:43:27","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=40949"},"modified":"2023-05-05T14:43:29","modified_gmt":"2023-05-05T12:43:29","slug":"commerciaux-en-freelance","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/commerciaux-en-freelance\/","title":{"rendered":"Commerciaux en Freelance"},"content":{"rendered":"\n<p><strong>Villes<\/strong>\u00a0: Douala, Yaound\u00e9, Bafoussam, Bu\u00e9a, Kribi, Bamenda, Limb\u00e9, Bertoua, Garoua, Ngaound\u00e9r\u00e9, Maroua,<\/p>\n\n\n\n<p>Vous voulez arrondir vos fins de mois, vous \u00eates dynamiques, vous \u00eates passionn\u00e9s par l\u2019art et la d\u00e9coration murale et avez des connaissances en vente et prospection, venez vous faire beaucoup d\u2019argent en proposant nos <strong>Tableaux d\u00e9coratifs<\/strong> et <strong>personnalis\u00e9s<\/strong> \u00e0 vos proches, amis et connaissances et \u00e0 d\u2019autres cibles telles que les h\u00f4tels, les studios et appartements meubl\u00e9s, restaurants, et bien d\u2019autres. <\/p>\n\n\n\n<p>Il s\u2019agit d\u2019un emploi <strong>100% \u00e0 distance<\/strong> que vous pouvez exercer depuis votre <strong>domicile<\/strong>. Ce partenariat vous permettra d\u2019\u00eatre notre repr\u00e9sentant dans la ville et \u00eatre votre <strong>propre patron<\/strong>. Un business <strong>sans pression<\/strong>. Vous gagnerez un revenu auquel vous ne vous attendez pas.<\/p>\n\n\n\n<p>Vous b\u00e9n\u00e9ficierez de notre approche commerciale et nos techniques de vente pour d\u00e9velopper votre chiffre d\u2019affaire et contr\u00f4ler votre secteur.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Missions :<\/strong><\/p>\n\n\n\n<ul><li>Prospection en ligne, sur les r\u00e9seaux sociaux<\/li><li>Prospecter les H\u00f4tels, les meubl\u00e9s, les restaurants, les particuliers et vos proches<\/li><li>Gestion des commandes et livraison des clients.<\/li><\/ul>\n\n\n\n<p><strong>Profil<\/strong>: Commercial en Freelance<\/p>\n\n\n\n<ul><li>Avoir une bonne culture du web et des r\u00e9seaux sociaux (Facebook, whatsapp et autres.)<\/li><li>Aucun dipl\u00f4me requis<\/li><li>Exp\u00e9rience dans le domaine de la d\u00e9coration est un atout<\/li><li>Bonne ma\u00eetrise de la ville dans laquelle il se trouve.<\/li><\/ul>\n\n\n\n<p><strong>Contactez-nous<\/strong>&nbsp;:<\/p>\n\n\n\n<p>Envoyez-nous votre candidature \u00e0 <a href=\"mailto:domainepofal@gmail.com\">domainepofal@gmail.com<\/a> tout en pr\u00e9cisant les motivations qui vous poussent \u00e0 vous lancer dans le domaine de la d\u00e9coration d\u2019int\u00e9rieur.<\/p>\n\n\n\n<p>D\u00e9lai&nbsp;: 08 Mai<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via domainepofal@gmail.com<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[251],"tags":[],"villes":[2714],"contrats":[149],"diplomes":[156],"louma_meta":{"emploi_title":"Commerciaux en Freelance","emplois_employeur":40935,"emplois_date_publication":"2023-05-05","emplois_heure_publication":"13:43","emplois_date_cloture":"2023-05-08","emplois_heure_cloture":"17:00","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"domainepofal@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/40949"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=40949"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/40949\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/40936"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=40949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=40949"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=40949"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=40949"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=40949"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=40949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}