{"id":40776,"date":"2023-05-02T11:21:37","date_gmt":"2023-05-02T09:21:37","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=40776"},"modified":"2023-05-02T11:21:40","modified_gmt":"2023-05-02T09:21:40","slug":"vendeurse","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/vendeurse\/","title":{"rendered":"Vendeur(se)"},"content":{"rendered":"\n<p>Description de l&rsquo;entreprise<\/p>\n\n\n\n<p>La soci\u00e9t\u00e9 SECODI SARL est une entreprise commerciale ouverte depuis 2009.<br>Le si\u00e8ge est \u00e0 Douala Akwa et avec une autre repr\u00e9sentation au march\u00e9<br>Mboppi. Une ouverture imminente d&rsquo;une showroom \u00e0 Bonapriso.<\/p>\n\n\n\n<p>Sp\u00e9cialis\u00e9es dans le commerce en gros et en d\u00e9tail des fournitures scolaire &amp;<br>bureautique,Papeterie, Appareillage et machine, Bazar, Produits festifs,<br>Bagagerie (Travel et Business), Jouets et Librairie scolaire.<\/p>\n\n\n\n<p>Missions<\/p>\n\n\n\n<ul><li>Dans le cadre du d\u00e9veloppement de ses activit\u00e9s, Secodi est \u00e0 la<br>recherche de 4 vendeur (se)s. Votre r\u00f4le sera d&rsquo;\u00eatre les ambassadeur<br>(rice)s d&rsquo;une marque opulente et exigeante, l&rsquo;entreprise tient \u00e0<br>d\u00e9livrer une exp\u00e9rience client optimis\u00e9e \u00e0 travers de la vente<br>omnicanale. Les candidates devront donc pr\u00e9senter une parfaite<br>ma\u00eetrise de la langue fran\u00e7aise (anglais \u00e9tant un atout),<\/li><li>Principales missions:<br>o La vente<br>o Accueillir, orienter et conseiller la client\u00e8le<br>Assurer la tenue et l&rsquo;entretien l&rsquo;espace de vente<br>Assurer la r\u00e9ception des stocks de marchandise et la tenue des<br>inventaires<br>o Assurer l&rsquo;encaissement et facturation<\/li><\/ul>\n\n\n\n<p>\u00b0.o<\/p>\n\n\n\n<ul><li>Profil recherch\u00e9:<br>o Femme\/homme entre 25 et 35 ans<br>o Niveau BACC minimum<\/li><li>237 698421749 <\/li><li>INFO@SECODICAMEROUN.NET<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Description de l&rsquo;entreprise La soci\u00e9t\u00e9 SECODI SARL est une entreprise commerciale ouverte depuis 2009.Le si\u00e8ge est \u00e0 Douala Akwa et avec une autre repr\u00e9sentation au&#8230;<\/p>\n","protected":false},"author":63,"comment_status":"open","ping_status":"closed","template":"","categories":[1273],"tags":[],"villes":[135],"contrats":[148],"diplomes":[162],"louma_meta":{"emploi_title":"Vendeur(se)","emplois_employeur":40771,"emplois_date_publication":"2023-05-02","emplois_heure_publication":"","emplois_date_cloture":"2023-05-16","emplois_heure_cloture":"","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"INFO@SECODICAMEROUN.NET"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/40776"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=40776"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/40776\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/40773"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=40776"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=40776"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=40776"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=40776"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=40776"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=40776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}