{"id":40742,"date":"2023-05-01T13:41:43","date_gmt":"2023-05-01T11:41:43","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=40742"},"modified":"2023-05-01T13:41:46","modified_gmt":"2023-05-01T11:41:46","slug":"digital-marketer-et-commerciaux","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/digital-marketer-et-commerciaux\/","title":{"rendered":"Digital Marketer et Commerciaux"},"content":{"rendered":"\n<p>Pour soutenir le d\u00e9veloppement de ses op\u00e9rations de prestation de service et consultation dans la ville de Yaound\u00e9, La soci\u00e9t\u00e9 AGTX recrute des Digital Marketer et Commerciaux \u00e0 temps partiel.<\/p>\n\n\n\n<p>Les principales missions :<\/p>\n\n\n\n<ul><li>Prospecter, promouvoir, vendre et livrer les produits aupr\u00e8s des clients cibles ;<\/li><li>D\u00e9velopper et fid\u00e9liser le portefeuille client<\/li><\/ul>\n\n\n\n<p><strong>Le profil recherch\u00e9 :<\/strong><\/p>\n\n\n\n<ul><li>\u00catre \u00e2g\u00e9 de moins de 35 ans ;<\/li><li>Avoir au moins le baccalaur\u00e9at ;<\/li><li>\u00catre \u00e9tudiant scolaris\u00e9 dans une institution d&rsquo;enseignement sup\u00e9rieur de la place<\/li><li>\u00catre polyvalent, rigoureux, organis\u00e9, honn\u00eate, de bonne moralit\u00e9, ponctuel, professionnel, proactif, avoir de bonne capacit\u00e9 relationnel, avoir une bonne aptitude d\u2019adaptation<\/li><li>\u00catre disponible et capable de travailler sous pression ;<\/li><li>\u00catre bilingue serait un atout suppl\u00e9mentaire<\/li><\/ul>\n\n\n\n<p><strong>Constitution du dossier<\/strong><\/p>\n\n\n\n<p>CV et lettre de motivation \u00e0 adresser par messagerie \u00e9lectronique \u00e0 :&nbsp;<a href=\"mailto:dev.agtx@gmail.com\"><strong>dev.agtx@gmail.com<\/strong><\/a>&nbsp;ou par whatsapp au 680027705<\/p>\n\n\n\n<p><strong>La date limite de candidature est fix\u00e9e au Mercredi 03 Mai 2023.<\/strong><\/p>\n\n\n\n<p>NB: Ne donnez jamais de l&rsquo;argent durant un processus de recrutement. Le m\u00e9decin du travail s&rsquo;occupe uniquement des employ\u00e9s de l&rsquo;entreprise.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via \u00a0dev.agtx@gmail.com\u00a0<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[22],"tags":[],"villes":[136],"contrats":[236],"diplomes":[212,159],"louma_meta":{"emploi_title":"Digital Marketer et Commerciaux","emplois_employeur":3046,"emplois_date_publication":"2023-05-01","emplois_heure_publication":"12:41","emplois_date_cloture":"2023-05-03","emplois_heure_cloture":"17:00","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"\u00a0dev.agtx@gmail.com\u00a0"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/40742"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=40742"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/40742\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=40742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=40742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=40742"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=40742"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=40742"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=40742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}