{"id":40528,"date":"2023-04-20T22:09:14","date_gmt":"2023-04-20T20:09:14","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=40528"},"modified":"2023-04-20T22:09:26","modified_gmt":"2023-04-20T20:09:26","slug":"ingenieur-genie-civil-4","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/ingenieur-genie-civil-4\/","title":{"rendered":"INGENIEUR GENIE CIVIL"},"content":{"rendered":"\n<p>AUDIT \u2013 INSPECTION \u2013 CERTIFICATION \u2013 FORMATION \u2013 CONSEIL<br>\u00ab La r\u00e9volution de l\u2019accompagnement, c\u2019est de \u00e7a qu\u2019il s\u2019agit \u00bb<\/p>\n\n\n\n<p>Couvrant l\u2019\u00e9tendue du territoire national, l\u2019engagement et le savoir-faire de notre jeune et dynamique \u00e9quipe,<br>font de nous le leader dans l\u2019innovation et la r\u00e9volution dans les domaines de l\u2019AUDIT \u2013 INSPECTION \u2013<br>CERTIFICATION \u2013 FORMATION \u2013 CONSEIL.<br>Rejoignez l\u2019excellence technique et innovante de nos \u00e9quipes.<br>Ville : Le poste est bas\u00e9 \u00e0 Douala.<br>Poste : INGENIEUR GENIE CIVIL<br>VOTRE MISSION :<br>KAMER ENGINEERING SOLUTIONS r\u00e9alise des prestations d\u2019audits, inspections, certifications, formations et<br>conseil dans le contexte r\u00e9glementaire ou contractuel de ses clients.<br>Rattach\u00e9 au CEO, \u00e0 ce titre vous :<\/p>\n\n\n\n<p>&#8211;<\/p>\n\n\n\n<p>R\u00e9alisez des \u00e9tudes techniques et \u00e9laborer des plans ;<\/p>\n\n\n\n<p>&#8211;<\/p>\n\n\n\n<p>Elaborez les diff\u00e9rentes phases du projet de construction de b\u00e2timents, depuis leur conception jusqu\u2019\u00e0<br>leur ex\u00e9cution ;<\/p>\n\n\n\n<p>&#8211;<\/p>\n\n\n\n<p>\u00c9laborez des solutions techniques et financi\u00e8res ;<\/p>\n\n\n\n<p>&#8211;<\/p>\n\n\n\n<p>Supervisez et contr\u00f4ler la r\u00e9alisation des travaux ;<\/p>\n\n\n\n<p>&#8211;<\/p>\n\n\n\n<p>Etablissez les pr\u00e9visions des co\u00fbts d\u2019investissement et les plannings des travaux<\/p>\n\n\n\n<p>&#8211;<\/p>\n\n\n\n<p>Veillez \u00e0 la num\u00e9risation, le stockage et la tra\u00e7abilit\u00e9 de toutes les informations relatives aux activit\u00e9s et<br>op\u00e9rations du projet ;<\/p>\n\n\n\n<p>&#8211;<\/p>\n\n\n\n<p>R\u00e9digez la r\u00e9daction du compte rendu et des informations sur l\u2019avancement des op\u00e9rations ;<\/p>\n\n\n\n<p>&#8211;<\/p>\n\n\n\n<p>Assurez le pilotage, la planification et le suivi sur tous les aspects (architecturaux, techniques,<br>administratifs, financiers et juridiques) du projet ;<\/p>\n\n\n\n<p>PROFIL :<br>De formation minimale Bac+5, ing\u00e9nieur en g\u00e9nie civil, vous b\u00e9n\u00e9ficiez d&rsquo;une exp\u00e9rience professionnelle<br>similaire de minimum 3 ans dans le domaine des \u00e9tudes et suivi de chantier de g\u00e9nie civil.<br>Les comp\u00e9tences recherch\u00e9es pour ce poste sont :<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">CONNAISSANCES :<\/h2>\n\n\n\n<p>Excellentes connaissances des normes et r\u00e9glementions applicables dans le cadre des projets de B\u00e2timents<br>et travaux publics aux Cameroun<br>Excellente connaissance des outils CAO suite Autodesk (Robot, Revit, AutoCAD, Advance,)<br>Bonne connaissance des outils de gestion de projet MS Project, Suite office, \u2026<br>Connaissance des techniques des diff\u00e9rents corps d\u2019\u00e9tat secondaires du b\u00e2timent (Electricit\u00e9, climatisation,<br>S\u00e9curit\u00e9 incendie, plomberie, \u00e9tanch\u00e9it\u00e9, menuiserie, Rev\u00eatements \u2026) ;<br>Connaissance et application du code de la commande publique et des diff\u00e9rents CCAG (prestations<br>intellectuelles, ma\u00eetrise d\u2019\u0153uvre et travaux)<br>Excellente veille technologique et r\u00e8glementaire<br>Des connaissances en VBA et Gestion des Bases de donn\u00e9es seraient un gros plus.<\/p>\n\n\n\n<p>KAMER ENGINEERING SOLUTIONS SARL<br>B.P. 4489 Douala (Cameroun) \/ Tel : 00237 699 42 95 89 \/ 677 51 08 24 \/ 698 37 70 79 &#8211; Courriel : kessarl@outlook.fr \u2013 contac.cmr@kes-africa.com<br>www.kes-africa.com &#8211; RCCM : RC\/DLA\/2020\/B\/3405 &#8211; N\u00b0 Contribuable : M072014716024Q<\/p>\n\n\n\n<p>AUDIT \u2013 INSPECTION \u2013 CERTIFICATION \u2013 FORMATION \u2013 CONSEIL<br>\u00ab La r\u00e9volution de l\u2019accompagnement, c\u2019est de \u00e7a qu\u2019il s\u2019agit \u00bb<\/p>\n\n\n\n<p>2\/2<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">COMPETENCES OPERATIONNELLES :<\/h2>\n\n\n\n<p>Tr\u00e8s bonnes capacit\u00e9s r\u00e9dactionnelles et d&rsquo;expression orale<br>Rigueur, sens de l&rsquo;organisation et autonomie de travail<br>Sens des priorit\u00e9s<br>Capacit\u00e9 \u00e0 prendre des initiatives<br>Capacit\u00e9 \u00e0 rendre compte de son activit\u00e9 de mani\u00e8re spontan\u00e9e et synth\u00e9tique<br>Capacit\u00e9 \u00e0 s&rsquo;adapter aux changements, \u00e0 faire face \u00e0 des situations d&rsquo;urgence<br>Savoir g\u00e9rer son activit\u00e9 dans un calendrier et un cadre de gestion avec plusieurs intervenants<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">SAVOIR ETRE :<\/h2>\n\n\n\n<p>Discr\u00e9tion<br>Tr\u00e8s bon sens relationnel<br>Calme<br>Autonome<br>Accueillant<br>Capacit\u00e9 d\u2019anticipation<br>Force de proposition<br>Sens de l&rsquo;\u00e9coute<br>Sens du service client<\/p>\n\n\n\n<p>En nous rejoignant, vous serez form\u00e9 \u00e0 nos m\u00e9tiers<br>Votre sens du service client, votre \u00e9thique et votre capacit\u00e9 d\u2019adaptation contribueront \u00e0 votre r\u00e9ussite au sein<br>de KAMER ENGINEERING SOLUTIONS.<br>Transmettre votre CV et lettre de motivation \u00e0 contact.cmr@kes-africa.com, au plus tard le 06 Mai 2023<\/p>\n\n\n\n<p>KAMER ENGINEERING SOLUTIONS SARL<br>B.P. 4489 Douala (Cameroun) \/ Tel : 00237 699 42 95 89 \/ 677 51 08 24 \/ 698 37 70 79 &#8211; Courriel : kessarl@outlook.fr \u2013 contac.cmr@kes-africa.com<br>www.kes-africa.com &#8211; RCCM : RC\/DLA\/2020\/B\/3405 &#8211; N\u00b0 Contribuable : M072014716024Q<\/p>\n","protected":false},"excerpt":{"rendered":"<p>AUDIT \u2013 INSPECTION \u2013 CERTIFICATION \u2013 FORMATION \u2013 CONSEIL\u00ab La r\u00e9volution de l\u2019accompagnement, c\u2019est de \u00e7a qu\u2019il s\u2019agit \u00bb Couvrant l\u2019\u00e9tendue du territoire national, l\u2019engagement&#8230;<\/p>\n","protected":false},"author":63,"comment_status":"open","ping_status":"closed","template":"","categories":[976],"tags":[],"villes":[135],"contrats":[236],"diplomes":[160],"louma_meta":{"emploi_title":"INGENIEUR GENIE CIVIL","emplois_employeur":37583,"emplois_date_publication":"2023-04-20","emplois_heure_publication":"","emplois_date_cloture":"2023-05-06","emplois_heure_cloture":"","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"contact.cmr@kes-africa.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/40528"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=40528"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/40528\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/37584"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=40528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=40528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=40528"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=40528"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=40528"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=40528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}