{"id":40103,"date":"2023-04-10T17:28:26","date_gmt":"2023-04-10T15:28:26","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=40103"},"modified":"2023-04-11T08:24:28","modified_gmt":"2023-04-11T06:24:28","slug":"community-manager-45","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/community-manager-45\/","title":{"rendered":"Community Manager"},"content":{"rendered":"\n<p>Offre d&#8217;emploi : Community Manager<br>chez Nano Dev Sarl<\/p>\n\n\n\n<p>Localisation : Yaound\u00e9<\/p>\n\n\n\n<p>Description du poste:<\/p>\n\n\n\n<p>Nano Dev Sarl est \u00e0 la recherche d&rsquo;un Community Manager pour rejoindre son \u00e9quipe \u00e0 Yaound\u00e9. Le candidat id\u00e9al sera responsable de r\u00e9pondre aux demandes des clients, g\u00e9rer les appartements meubl\u00e9s et des voitures en locations. Il ou elle doit \u00e9galement poss\u00e9der un excellent fran\u00e7ais, \u00eatre attentif aux d\u00e9tails, faire preuve de leadership, savoir g\u00e9rer les conflits, \u00eatre disponible pour travailler de 9h \u00e0 17h, avoir au moins 2 ans d&rsquo;exp\u00e9rience, avoir une bonne connaissance de l&rsquo;outil informatique et des mesures de s\u00e9curit\u00e9, et superviser des \u00e9quipes sur le terrain pour la gestion des biens immobiliers et automobiles de l&rsquo;entreprise.<\/p>\n\n\n\n<p>Responsabilit\u00e9s :<\/p>\n\n\n\n<ul><li>R\u00e9pondre aux demandes des clients<\/li><li>G\u00e9rer les appartements meubl\u00e9s et des voitures en location<\/li><li>Superviser des \u00e9quipes sur le terrain pour la gestion des biens immobiliers et automobiles de l&rsquo;entreprise <\/li><li>Faire preuve de leadership<\/li><li>G\u00e9rer les conflits<\/li><li>Avoir une bonne connaissance de l&rsquo;outil informatique et des mesures de s\u00e9curit\u00e9<\/li><\/ul>\n\n\n\n<p>Exigences :<\/p>\n\n\n\n<ul><li>Au moins 2 ans d&rsquo;exp\u00e9rience en tant que Community Manager ou dans un poste similaire<\/li><li>Excellent fran\u00e7ais<\/li><li>Attention aux d\u00e9tails<\/li><li>Leadership<\/li><li>Capacit\u00e9 \u00e0 g\u00e9rer les conflits<\/li><li>Disponible pour travailler de 9h \u00e0 17h<\/li><li>Bonne connaissance de l&rsquo;outil informatique et des mesures de s\u00e9curit\u00e9<\/li><\/ul>\n\n\n\n<p>Salaire:<\/p>\n\n\n\n<ul><li>Le salaire sera entre 150 000 FCFA et 250 000 FCFA en fonction de l&rsquo;exp\u00e9rience et des comp\u00e9tences.<br>Nous offrons \u00e9galement un bonus de signature de 100 000 FCFA et un Macbook Air M1.<\/li><\/ul>\n\n\n\n<p>Comment postuler :<br>Si vous \u00eates int\u00e9ress\u00e9(e) par ce poste, veuillez envoyer votre CV \u00e0 l&rsquo;adresse<\/p>\n\n\n\n<p>suivante : social@nanodev.ca<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Offre d&#8217;emploi : Community Managerchez Nano Dev Sarl Localisation : Yaound\u00e9 Description du poste: Nano Dev Sarl est \u00e0 la recherche d&rsquo;un Community Manager pour&#8230;<\/p>\n","protected":false},"author":63,"comment_status":"open","ping_status":"closed","template":"","categories":[1139],"tags":[],"villes":[136],"contrats":[234],"diplomes":[163],"louma_meta":{"emploi_title":" Community Manager","emplois_employeur":40096,"emplois_date_publication":"2023-04-10","emplois_heure_publication":"","emplois_date_cloture":"2023-04-24","emplois_heure_cloture":"","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"social@nanodev.ca"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/40103"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=40103"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/40103\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/40143"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=40103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=40103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=40103"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=40103"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=40103"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=40103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}