{"id":39826,"date":"2023-03-31T11:09:25","date_gmt":"2023-03-31T09:09:25","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=39826"},"modified":"2023-03-31T11:09:27","modified_gmt":"2023-03-31T09:09:27","slug":"agent-commercial-19","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/agent-commercial-19\/","title":{"rendered":"Agent Commercial"},"content":{"rendered":"\n<p>OFFRE D&rsquo;EMPLOI POUR LE POSTE DE COMMERCIAL TERRAIN<\/p>\n\n\n\n<p>Dans le cadre du d\u00e9veloppement de ses activit\u00e9s, STREET BET AFRICA recrute des Commerciaux pour ses kiosques et points de vente dans la ville de Douala.<\/p>\n\n\n\n<p>Missions:<\/p>\n\n\n\n<ul><li>Promouvoir l&rsquo;offre de service dont il a la charge, former de nouveaux utilisateurs sur nos terminaux;<\/li><li>cr\u00e9er des r\u00e9seaux partenaires locales;<\/li><li>Analyse du marche et veille concurrentielle;<\/li><li>Faire un reporting permanent aupr\u00e8s de sa hi\u00e9rarchie;<\/li><\/ul>\n\n\n\n<p>Connaissances et comp\u00e9tences requises:<\/p>\n\n\n\n<ul><li>Connaissance des techniques de vente et de n\u00e9gociation;<\/li><li>connaissance des jeux hasard et des paris;<\/li><li>Esprit d&rsquo;initiative et animation d&rsquo;\u00e9quipe;<\/li><li>Faible maitrise du mat\u00e9riel informatique.<\/li><\/ul>\n\n\n\n<p>Profil:<\/p>\n\n\n\n<ul><li>Homme \/ Femme (21 \u00e0 35 ans);<\/li><li>Disposer d&rsquo;une exp\u00e9rience minimum de 06 (six) mois comme commercial;<\/li><\/ul>\n\n\n\n<p>Ce que nous vous proposons:<\/p>\n\n\n\n<ul><li>Lieu de travail: Douala<\/li><li>Type de contrat : CDD (avec essai de 03 mois);<\/li><li>Salaire brut mensuel \u00e0 n\u00e9gocier selon le profil + commission sur les ventes et transport selon les sites a d\u00e9ployer<\/li><\/ul>\n\n\n\n<p>Si cette offre vous int\u00e9resse, merci de nous faire parvenir votre dossier de candidature constitu\u00e9; de votre Curriculum vitae + lettre de motivation \u00e0 l&rsquo;adresse suivante streetbetafrica@gmail.com ou WhatsApp au 693336793 au plus tard le 30 Avril 2023.<\/p>\n\n\n\n<p> seuls les candidats pr&amp;eacute;s&amp;eacute;lectionn&amp;eacute;s seront contact&amp;eacute;s.<\/p>\n\n\n\n<p>NB: Ne donnez jamais de l&rsquo;argent durant un processus de recrutement. Le m\u00e9decin du travail s&rsquo;occupe uniquement des employ\u00e9s de l&rsquo;entreprise.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via streetbetafrica@gmail.com<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[251,1273],"tags":[],"villes":[136],"contrats":[236],"diplomes":[162,248],"louma_meta":{"emploi_title":"Agent Commercial","emplois_employeur":3046,"emplois_date_publication":"2023-03-31","emplois_heure_publication":"10:09","emplois_date_cloture":"2023-04-30","emplois_heure_cloture":"17:00","emplois_experience_min":"6","emplois_experience_max":"","emploi_email":"streetbetafrica@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/39826"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=39826"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/39826\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=39826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=39826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=39826"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=39826"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=39826"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=39826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}