{"id":3967,"date":"2020-06-19T10:49:44","date_gmt":"2020-06-19T08:49:44","guid":{"rendered":"https:\/\/louma-jobs.com\/cm\/?post_type=emplois&#038;p=3967"},"modified":"2020-06-19T10:49:46","modified_gmt":"2020-06-19T08:49:46","slug":"agents-de-terrain-cash-transfert","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2020\/agents-de-terrain-cash-transfert\/","title":{"rendered":"Agents de terrain Cash Transfert"},"content":{"rendered":"\n<p>Agents de terrain Cash Transfert<\/p>\n\n\n\n<p>Infos cl\u00e9s<br>\u2022 Type de contrat : A n\u00e9gocier<br>\u2022 Domaine d&rsquo;activit\u00e9 : Non sp\u00e9cifi\u00e9<br>\u2022 Lieu de travail : A pr\u00e9ciser<br>\u2022 Exp\u00e9rience : D\u00e9butant<br>\u2022 Niveau d&rsquo;\u00e9tude minimum : Baccalaur\u00e9at<br>\u2022 Salaire : \u00e0 n\u00e9gocier<\/p>\n\n\n\n<p>Profil souhait\u00e9<br>5 personnes, homme ou femme ayant entre 25 et 55 ans avec comme niveau d\u00b4\u00e9tude Baccalaur\u00e9at ni plus ni moins parlant et \u00e9crivant fran\u00e7ais, anglais<br>Description du profil<br>Avis de recrutement Local de (05) Agents de terrain Cash Transfert\/distribution de vivres<br>Fonctions et t\u00e2ches<br>Organisation et Distribution des produits sur site :<br>\u2022 Evaluer les besoins et acheminer des produits alimentaires et non alimentaires aux b\u00e9n\u00e9ficiaires ;<br>\u2022 S\u00b4assurer que les d\u00e9lais de livraison soient respect\u00e9s et de leur bonne organisation g\u00e9n\u00e9rale ;<br>\u2022 S\u00b4assurer que chaque b\u00e9n\u00e9ficiaire re\u00e7oive la bonne quantit\u00e9 de produit ;<br>\u2022 S\u00b4assurer du respect des conditions d\u00b4hygi\u00e8ne de la livraison ;<br>\u2022 V\u00e9rifier la conformit\u00e9 de la livraison en termes quantitatifs et qualitatifs ;<br>\u2022 Contr\u00f4le des b\u00e9n\u00e9ficiaires : contr\u00f4le de la foule ;<br>\u2022 Pr\u00e9paration du mat\u00e9riel n\u00e9cessaire \u00e0 la distribution du produit ;<br>\u2022 Intervenir en cas de probl\u00e8me avec les b\u00e9n\u00e9ficiaires ;<br>\u2022 R\u00e9diger un rapport d\u00b4activit\u00e9 qui d\u00e9crit tous les processus de distribution ;<br>\u2022 Emettre des recommandations pour am\u00e9liorer les r\u00e9sultats des processus de distribution ;<br>\u2022 Proposer de nouvelles mesures pour des activit\u00e9s \u00e0 venir ;<br>\u2022 Distribution de jetons aux b\u00e9n\u00e9ficiaires ;<br>\u2022 Recenser et renseigner les plaintes des b\u00e9n\u00e9ficiaires au superviseur<br>Gestion des b\u00e9n\u00e9ficiaires :<br>\u2022 Sensibiliser les b\u00e9n\u00e9ficiaires sur les mesures barri\u00e8res au Covid-19 ;<br>\u2022 R\u00e9aliser les enqu\u00eates PDM ;<br>\u2022 Expliquer le projet aux b\u00e9n\u00e9ficiaires et \u00e0 la population ;<br>\u2022 Faire le lien entre l\u00b4Organisation et les b\u00e9n\u00e9ficiaires.<br>\u2022 V\u00e9rifier que la liste des b\u00e9n\u00e9ficiaires soit conforme avec les crit\u00e8res de vuln\u00e9rabilit\u00e9 d\u00e9cid\u00e9s avant la mise en place de l\u00b4activit\u00e9.<br>\u2022 Informer le Superviseur de site si des personnes vuln\u00e9rables ne sont pas incluses sur ces listes.<br>\u2022 Collecter des donn\u00e9es et r\u00e9aliser des interviews ;<br>\u2022 Informer le Superviseur de site en cas de litige.<br>Formation et exp\u00e9riences:<br>Niveau BAC<br>Exp\u00e9rience d\u00b4ONG dans un contexte humanitaire, de pr\u00e9f\u00e9rence en cas d\u00b4urgence ;<br>Exp\u00e9rience \u00e0 un poste similaire serait un atout<br>\u00catre de nationalit\u00e9 camerounaise<br>R\u00e9sider dans le Logone et Chari, le Mayo Sava ou le Mayo Danay<br>Comp\u00e9tences:<br>Capacit\u00e9 \u00e0 travailler sous pression, en milieu s\u00e9curitaire tendu ;<br>Bonne capacit\u00e9 d\u00b4organisation et r\u00e9activit\u00e9;<br>Bonnes capacit\u00e9s de collecte de donn\u00e9es ;<br>Connaissance du fonctionnement des march\u00e9s en zone rurale et urbaine;<br>Bonne connaissance de la zone d\u00b4intervention<br>Flexibilit\u00e9<br>Autonomie dans le travail en \u00e9quipe.<br>Bonnes capacit\u00e9 en communication et information.<br>Langues :<br>Fran\u00e7ais obligatoire<br>Anglais : langue de travail sur le projet<br>La connaissance des langues locales (Fufulde, arabe choa, Kanuri, Musgoum ) serait un atout<br>Qualit\u00e9s personnelles :<br>Sens du travail en \u00e9quipe,<br>Motivation sinc\u00e8re pour l\u00b4engagement humanitaire<br>Les candidatures f\u00e9minines et de personnes handicap\u00e9es sont fortement encourag\u00e9es et seront analys\u00e9es avec une attention particuli\u00e8re.<br>Envoyez votre CV (en respectant le format : CV-Nom) et votre lettre de motivation en suivant le lien ci-apr\u00e8s : https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSf_EQ_pO_gvLL2W80A4IeUiJOOcFG6y98I31kfmhic6qtslXw\/viewform?vc=0&amp;c=0&amp;w=1<\/p>\n\n\n\n<p>Le d\u00e9lai de d\u00e9p\u00f4t de candidature est fix\u00e9 le Vendredi 19 Juin 2020 \u00e0 17h.<br>NB : Seules les candidatures pr\u00e9s\u00e9lectionn\u00e9es seront contact\u00e9es.<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avis de recrutement Local de (05) Agents de terrain Cash Transfert\/distribution de vivres<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[354],"tags":[296],"villes":[136],"contrats":[234],"diplomes":[162],"louma_meta":{"emploi_title":"Agents de terrain Cash Transfert","emplois_employeur":3046,"emplois_date_publication":"2020-06-19","emplois_heure_publication":"","emplois_date_cloture":"2020-06-19","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSf_EQ_pO_gvLL2W80A4IeUiJOOcFG6y98I31kfmhic6qtslXw\/viewform?vc=0&c=0&w=1"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/3967"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=3967"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/3967\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/3031"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=3967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=3967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=3967"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=3967"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=3967"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=3967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}