{"id":39590,"date":"2023-03-24T16:02:02","date_gmt":"2023-03-24T15:02:02","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=39590"},"modified":"2023-03-24T16:02:04","modified_gmt":"2023-03-24T15:02:04","slug":"un-assistant-comptable-2","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/un-assistant-comptable-2\/","title":{"rendered":"un Assistant Comptable"},"content":{"rendered":"\n<p>Elite RH recrute un Assistant Comptable.<br>Missions et responsabilit\u00e9s :<\/p>\n\n\n\n<p>Saisir les factures<\/p>\n\n\n\n<p>Effectuer le rapprochement bancaire<br>Relancer les impay\u00e9s<\/p>\n\n\n\n<p>Enregistrer les documents comptables<\/p>\n\n\n\n<p>Traiter les litiges<\/p>\n\n\n\n<p>Assurer le traitement administratif des retours<br>Traiter les notes de frais<\/p>\n\n\n\n<p>Comp\u00e9tences requises<\/p>\n\n\n\n<p>Issue d&rsquo;une formation en comptabilit\u00e9 gestion, vous justifiez au<br>moins d&rsquo;une exp\u00e9rience similaire significative. Vous \u00eates<br>autonome, rigoureux, ambitieux et vous avez un excellent<br>relationnel<\/p>\n\n\n\n<p>Vous avez envie de rejoindre une \u00e9quipe dynamique et<br>ambitieuse.<\/p>\n\n\n\n<p>Vous \u00eates proactif(ve), rigoureux(se), polyvalent(e) et vous<br>appr\u00e9ciez travailler en \u00e9quipe<\/p>\n\n\n\n<p>Envoyez votre candidature \u00e0 l&rsquo;adresse :<\/p>\n\n\n\n<p>eliterhrecrutement@gmail.com<br>en mentionnant en objet le titre du poste.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Elite RH recrute un Assistant Comptable.Missions et responsabilit\u00e9s : Saisir les factures Effectuer le rapprochement bancaireRelancer les impay\u00e9s Enregistrer les documents comptables Traiter les litiges&#8230;<\/p>\n","protected":false},"author":63,"comment_status":"open","ping_status":"closed","template":"","categories":[282],"tags":[],"villes":[4061],"contrats":[234],"diplomes":[278],"louma_meta":{"emploi_title":"un Assistant Comptable","emplois_employeur":39593,"emplois_date_publication":"2023-03-24","emplois_heure_publication":"","emplois_date_cloture":"2023-03-31","emplois_heure_cloture":"","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"eliterhrecrutement@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/39590"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=39590"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/39590\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/39595"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=39590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=39590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=39590"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=39590"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=39590"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=39590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}