{"id":39035,"date":"2023-03-16T04:31:23","date_gmt":"2023-03-16T03:31:23","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=39035"},"modified":"2023-03-16T04:31:25","modified_gmt":"2023-03-16T03:31:25","slug":"coordinateur-risques-et-conformite-cameroun-yaounde","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/coordinateur-risques-et-conformite-cameroun-yaounde\/","title":{"rendered":"Coordinateur Risques et Conformit\u00e9 Cameroun Yaound\u00e9"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">DESCRIPTION DE L&rsquo;EMPLOI<\/h2>\n\n\n\n<p>Le coordinateur des risques et de la conformit\u00e9 est charg\u00e9 de soutenir les efforts de NRC Cameroun pour g\u00e9rer efficacement les risques, promouvoir une culture de gestion des risques au sein du bureau de pays (CO), soutenir le directeur de pays (CD) pour assurer la conformit\u00e9 du CO dans les zones \u00e0 haut risque et avec les r\u00e9glementations non sp\u00e9cifiques \u00e0 une fonction donn\u00e9e et r\u00e9pondant \u00e0 tous les probl\u00e8mes ou questions qui se posent concernant le travail du CO.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">RESPONSABILIT\u00c9S<\/h2>\n\n\n\n<p>Responsabilit\u00e9s sp\u00e9cifiques<\/p>\n\n\n\n<ol><li>Surveiller la conformit\u00e9 dans la mise en \u0153uvre des politiques, proc\u00e9dures et contr\u00f4les du CNRC gr\u00e2ce \u00e0 des v\u00e9rifications ponctuelles r\u00e9guli\u00e8res, des visites sur le terrain et des examens approfondis<\/li><li>En collaboration avec le personnel de programme et de soutien, soutien au d\u00e9veloppement de syst\u00e8mes de gestion de documents, y compris le d\u00e9veloppement d&rsquo;un syst\u00e8me de remplissage et de r\u00e9f\u00e9rencement standard, y compris la formation et le conseil aux services responsables<\/li><li>Effectuer des v\u00e9rifications ponctuelles et des rapports de visite sur le terrain sur divers aspects des op\u00e9rations et des fonctions du CNRC<\/li><li>Soutenir chaque site de terrain du CNRC dans la compilation d&rsquo;une cartographie des risques bas\u00e9e sur la localisation mise \u00e0 jour&nbsp;;&nbsp;un accompagnement dans la formation du personnel et le d\u00e9veloppement d&rsquo;une culture de gestion des risques<\/li><li>Soutenir l&rsquo;am\u00e9lioration continue des normes op\u00e9rationnelles<\/li><li>En coordination avec le sup\u00e9rieur hi\u00e9rarchique, organiser des formations et des remises \u00e0 niveau pour le personnel, les partenaires, etc. sur les diff\u00e9rentes politiques du NRC, par exemple la politique anti-corruption du NRC, la s\u00e9curisation des initiatives de documentation \u00e0 l&rsquo;appui (SSDI), la sensibilisation \u00e0 la conformit\u00e9&nbsp;<\/li><li>Sous la direction du CD, soutien dans les enqu\u00eates internes, avec examen de documents ou recherche de faits lors d&rsquo;enqu\u00eates<\/li><li>Soutenir le d\u00e9veloppement du cadre de conformit\u00e9 du NRC au Cameroun sur la base d&rsquo;une compr\u00e9hension approfondie des proc\u00e9dures et directives du NRC, y compris le suivi des indicateurs de performance cl\u00e9s \u00e0 intervalles r\u00e9guliers<\/li><li>Servir de point focal pour la protection des donn\u00e9es, ce qui comprendra la facilitation d&rsquo;une cartographie des processus de donn\u00e9es de toutes les activit\u00e9s de traitement des donn\u00e9es, la surveillance de la collecte de donn\u00e9es d&rsquo;informations sensibles et des conseils sur les \u00e9valuations d&rsquo;impact et les violations de donn\u00e9es<\/li><li>Travailler, lorsqu&rsquo;il est assign\u00e9, en tant que point focal d&rsquo;audit &#8211; ce qui comprend la cr\u00e9ation d&rsquo;un calendrier et d&rsquo;une structure de classement, la communication avec les auditeurs et la liaison avec les points focaux des d\u00e9partements<\/li><li>D\u00e9velopper et d\u00e9ployer un suivi des recommandations des recommandations internes et externes (ex: des rapports d&rsquo;audit, des enqu\u00eates, des \u00e9valuations, des missions, etc.) et travailler avec les chefs de d\u00e9partement pour surveiller le suivi des recommandations<\/li><li>Effectuer des contr\u00f4les ponctuels sur les probl\u00e8mes \u00e0 haut risque sous la fonction R&amp;C (ex&nbsp;: COTER, protection des donn\u00e9es, anti-corruption et PSEA, etc.), ainsi que soutenir les contr\u00f4les ponctuels sur les probl\u00e8mes \u00e0 haut risque au sein d&rsquo;autres d\u00e9partements, en coordination avec les chefs de d\u00e9partement.&nbsp;Des rapports d\u00e9crivant les probl\u00e8mes \u00e0 haut risque seront fournis \u00e0 la haute direction, y compris des recommandations relatives aux politiques et proc\u00e9dures du CNRC<\/li><\/ol>\n\n\n\n<h2 class=\"wp-block-heading\">QUALIFICATIONS<\/h2>\n\n\n\n<p>Qualifications essentielles :<\/p>\n\n\n\n<ul><li>&nbsp;Dipl\u00f4me universitaire dans le domaine (audit, finances, administration publique et similaire)<\/li><li>Minimum 2 ans d&rsquo;exp\u00e9rience en tant que coordinateur dans des fonctions de conformit\u00e9 ou de gestion des risques ou en tant que coordinateur dans le secteur humanitaire.&nbsp;L&rsquo;exp\u00e9rience pertinente pourrait inclure le travail dans la prestation de programmes, la gestion des subventions, les partenariats, les audits, car le CNRC pr\u00e9f\u00e8re quelqu&rsquo;un avec une exp\u00e9rience holistique dans les fonctions de programme et de soutien.<\/li><li>Ma\u00eetrise parfaite de l&rsquo;anglais et du fran\u00e7ais parl\u00e9s et \u00e9crits<\/li><li>Solides comp\u00e9tences en planification, en organisation et en relations interpersonnelles<\/li><li>Excellentes capacit\u00e9s d&rsquo;analyse, de pr\u00e9sentation et de production de rapports<\/li><li>Capacit\u00e9 \u00e0 r\u00e9pondre aux priorit\u00e9s changeantes<\/li><li>Capacit\u00e9 \u00e0 travailler de mani\u00e8re autonome de sa propre initiative<\/li><\/ul>\n\n\n\n<p>Comp\u00e9tences, connaissances et exp\u00e9rience li\u00e9es au contexte :<\/p>\n\n\n\n<ul><li>Connaissance des r\u00e8gles, r\u00e8glements et proc\u00e9dures des ONGI des donateurs<\/li><li>Esprit syst\u00e9matique, souci du d\u00e9tail et capacit\u00e9 \u00e0 structurer une grande quantit\u00e9 d&rsquo;informations de mani\u00e8re facilement accessible<\/li><li>Connaissance du contexte r\u00e9glementaire au Cameroun<\/li><li>Exp\u00e9rience dans l&rsquo;\u00e9laboration de proc\u00e9dures internes, de documents juridiques, de contrats\u2026<\/li><\/ul>\n\n\n\n<p>Nous proposons un contrat \u00e0 dur\u00e9e d\u00e9termin\u00e9e de douze mois bas\u00e9 \u00e0 Yaound\u00e9 avec 40% de d\u00e9placements dans toutes&nbsp;&nbsp;les zones du Cameroun o\u00f9 NRC a des op\u00e9rations sur le terrain.&nbsp;&nbsp;Nous offrons \u00e9galement un salaire comp\u00e9titif (\u00e9chelle 7 NRC Cameroun) et un ensemble d&rsquo;avantages sociaux (assurance m\u00e9dicale \u00e0 90%).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00c0 PROPOS DE NOUS<\/h2>\n\n\n\n<p>Le Conseil norv\u00e9gien pour les r\u00e9fugi\u00e9s (NRC) est une organisation humanitaire ind\u00e9pendante qui aide les personnes contraintes de fuir.\u00a0Nous intervenons dans des situations de crise dans plus de 31 pays, fournissant chaque ann\u00e9e une aide d&rsquo;urgence et une assistance \u00e0 long terme \u00e0 des millions de personnes.\u00a0Nous d\u00e9fendons les personnes contraintes de fuir, d\u00e9fendant leurs droits.\u00a0NORCAP, notre fournisseur mondial d&rsquo;expertise, aide \u00e0 am\u00e9liorer la capacit\u00e9 internationale et locale \u00e0 pr\u00e9venir, pr\u00e9parer, r\u00e9pondre et se remettre des crises.\u00a0Le NRC g\u00e8re \u00e9galement l&rsquo;Observatoire des d\u00e9placements internes \u00e0 Gen\u00e8ve, un chef de file mondial dans le domaine des rapports et de la d\u00e9fense des personnes d\u00e9plac\u00e9es dans leur propre pays.L&#8217;emploi au sein du NRC peut conduire \u00e0 un emploi ou \u00e0 un d\u00e9ploiement dans des r\u00e9gions, des pays, des zones ou des bureaux qui peuvent pr\u00e9senter des risques consid\u00e9rables pour la sant\u00e9, la s\u00fbret\u00e9 et la s\u00e9curit\u00e9.\u00a0Le CNRC prend cela tr\u00e8s au s\u00e9rieux et nous avons mis en place des proc\u00e9dures pour r\u00e9duire les risques connus, mais nous ne pourrons jamais \u00e9liminer tous les risques.NRC est un employeur garantissant l&rsquo;\u00e9galit\u00e9 des chances et vise \u00e0 avoir une diversit\u00e9 de personnel en termes d&rsquo;\u00e2ge, de sexe, d&rsquo;origine ethnique, de nationalit\u00e9 et de capacit\u00e9 physique.<\/p>\n\n\n\n<p>NB: Ne donnez jamais de l&rsquo;argent durant un processus de recrutement. Le m\u00e9decin du travail s&rsquo;occupe uniquement des employ\u00e9s de l&rsquo;entreprise.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via https:\/\/ekum.fa.em2.oraclecloud.com\/hcmUI\/CandidateExperience\/en\/sites\/CX_2019\/requisitions\/preview\/10012\/?location=Cameroon&amp;locationId=300000000306624&amp;locationLevel=country<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[1594,23,2572],"tags":[],"villes":[136],"contrats":[148],"diplomes":[212,159],"louma_meta":{"emploi_title":"Coordinateur Risques et Conformit\u00e9 Cameroun Yaound\u00e9","emplois_employeur":2921,"emplois_date_publication":"2023-03-16","emplois_heure_publication":"04:31","emplois_date_cloture":"2023-03-19","emplois_heure_cloture":"18:00","emplois_experience_min":"","emplois_experience_max":"2","emploi_email":"https:\/\/ekum.fa.em2.oraclecloud.com\/hcmUI\/CandidateExperience\/en\/sites\/CX_2019\/requisitions\/preview\/10012\/?location=Cameroon&locationId=300000000306624&locationLevel=country"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/39035"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=39035"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/39035\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/2923"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=39035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=39035"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=39035"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=39035"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=39035"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=39035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}