{"id":38629,"date":"2023-02-27T13:50:29","date_gmt":"2023-02-27T12:50:29","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=38629"},"modified":"2023-02-27T13:50:31","modified_gmt":"2023-02-27T12:50:31","slug":"cuisiniere-vendeureuse-pour-fast-food","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/cuisiniere-vendeureuse-pour-fast-food\/","title":{"rendered":"Cuisinier(e) Vendeur(euse) Pour Fast-Food"},"content":{"rendered":"\n<p>Une PME recherche recherche cuisinier(e) vendeur(euse) pour fast-food.<\/p>\n\n\n\n<p><em>PROFIL<\/em><\/p>\n\n\n\n<p>\u00catre \u00e2g\u00e9e d&rsquo;au moins 22ans<\/p>\n\n\n\n<p>Homme ou femme propre et dynamique<\/p>\n\n\n\n<p>Tr\u00e8s ouvert(e) d&rsquo;esprit, avoir le go\u00fbt de la vente et de la culture du r\u00e9sultat<\/p>\n\n\n\n<p>Bien s&rsquo;exprimer en fran\u00e7ais<\/p>\n\n\n\n<p>Disposer d&rsquo;exp\u00e9rience en p\u00e2tisserie cuisine et vente.<\/p>\n\n\n\n<p><em>Missions<\/em>&nbsp;<\/p>\n\n\n\n<p>Faire des p\u00e2tisserie et fast-food<\/p>\n\n\n\n<p>Transmettre quotidiennement les productions et ventes r\u00e9alis\u00e9es<\/p>\n\n\n\n<p>Gestions des commandes des clients<\/p>\n\n\n\n<p>Gestion de la satisfaction et des relations clients<\/p>\n\n\n\n<p><em>Lieu de travail:&nbsp;Douala<\/em><br>&nbsp;<br>COMMENT POSTULER&nbsp;<br>Merci de transmettre votre candidature ( CV) aux&nbsp;654317097 (WhatsApp)&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une PME recherche recherche cuisinier(e) vendeur(euse) pour fast-food. PROFIL \u00catre \u00e2g\u00e9e d&rsquo;au moins 22ans Homme ou femme propre et dynamique Tr\u00e8s ouvert(e) d&rsquo;esprit, avoir le&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[1273],"tags":[],"villes":[135],"contrats":[234],"diplomes":[162,3183,158],"louma_meta":{"emploi_title":"Cuisinier(e) Vendeur(euse) Pour Fast-Food","emplois_employeur":3046,"emplois_date_publication":"2023-02-27","emplois_heure_publication":"","emplois_date_cloture":"2023-03-13","emplois_heure_cloture":"","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"654317097"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/38629"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=38629"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/38629\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=38629"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=38629"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=38629"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=38629"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=38629"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=38629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}