{"id":38618,"date":"2023-02-27T12:06:41","date_gmt":"2023-02-27T11:06:41","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=38618"},"modified":"2023-02-27T12:06:43","modified_gmt":"2023-02-27T11:06:43","slug":"une-01-import-export-transport-officer-1","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/une-01-import-export-transport-officer-1\/","title":{"rendered":"Un(e)-01-Import-Export\/Transport Officer 1\u00a0"},"content":{"rendered":"\n<p>Organisation impartiale, neutre et ind\u00e9pendante, le Comit\u00e9 international de la Croix-Rouge (CICR) a la mission exclusivement humanitaire de prot\u00e9ger la vie et la dignit\u00e9 des victimes de conflits arm\u00e9s<\/p>\n\n\n\n<p>CICR<\/p>\n\n\n\n<p>et d&rsquo;autres situations de violence, et de porter assistance. Le CICR s&rsquo;efforce \u00e9galement de pr\u00e9venir la souffrance par la promotion et le renforcement du droit et des principes humanitaires universels<\/p>\n\n\n\n<p>La d\u00e9l\u00e9gation du Comit\u00e9 international de la Croix-Rouge pour l&rsquo;Afrique centrale \u00e0 Yaound\u00e9 recherche pour son Hub<\/p>\n\n\n\n<p>logistique de Douala appel\u00e9 Coorporate Services Network-CSN: Un(e)-01-Import-Export\/Transport Officer 1<\/p>\n\n\n\n<p>Lieu de travail : Douala<\/p>\n\n\n\n<p>Dur\u00e9e initiale du contrat : 12 mois<\/p>\n\n\n\n<p>Prise de fonction&nbsp;: D\u00e8s que possible.<\/p>\n\n\n\n<p>(CANA)<\/p>\n\n\n\n<p>Mais du poste :<\/p>\n\n\n\n<p>L&rsquo;Import-Export\/Transport Officer 1 s&rsquo;assure que toutes les marchandises import\u00e9es, export\u00e9es et en transit sont transport\u00e9es conform\u00e9ment \u00e0 la r\u00e9glementation douani\u00e8re en vigueur et est charg\u00e9(e) d&rsquo;organiser le volet logistique du transport de marchandises afin que le Le CICR peut mener ses activit\u00e9s d&rsquo;assistance.<\/p>\n\n\n\n<p>Responsabilit\u00e9s principales<\/p>\n\n\n\n<p>\u00c9tablit les formalit\u00e9s douani\u00e8res en coordination avec les parties concern\u00e9es pour tous les envois entrants et sortants, conform\u00e9ment \u00e0 la l\u00e9gislation et aux r\u00e8gles douani\u00e8res en vigueur&nbsp;:<\/p>\n\n\n\n<p>\u26ab R\u00e9server les services de transport a\u00e9riens, maritimes et terrestres et suivre leur ex\u00e9cution\u00a0;<\/p>\n\n\n\n<p> \u2022 Organiser, regrouper et r\u00e9partit par destination les marchandises devant \u00eatre exp\u00e9di\u00e9es, selon les normes du CICR<\/p>\n\n\n\n<p>\u26ab Compl\u00e8te, suit et archive les documents relatifs aux activit\u00e9s d&rsquo;import-export et de transport&nbsp;; V\u00e9rifiez les factures (des douanes, des transitaires, des transporteurs) et les soumises \u00e0 ses sup\u00e9rieurs.<\/p>\n\n\n\n<p>Collaborer avec les logisticiens-ne-s pour traiter les demandes<\/p>\n\n\n\n<p>Participe \u00e0 la s\u00e9lection des prestataires externes de services logistiques (transitaires et transporteurs)<\/p>\n\n\n\n<p>Obtient des exemptions de taxes de la part des autorit\u00e9s nationales ou r\u00e9gionales marchandises que le CICR importe&nbsp;:<\/p>\n\n\n\n<p>\u26ab \u00c9tablir des rapports hebdomadaires sur l&rsquo;\u00e9tat d&rsquo;avancement des dossiers \u2022 Tenir \u00e0 jour de JDE Impex, Profile et autres bases de donn\u00e9es;<\/p>\n\n\n\n<p>S&rsquo;assurer que les r\u00e9glementations douani\u00e8res les plus r\u00e9centes sont transmises et appliqu\u00e9es.<\/p>\n\n\n\n<p>Exigences du poste<\/p>\n\n\n\n<p>Dipl\u00f4me d&rsquo;\u00e9tudes sup\u00e9rieures en Transit, Commerce International, Logistique et Transport ou tout autre<\/p>\n\n\n\n<p>dipl\u00f4me \u00e9quivalent :<\/p>\n\n\n\n<p>\u26ab03 ans d&rsquo;exp\u00e9rience professionnelle dans un poste similaire avec de bonnes connaissances du droit et de la r\u00e9glementation douani\u00e8re&nbsp;:<\/p>\n\n\n\n<p>\u2022 Bonnes connaissances des formalit\u00e9s et r\u00e8gles douani\u00e8res&nbsp;: Parfaite ma\u00eetrise du Fran\u00e7ais et bon niveau d&rsquo;Anglais (\u00e9crit et parl\u00e9)&nbsp;: excellente ma\u00eetrise des outils informatiques (Excel et Word) et des syst\u00e8mes ERP&nbsp;:<\/p>\n\n\n\n<p>\u00catre capable de travailler sous pression et d&rsquo;une mani\u00e8re autonome&nbsp;; Dot\u00e9(e) des comp\u00e9tences suivantes&nbsp;: travail en \u00e9quipe, sens des responsabilit\u00e9s, adaptation et apprentissage, planification, esprit d&rsquo;analyse et de synth\u00e8se<\/p>\n\n\n\n<p>Commentaire postulant ?<\/p>\n\n\n\n<p>Les candidats recherch\u00e9s sont invit\u00e9s \u00e0 envoyer leur CV et lettre de motivation en format PDF par courriel \u00e0 l&rsquo;adresse yao recrutement_services@ierc.org avec sujet\u00a0\u00bb Import-Export\/Transport Officer 1&Prime;. Ce poste est ouvert \u00e0 la fois pour les candidatures internes et externes.<\/p>\n\n\n\n<p>Date limite : 09.03.2023 \u00e0 17h00.<\/p>\n\n\n\n<p>Le CICR valorise la diversit\u00e9 et s&rsquo;engage \u00e0 cr\u00e9er un environnement de travail inclusif. Nous accueillons les candidatures de toutes les personnes qualifi\u00e9es.<\/p>\n\n\n\n<p>NB : Tout le processus de recrutement au CICR est libre et gratuit. Seul le D\u00e9partement RH, (yao recrutement services@icrc.org) est habilit\u00e9 \u00e0 fournir des informations ou des r\u00e9sultats sur ce processus.<\/p>\n\n\n\n<p>verser les<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Organisation impartiale, neutre et ind\u00e9pendante, le Comit\u00e9 international de la Croix-Rouge (CICR) a la mission exclusivement humanitaire de prot\u00e9ger la vie et la dignit\u00e9 des&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[4022],"tags":[],"villes":[136],"contrats":[234],"diplomes":[162,212],"louma_meta":{"emploi_title":"Un(e)-01-Import-Export\/Transport Officer 1","emplois_employeur":3172,"emplois_date_publication":"2023-02-27","emplois_heure_publication":"","emplois_date_cloture":"2023-03-13","emplois_heure_cloture":"","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"yao_recrutement services@icrc.org"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/38618"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=38618"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/38618\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/24750"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=38618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=38618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=38618"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=38618"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=38618"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=38618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}