{"id":38344,"date":"2023-02-18T22:16:50","date_gmt":"2023-02-18T21:16:50","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=38344"},"modified":"2023-02-18T22:16:52","modified_gmt":"2023-02-18T21:16:52","slug":"stagiaire-logistique","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/stagiaire-logistique\/","title":{"rendered":"Stagiaire logistique"},"content":{"rendered":"\n<p>NORWEGIAN REFUGEE COUNCIL<\/p>\n\n\n\n<p>OFFRE DE STAGE A NRC YAOUNDE<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">I. Contexte et justifications<\/h2>\n\n\n\n<p>Le Conseil Norv\u00e9gien pour les r\u00e9fugi\u00e9s est une organisation internationale non-gouvernementale qui<br>ceuvre depuis plus de 70 ans dans le domaine humanitaire. Sa mission est d\u2019assurer la promotion et<br>la protection des droits des personnes d\u00e9plac\u00e9es affect\u00e9es par la crise humanitaire. NRC intervient<br>au Cameroun depuis 2017. A ce jour, nous continuons a nous d\u00e9velopper grace a la mise en ceuvre<br>des activit\u00e9s dans les r\u00e9gions de L\u2019Extr\u00e9me-Nord, Est, du Sud-Ouest et Nord-Ouest du Cameroun.<br>Notre bureau de coordination est actuellement a la recherche d&rsquo;un stagiaire qualifi\u00e9 ayant de bonnes<br>comp\u00e9tences suivantes : Facult\u00e9s en gestion administrative et financi\u00e9re, bonnes aptitudes a la communication \u00e9crire et orale, connaissances en informatique et fortes comp\u00e9tences<br>interpersonnelles.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">I. Objectifs<\/h2>\n\n\n\n<ul><li>\u00b0 Offrir une exp\u00e9rience d&rsquo;apprentissage unique aux \u00e9tudiants et diplom\u00e9s exceptionnels,<\/li><li>\u00b0 Donner aux candidats admissibles la possibilit\u00e9 d&rsquo;acqu\u00e9rir une exp\u00e9rience pratique dans un environnement de travail international,<\/li><li>\u00b0 Accroitre la compr\u00e9hension des candidats admissibles a I&rsquo;\u00e9gard des objectifs, des strat\u00e9gies et des programmes du NRC,<\/li><li>\u00b0 Fournir au NRC l&rsquo;occasion de b\u00e9n\u00e9ficier des connaissances et des comp\u00e9tences de jeunes<\/li><li>stagiaires motiv\u00e9s dont la sp\u00e9cialisation universitaire se situe dans un domaine pertinent pour les activit\u00e9s du NRC.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">i. Descriptif g\u00e9n\u00e9ral du poste<\/h2>\n\n\n\n<p>Sous la responsabilit\u00e9 directe du Manager Logistique, le Stagiaire support aura comme tache<br>essentiel la cloture des demandes d\u2019achat et bon de commandes encore actifs dans le logiciel de<br>traitement AGRESSO. II\/Elle collabore avec I&rsquo;ensemble de I&rsquo;\u00e9quipe des services support et les \u00e9quipes<br>projets \/ programme du bureau de la coordination. Il\/elle sera un appui au d\u00e9partement Logistique<br>et finance dans le nettoyage de ce logiciel et en fonction des besoins<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">ll. Les Taches<\/h2>\n\n\n\n<p>Le stagiaire sera responsable des activit\u00e9s suivantes :<\/p>\n\n\n\n<ul><li>Fermeture des PR\/PO dans le syst\u00e9me pour les projets boucl\u00e9s durant &lsquo;ann\u00e9e 2022<\/li><li>Fermeture des PR\/PO dans le syst\u00e9me pour tous les projets ant\u00e9rieurs depuis I&rsquo;impl\u00e9mentation de I&rsquo;organisation en 2017<\/li><li>Participation aux points r\u00e9guliers avec les staffs LOG\/FIN\/PROG sur les PR\/PO<\/li><li>Suivi de la plateforme Unit4 Agresso<\/li><li>Ex\u00e9cution de toute autre tiche a la demande des superviseurs.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">IV. Profil Souhait\u00e9<\/h2>\n\n\n\n<p>Le stagiaire doit r\u00e9pondre aux crit\u00e9res suivants :<\/p>\n\n\n\n<ul><li>Bac+3\/ en Logistique et transport, Douane et transit ou Commerce international, comptabilit\u00e9, gestion financi\u00e9re et administrative, ou autre formation \u00e9quivalente ;<\/li><li>Avoir effectu\u00e9 au moins 1 stage acad\u00e9mique ou professionnel de 3 mois minimum ;<\/li><li>Comp\u00e9tences linguistiques : francais, la connaissance de I&rsquo;anglais est un atout, mais n&rsquo;est pas un facteur d\u2019\u00e9limination ;<\/li><li>Comp\u00e9tences informatiques: Kit Microsoft office (Word, Excel, power point\u2026), Office 365.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">V. Qualit\u00e9s personnelles<\/h2>\n\n\n\n<ul><li>. Etre capable de travailler en \u00e9quipe et dans un environnement h\u00e9t\u00e9rog\u00e9ne et international,<\/li><li>. Ex\u00e9cuter les tdches assign\u00e9es dans les d\u00e9lais impartis,<\/li><li>. Communiquer de mani\u00e9re professionnelle,<\/li><li>\u00b0 Accepter les id\u00e9es nouvelles et les changements n\u00e9cessaires,<\/li><li>. Adh\u00e9rer aux valeurs du NRC, au code de conduite, a la politique administrative et de s\u00e9curit\u00e9 du NRC<\/li><\/ul>\n\n\n\n<p>Vous \u00e9tes int\u00e9ress\u00e9 par ce poste ?<\/p>\n\n\n\n<p>Veuillez soumettre votre candidature (CV et lettre de motivation) 3 I&rsquo;adresse \u00e9lectronique suivante :<br>cm.recruitment@nrc.no<\/p>\n\n\n\n<p>Dimanche, 26 f\u00e9vrier 2023 a 17 heures pr\u00e9cises<\/p>\n\n\n\n<p>\u00ab NRC fait la promotion de I&rsquo;\u00e9galit\u00e9 de sexe. Les candidatures f\u00e9minines sont fortement encourag\u00e9es \u00bb.<\/p>\n\n\n\n<p>Fait a Yaound\u00e9 le 15 f\u00e9vrier 2023<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NORWEGIAN REFUGEE COUNCIL OFFRE DE STAGE A NRC YAOUNDE I. Contexte et justifications Le Conseil Norv\u00e9gien pour les r\u00e9fugi\u00e9s est une organisation internationale non-gouvernementale quiceuvre&#8230;<\/p>\n","protected":false},"author":63,"comment_status":"open","ping_status":"closed","template":"","categories":[113],"tags":[],"villes":[136],"contrats":[152,148],"diplomes":[248,3994,212],"louma_meta":{"emploi_title":"Stagiaire logistique","emplois_employeur":2921,"emplois_date_publication":"2023-02-18","emplois_heure_publication":"","emplois_date_cloture":"2023-02-28","emplois_heure_cloture":"","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"cm.recruitment@nrc.no"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/38344"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=38344"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/38344\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/2923"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=38344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=38344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=38344"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=38344"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=38344"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=38344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}