{"id":3774,"date":"2020-06-10T06:57:30","date_gmt":"2020-06-10T04:57:30","guid":{"rendered":"https:\/\/louma-jobs.com\/cm\/?post_type=emplois&#038;p=3774"},"modified":"2020-06-10T06:57:31","modified_gmt":"2020-06-10T04:57:31","slug":"responsable-fiscalite-douaniere-h-f","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2020\/responsable-fiscalite-douaniere-h-f\/","title":{"rendered":"RESPONSABLE FISCALIT\u00c9 DOUANI\u00c8RE (H\/F)"},"content":{"rendered":"\n<p>Le Cabinet HK Audit &amp; Conseils recherche pour un de ses clients, un<br>responsable fiscalit\u00e9 douani\u00e8re (H\/F) bas\u00e9 \u00e0 Yaound\u00e9.<\/p>\n\n\n\n<p><br>VOTRE MISSION<\/p>\n\n\n\n<p><br>Hi\u00e9rarchiquement rattach\u00e9 au Directeur Administratif et Financier, vous avez<br>pour mission d\u2019assurer l\u2019interface entre le Client et la Douane en recueillant<br>les pi\u00e8ces du client, en v\u00e9rifiant leur conformit\u00e9 \u00e0 la r\u00e9glementation en vigueur<br>et en r\u00e9alisant la d\u00e9claration en douane qu&rsquo;elle soit d&rsquo;importation ou<br>d&rsquo;exportation.<br>\u00c0 cet effet, vous devrez :<br>\uf0a7 Ouvrir et analyser les dossiers ;<br>\uf0a7 Assurer la responsabilit\u00e9 des aspects li\u00e9s \u00e0 la fiscalit\u00e9 ;<br>\uf0a7 D\u00e9finir, suivre et optimiser la politique fiscale de l&rsquo;entreprise ;<br>\uf0a7 Contr\u00f4ler le respect des proc\u00e9dures et des \u00e9ch\u00e9ances fiscales ;<br>\uf0a7 \u00c9tablir les liasses fiscales ;<br>\uf0a7 R\u00e9aliser les d\u00e9clarations fiscales (TVA, Imp\u00f4ts sur les soci\u00e9t\u00e9s, autres<br>taxes\u2026) et sociales courantes ;<br>\uf0a7 Assurer le paiement des diff\u00e9rents imp\u00f4ts dans le strict respect des<br>d\u00e9lais ;<br>\uf0a7 Effectuer la v\u00e9rification documentaire en contr\u00f4lant la conformit\u00e9 des<br>documents avec la l\u00e9gislation douani\u00e8re, relever les anomalies (si elles<br>existent) et les remonter pour action corrective ;<br>\uf0a7 R\u00e9aliser la tarification et communiquer \u00e0 la douane tous les<br>renseignements concernant la nature et le parcours des marchandises<br>;<br>\uf0a7 R\u00e9aliser la codification, calculer la valeur CAF afin de d\u00e9terminer le<br>montant des droits et taxes \u00e0 payer pour l\u2019import ou l\u2019export ;<br>\uf0a7 Saisir les \u00e9l\u00e9ments du dossier dans l\u2019outil SYDONYA ;<br>\uf0a7 Contr\u00f4ler les d\u00e9clarations provisoires et apposer le bon \u00e0 valider en<br>cas de demande du N+1 ;<br>\uf0a7 Se rendre au poste de douane en cas de besoin pour effectuer un<br>contr\u00f4le physique des marchandises ;<br>\uf0a7 Intervenir aupr\u00e8s des diff\u00e9rentes administrations douani\u00e8res afin de<br>g\u00e9rer et r\u00e9soudre les litiges douaniers ;<br>\uf0a7 Assister aux r\u00e9unions de coordination et faire un feed-back r\u00e9gulier<br>sur l\u2019\u00e9tat d\u2019avancement des dossiers ;<br>\uf0a7 Assister l\u2019\u00e9quipe du Service et s\u2019informer r\u00e9guli\u00e8rement sur la<br>r\u00e9glementation douani\u00e8re.<br>\uf0a7 Pr\u00e9parer et suivre les contentieux fiscaux.<br><\/p>\n\n\n\n<p><br>PROFIL REQUIS<br>\uf0a7 Dipl\u00f4me de Qualification Professionnelle de D\u00e9clarant en douane ;<br>\uf0a7 Minimum BAC+3 dans le domaine de la Fiscalit\u00e9,<\/p>\n\n\n\n<p><br>EXP\u00c9RIENCE<br>\uf0a7 Exp\u00e9rience professionnelle de 5 ans minimum dans le domaine de<br>la fiscalit\u00e9 et de la Douane.<br>\uf0a7 Tr\u00e8s bonne ma\u00eetrise des proc\u00e9dures de d\u00e9douanement.<br>\uf0a7 Tr\u00e8s bonne ma\u00eetrise de la l\u00e9gislation fiscale<\/p>\n\n\n\n<p><br>COMP\u00c9TENCES TECHNIQUES<br>\uf0a7 Ma\u00eetriser la l\u00e9gislation douani\u00e8re, et le droit du commerce<br>international import\/export ;<br>\uf0a7 Ma\u00eetriser la fiscalit\u00e9 appliqu\u00e9e aux diff\u00e9rents types de marchandises ;<br>\uf0a7 Aptitude \u00e0 s\u2019exprimer en anglais professionnel ;<br>\uf0a7 Bonne utilisation du Pack Office ;<br>COMP\u00c9TENCES COMPORTEMENTALES<br>\uf0a7 Tr\u00e8s bon relationnel et sens du client<br>\uf0a7 Rigueur aigue<br>\uf0a7 Go\u00fbt des chiffres<br>\uf0a7 Capacit\u00e9 \u00e0 travailler en autonomie<br>\uf0a7 Capacit\u00e9 \u00e0 travailler sous pression<br>\uf0a7 Disponibilit\u00e9<br>\uf0a7 Bonne probit\u00e9<br>\uf0a7 Esprit d\u2019\u00e9quipe<br>\uf0a7 Force de proposition<br>\uf0a7 \u00c9coute et remise en question<br>\uf0a7 Aptitude \u00e0 la r\u00e9solution de probl\u00e8me<br>\uf0a7 Anticipation et capacit\u00e9 d\u2019analyse<br>LIEU DE TRAVAIL : Yaound\u00e9<br>Envoyez votre candidature (Lettre de motivation + Curriculum Vitae) \u00e0<br>l\u2019adresse suivante : tambo.jules69@yahoo.fr<br>T\u00e9l\u00e9phone : 679 753 089 \/ 696 259 315<br>PRISE DE FONCTION : d\u00e9but juillet 2020<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Cabinet HK Audit &amp; Conseils recherche pour un de ses clients, un<br \/>\nresponsable fiscalit\u00e9 douani\u00e8re (H\/F) bas\u00e9 \u00e0 Yaound\u00e9.<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[346],"tags":[93,347],"villes":[136],"contrats":[],"diplomes":[212,159],"louma_meta":{"emploi_title":"RESPONSABLE FISCALIT\u00c9 DOUANI\u00c8RE (H\/F) ","emplois_employeur":3046,"emplois_date_publication":"2020-06-10","emplois_heure_publication":"","emplois_date_cloture":"2020-07-01","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"5","emploi_email":" tambo.jules69@yahoo.fr"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/3774"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=3774"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/3774\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/3031"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=3774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=3774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=3774"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=3774"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=3774"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=3774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}