{"id":37374,"date":"2023-01-17T19:42:54","date_gmt":"2023-01-17T18:42:54","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=37374"},"modified":"2023-01-17T19:44:01","modified_gmt":"2023-01-17T18:44:01","slug":"it-support-infrastructure","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/it-support-infrastructure\/","title":{"rendered":"IT SUPPORT INFRASTRUCTURE"},"content":{"rendered":"\n<p>Nous embauchons<\/p>\n\n\n\n<p>Infrastructure d\u2019Informatique<\/p>\n\n\n\n<p>Cameroun<\/p>\n\n\n\n<p>Nos valeurs<\/p>\n\n\n\n<p>Entrepreneurial<\/p>\n\n\n\n<p>Durable collaboratif<\/p>\n\n\n\n<p>Ing\u00e9nieux<\/p>\n\n\n\n<p>Agile<\/p>\n\n\n\n<p>En savoir plus \u25ba<\/p>\n\n\n\n<p>Fournir une assistance de premier niveau aux utilisateurs pour les probl\u00e8mes li\u00e9s \u00e0 l&rsquo;informatique, enregistrer tous les incidents et les suivre jusqu&rsquo;\u00e0 leur r\u00e9solution, maintenir le bon fonctionnement des syst\u00e8mes informatiques et s&rsquo;assurer que les utilisateurs en tirent le meilleur parti.<\/p>\n\n\n\n<p>Configurez les comptes et les profils des nouveaux utilisateurs et g\u00e9rez les probl\u00e8mes de mot de passe.<\/p>\n\n\n\n<p>Installer et configurer les syst\u00e8mes d&rsquo;exploitation et les applications du mat\u00e9riel informatique, l&rsquo;infrastructure TIC, y compris<\/p>\n\n\n\n<p>LAN et WAN, Wi-Fi, r\u00e9seaux, ordinateurs, ordinateurs portables et serveurs dans toute l&rsquo;organisation.<\/p>\n\n\n\n<p>Assurer le suivi des prestations fournies par les fournisseurs externes en liaison avec l&rsquo;Assistant Achats &amp; Logistique<\/p>\n\n\n\n<p>pour s&rsquo;assurer que des niveaux \u00e9lev\u00e9s de service sont re\u00e7us et maintenus conform\u00e9ment aux normes convenues.<\/p>\n\n\n\n<p>Assurer la conformit\u00e9 et le respect des politiques et proc\u00e9dures TIC.<\/p>\n\n\n\n<p>Assurez l&rsquo;acc\u00e8s des utilisateurs aux applications et aux syst\u00e8mes et r\u00e9solvez les pannes de r\u00e9seau en temps opportun.<\/p>\n\n\n\n<p>Examiner les applications en collaboration avec les utilisateurs pour d\u00e9terminer les am\u00e9liorations ou les nouveaux syst\u00e8mes.<\/p>\n\n\n\n<p>G\u00e9rer le programme de formation formalis\u00e9 pour tous les utilisateurs dans le but d&rsquo;\u00e9lever les normes de comp\u00e9tences et la sensibilisation \u00e0 l&rsquo;utilisation des nouvelles applications TIC.<\/p>\n\n\n\n<p>Pr\u00e9parer des rapports p\u00e9riodiques conform\u00e9ment aux directives de l&rsquo;organisation en mati\u00e8re de rapports \u00e0 la direction <\/p>\n\n\n\n<p>R\u00e9pondre dans les d\u00e9lais convenus aux appels<\/p>\n\n\n\n<p>Toute autre t\u00e2che assign\u00e9e de temps \u00e0 autre par le superviseur.<\/p>\n\n\n\n<p>Nos valeurs<\/p>\n\n\n\n<p>Entrepreneurial Collaboratif Durable Ing\u00e9nieux Agile<\/p>\n\n\n\n<p>Olam Agri<\/p>\n\n\n\n<p>Comp\u00e9tences\/Exp\u00e9rience<\/p>\n\n\n\n<p>Doit d\u00e9tenir au moins un baccalaur\u00e9at en TIC ou en informatique<\/p>\n\n\n\n<p>La science<\/p>\n\n\n\n<p>Au moins deux ans d&rsquo;exp\u00e9rience professionnelle dans une entreprise r\u00e9put\u00e9e<\/p>\n\n\n\n<p>organisme.<\/p>\n\n\n\n<p>Devrait avoir une certification de l&rsquo;industrie de CISCO, Microsoft ou<\/p>\n\n\n\n<p>Oracle. (Recommand\u00e9)<\/p>\n\n\n\n<p>Exp\u00e9rience de travail avec Office365 avec des comp\u00e9tences sp\u00e9cifiques dans SharePoint et OneDrive. <\/p>\n\n\n\n<p>Connaissance de l&rsquo;installation, de la configuration et du d\u00e9pannage pour<\/p>\n\n\n\n<p>syst\u00e8mes d&rsquo;exploitation, suites bureautiques informatiques, e-mail et inter\/intranet. <br><\/p>\n\n\n\n<p>Doit \u00eatre ax\u00e9 sur les r\u00e9sultats, motiv\u00e9 et capable de travailler sous un minimum de supervision.<\/p>\n\n\n\n<p>Doit \u00eatre capable de travailler sous pression. Excellentes comp\u00e9tences en communication interpersonnelle<\/p>\n\n\n\n<p>Haut niveau d&rsquo;int\u00e9grit\u00e9 et preuve de travail d&rsquo;\u00e9quipe.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Infrastructure de soutien informatique<\/p>\n\n\n\n<p>Salaire&nbsp;: \u00e0 d\u00e9terminer<\/p>\n\n\n\n<p>Lieu : OLAM Agri, BEKOKO Cameroun.<\/p>\n\n\n\n<p>Date de d\u00e9but : janvier 2023<\/p>\n\n\n\n<p>Type d&#8217;emploi : Permanent<\/p>\n\n\n\n<p>Date limite de candidature : lundi 20 janvier<\/p>\n\n\n\n<p>2023, \u00e0 17h00.<\/p>\n\n\n\n<p>Courriel : HR_cameroon@olamagri.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous embauchons Infrastructure d\u2019Informatique Cameroun Nos valeurs Entrepreneurial Durable collaboratif Ing\u00e9nieux Agile En savoir plus \u25ba Fournir une assistance de premier niveau aux utilisateurs pour&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[4065],"tags":[],"villes":[135],"contrats":[234],"diplomes":[162,212],"louma_meta":{"emploi_title":"IT SUPPORT INFRASTRUCTURE","emplois_employeur":24682,"emplois_date_publication":"2023-01-17","emplois_heure_publication":"","emplois_date_cloture":"2023-01-20","emplois_heure_cloture":"","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"HR_cameroon@olamagri.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/37374"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=37374"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/37374\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/24683"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=37374"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=37374"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=37374"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=37374"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=37374"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=37374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}