{"id":37237,"date":"2023-01-13T12:41:16","date_gmt":"2023-01-13T11:41:16","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=37237"},"modified":"2023-01-13T12:41:18","modified_gmt":"2023-01-13T11:41:18","slug":"chauffeur-prive","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/chauffeur-prive\/","title":{"rendered":"Chauffeur priv\u00e9"},"content":{"rendered":"\nRecherche d&rsquo;un chauffeur priv&eacute; pour m&rsquo;accompagner dans mes d&eacute;placements relatifs &agrave; mes activit&eacute;s.&nbsp;<br \/>Les d&eacute;placements s&rsquo;effectuent sur Yaound&eacute; et la p&eacute;riph&eacute;rie, et vers d&rsquo;autres villes telles que Bafoussam, Douala, Nkoteng.<br \/><br \/>Bien &eacute;videmment le chauffeur ne conduira pas en permanence. Il devrait &ecirc;tre disponible et chez l&#8217;employeur 6 jours sur 7.&nbsp;<br \/><br \/>Les termes et modalit&eacute;s annexes seront discut&eacute;s entre l&#8217;employeur et l&#8217;employ&eacute;.&nbsp;\n","protected":false},"excerpt":{"rendered":"<p>Recherche d&rsquo;un chauffeur priv&eacute; pour m&rsquo;accompagner dans mes d&eacute;placements relatifs &agrave; mes activit&eacute;s.&nbsp;Les d&eacute;placements s&rsquo;effectuent sur Yaound&eacute; et la p&eacute;riph&eacute;rie, et vers d&rsquo;autres villes telles&#8230;<\/p>\n","protected":false},"author":1,"comment_status":"open","ping_status":"closed","template":"","categories":[4025],"tags":[],"villes":[136],"contrats":[234,150],"diplomes":[2259],"louma_meta":{"emploi_title":"Chauffeur priv\u00e9","emplois_employeur":3046,"emplois_date_publication":"2023-01-13","emplois_heure_publication":"","emplois_date_cloture":"2023-01-20","emplois_heure_cloture":"","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"akankeut@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/37237"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=37237"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/37237\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=37237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=37237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=37237"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=37237"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=37237"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=37237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}