{"id":36684,"date":"2022-12-15T16:41:48","date_gmt":"2022-12-15T15:41:48","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=36684"},"modified":"2022-12-18T23:35:32","modified_gmt":"2022-12-18T22:35:32","slug":"comptable-tresorerie-01","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/comptable-tresorerie-01\/","title":{"rendered":"Comptable Tr\u00e9sorerie (01)\u00a0"},"content":{"rendered":"\n<p>Appel \u00e0 Candidatures<br>Cadyst Group est une holding, un acteur de l\u2019Agro-alimentaire. La mission du Groupe est d\u2019apporter aux populations africaines des produits de qualit\u00e9, respectant les standards internationaux, fabriqu\u00e9s localement et accessible \u00e0 tous.<br>Cadyst Group est constitu\u00e9 de 3 filiales : LA PASTA S.A, PANZANI Cameroun et SAE.<br>Pour les besoins de ses services, la Direction Finances-Comptabilit\u00e9 de LA PASTA S.A recherche pour la ville de Douala des candidat(e)s au poste de :<br><strong>Comptable Tr\u00e9sorerie (01)<\/strong><br>Raison d\u2019\u00eatre du poste :<br>Assurer la collecte et le traitement des \u00e9l\u00e9ments de la comptabilit\u00e9 g\u00e9n\u00e9rale, des op\u00e9rations de tr\u00e9sorerie et des op\u00e9rations diverses de l\u2019entreprise.<br>Missions principales :<\/p>\n\n\n\n<ol><li>Collecter, contr\u00f4ler et codifier les pi\u00e8ces de banques, de caisses, toutes autres pi\u00e8ces de tr\u00e9sorerie et tous les frais bancaires avant saisie<\/li><li>Saisir les pi\u00e8ces dans X3, les contr\u00f4ler et les classer<\/li><li>Produire les \u00e9tats de rapprochements bancaires<\/li><li>Produire l\u2019\u00e9tat des instances bancaires<\/li><li>Contr\u00f4ler de mani\u00e8re inopin\u00e9e les caisses<\/li><li>Analyser les comptes li\u00e9s \u00e0 la tr\u00e9sorerie<\/li><li>Traiter les effets \u00e0 payer<\/li><li>Provisionner les charges financi\u00e8res<\/li><li>Lettrer les comptes d&rsquo;imp\u00f4ts apr\u00e8s saisie des ordres de virement et les comptes de liaisons<\/li><li>Assurer la veille fiscale<\/li><li>Produire le compte de r\u00e9sultat &amp; Bilan, le reporting de charges financi\u00e8res, le reporting de ventes, et tout autre reporting n\u00e9cessaires.<br>Profil \/ Comp\u00e9tences cl\u00e9s :<br>\u2022 Bac+2\/BTS en Comptabilit\u00e9 Contr\u00f4le de Gestion ou \u00e9quivalent, avec un Baccalaur\u00e9at G2<br>\u2022 Exp\u00e9rience professionnelle de 2 ans minimum au sein d\u2019un service Comptabilit\u00e9 avec des missions<br>orient\u00e9es Tr\u00e9sorerie<br>\u2022 Maitrise de l\u2019outil informatique (Logiciels, Pack Office, etc.)<br>\u2022 Bonnes connaissances de la Fiscalit\u00e9, du plan comptable OHADA, et du transit (Import\/Export) Il\/elle doit avoir :<br>\u2022 Un esprit d\u2019initiative et d\u2019anticipation<br>\u2022 Le sens de l\u2019organisation<br>Il\/elle doit \u00eatre :<br>\u2022 Int\u00e8gre<br>\u2022 Rigoureux<\/li><li><br>Partager les valeurs suivantes : Leadership \u2013 Professionnalisme \u2013 Responsabilit\u00e9 &#8211; Esprit<br>d\u2019Equipe<\/li><li><br>Souhaitez-vous faire un bond dans votre carri\u00e8re, donner un nouvel \u00e9lan \u00e0 votre vie professionnelle ? Souhaitez-vous avoir de nouveaux challenges et progresser dans un environnement dynamique ?<\/li><li><br>D\u00e9lai de recevabilit\u00e9 des dossiers de candidature : 16 d\u00e9cembre 2022<\/li><\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Appel \u00e0 CandidaturesCadyst Group est une holding, un acteur de l\u2019Agro-alimentaire. La mission du Groupe est d\u2019apporter aux populations africaines des produits de qualit\u00e9, respectant&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[282],"tags":[],"villes":[135],"contrats":[234],"diplomes":[162,212],"louma_meta":{"emploi_title":"Comptable Tr\u00e9sorerie (01)","emplois_employeur":14731,"emplois_date_publication":"2022-12-15","emplois_heure_publication":"","emplois_date_cloture":"2022-12-16","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"1","emploi_email":"Pour postuler rendez-vous sur notre site www.lapastacameroun.com \u00e0 l\u2019onglet \u00ab carri\u00e8re \u00bb menu  \u00aboffre d\u2019emploi \u00bb"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/36684"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=36684"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/36684\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/33744"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=36684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=36684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=36684"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=36684"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=36684"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=36684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}