{"id":36635,"date":"2022-12-13T09:26:02","date_gmt":"2022-12-13T08:26:02","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=36635"},"modified":"2022-12-18T23:58:29","modified_gmt":"2022-12-18T22:58:29","slug":"01-serveuse-et-01-videur","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/01-serveuse-et-01-videur\/","title":{"rendered":"01 Serveuse et 01 Videur"},"content":{"rendered":"\n<ul><li>01 serveuse ponctuelle, r\u00e9guli\u00e8re , apte \u00e0 travailler de nuit , souple en ce qui concerne les horaires de fin de service .<\/li><\/ul>\n\n\n\n<p>-01 videur ponctuelle , r\u00e9gulier , courtois , apte \u00e0 travailler de nuit , avoir une bonne condition physique , \u00eatre flexible en ce qui concerne les horaires de fin de services .<\/p>\n\n\n\n<p>Heure de d\u00e9but de service 17 h<\/p>\n\n\n\n<p>Comment postuler ?<br>Envoyer , KEMIT lounge suivi d\u2019une photo enti\u00e8re de vous , tout en pr\u00e9cisant votre quartier de r\u00e9sidence .<\/p>\n\n\n\n<p>contacte what\u2019sapp 691 07 26 01 \/ 693 29 23 13<\/p>\n\n\n\n<p>NB: habiter les alentours de ndogbong serait un atout .<\/p>\n\n\n\n<p>Date limite : 23 D\u00e9cembre 2022<\/p>\n\n\n\n<p>Le KEMIT LOUNGE situ\u00e9 \u00e0 Douala , recherche dans le cadre de ses activit\u00e9s deux profils:<\/p>\n\n\n\n<ul><li>01 serveuse ponctuelle, r\u00e9guli\u00e8re , apte \u00e0 travailler de nuit , souple en ce qui concerne les horaires de fin de service .<\/li><\/ul>\n\n\n\n<p>-01 videur ponctuelle , r\u00e9gulier , courtois , apte \u00e0 travailler de nuit , avoir une bonne condition physique , \u00eatre flexible en ce qui concerne les horaires de fin de services .<\/p>\n\n\n\n<p>Heure de d\u00e9but de service 17 h<\/p>\n\n\n\n<p>Comment postuler ?<br>Envoyer , KEMIT lounge suivi d\u2019une photo enti\u00e8re de vous , tout en pr\u00e9cisant votre quartier de r\u00e9sidence .<\/p>\n\n\n\n<p>contacte what\u2019sapp 691 07 26 01 \/ 693 29 23 13<\/p>\n\n\n\n<p>NB: habiter les alentours de ndogbong serait un atout .<\/p>\n\n\n\n<p>Date limite : 23 D\u00e9cembre 2022<\/p>\n","protected":false},"excerpt":{"rendered":"<p>01 serveuse ponctuelle, r\u00e9guli\u00e8re , apte \u00e0 travailler de nuit , souple en ce qui concerne les horaires de fin de service . -01 videur&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[1182],"tags":[],"villes":[135],"contrats":[234],"diplomes":[162,212],"louma_meta":{"emploi_title":"01 Serveuse et 01 Videur","emplois_employeur":3046,"emplois_date_publication":"2022-12-13","emplois_heure_publication":"","emplois_date_cloture":"2022-12-31","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"691 07 26 01 \/ 693 29 23 13"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/36635"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=36635"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/36635\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=36635"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=36635"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=36635"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=36635"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=36635"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=36635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}