{"id":36457,"date":"2022-12-06T11:20:48","date_gmt":"2022-12-06T10:20:48","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=36457"},"modified":"2022-12-06T11:20:51","modified_gmt":"2022-12-06T10:20:51","slug":"specialite-grillade","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/specialite-grillade\/","title":{"rendered":"Sp\u00e9cialit\u00e9 Grillade"},"content":{"rendered":"\n<pre class=\"wp-block-code\"><code>Titre du poste : Sp\u00e9cialit\u00e9 Grillade,\ndate d'expiration : 2022-12-16,\nNouvelle entreprise : Love grillade \nPays : cameroun,\nvilles : douala,\ncontact pour postuler : mylittlefarm237@gmail.com\n\n<p class=\"p1\" style=\"margin: 0px;font-size: 13px;line-height: normal;font-family: 'Helvetica Neue'\">Exp\u00e9rience: pas obligatoire( mais n\u00e9cessaire niveau assaisonnement )<span class=\"Apple-converted-space\">&nbsp;<\/span><\/p> <p class=\"p1\" style=\"margin: 0px;font-size: 13px;line-height: normal;font-family: 'Helvetica Neue'\">Travail : De Lundi \u00e0 Samedi (10hr - 18hr30)<\/p> <p class=\"p1\" style=\"margin: 0px;font-size: 13px;line-height: normal;font-family: 'Helvetica Neue'\">Salaire :30000 fcfa le mois<span class=\"Apple-converted-space\">&nbsp;<\/span><\/p> <p class=\"p1\" style=\"margin: 0px;font-size: 13px;line-height: normal;font-family: 'Helvetica Neue'\">Situ\u00e9 : pk8 esg universit\u00e9 campus num\u00e9rique D<span class=\"Apple-converted-space\">&nbsp;<\/span><\/p> <p class=\"p1\" style=\"margin: 0px;font-size: 13px;line-height: normal;font-family: 'Helvetica Neue'\"><span class=\"Apple-converted-space\">&nbsp;<\/span>D\u00e9tail job :<\/p> <p class=\"p1\" style=\"margin: 0px;font-size: 13px;line-height: normal;font-family: 'Helvetica Neue'\">Assaisonner et grill\u00e9 (poisson,brochette de porc,poulet,viande) faire leur compl\u00e9ment&nbsp; accompagn\u00e9 de leur sauce de condiments et piments . Bien prendre soins de son espace et du mat\u00e9riel.&nbsp; faire les courses pour les grillades.<\/p><\/code><\/pre>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[1182],"tags":[],"villes":[135],"contrats":[234],"diplomes":[156,164],"louma_meta":{"emploi_title":"Sp\u00e9cialit\u00e9 Grillade","emplois_employeur":3046,"emplois_date_publication":"2022-12-06","emplois_heure_publication":"","emplois_date_cloture":"2022-12-31","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"mylittlefarm237@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/36457"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=36457"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/36457\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=36457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=36457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=36457"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=36457"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=36457"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=36457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}