{"id":36438,"date":"2022-12-05T19:26:35","date_gmt":"2022-12-05T18:26:35","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=36438"},"modified":"2022-12-05T19:26:37","modified_gmt":"2022-12-05T18:26:37","slug":"nounou-residente","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/nounou-residente\/","title":{"rendered":"Nounou R\u00e9sidente"},"content":{"rendered":"\n<p>Un particulier recherche pour son domicile situ\u00e9 \u00e0 Douala &#8211; Logbessou une Nounou R\u00e9sidente . <\/p>\n\n\n\n<p>1.Conditions Age : Compris entre 18-35 ans Jour de repos :<\/p>\n\n\n\n<p> A discuter avec l&rsquo;Employeur Nombre de personnes en charges :<\/p>\n\n\n\n<p> 2 Enfants ( 2 ans et 3 mois ) . <\/p>\n\n\n\n<p>2.Profil * Etre Anglophone ou bilingue <\/p>\n\n\n\n<p>* Etre propre et avoir une bonne moralit\u00e9<\/p>\n\n\n\n<p> * Etre respectueuse et patiente envers les enfants . <\/p>\n\n\n\n<p>3.Taches \u00e0 effectuer * S&rsquo;occuper des Enfants principalement et de la maison ( en cas de besoin ) . <\/p>\n\n\n\n<p>Bien vouloir nous joindre sur WhatsApp au 682444304 suivi de la capture d&rsquo;\u00e9cran de l&rsquo;offre . ba J U<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un particulier recherche pour son domicile situ\u00e9 \u00e0 Douala &#8211; Logbessou une Nounou R\u00e9sidente . 1.Conditions Age : Compris entre 18-35 ans Jour de repos&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[4018],"tags":[],"villes":[136],"contrats":[234],"diplomes":[3083,157],"louma_meta":{"emploi_title":"Nounou R\u00e9sidente","emplois_employeur":3046,"emplois_date_publication":"2022-12-05","emplois_heure_publication":"","emplois_date_cloture":"2022-12-31","emplois_heure_cloture":"","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"682444304"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/36438"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=36438"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/36438\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=36438"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=36438"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=36438"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=36438"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=36438"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=36438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}