{"id":36325,"date":"2022-11-30T14:19:47","date_gmt":"2022-11-30T13:19:47","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=36325"},"modified":"2022-11-30T14:19:49","modified_gmt":"2022-11-30T13:19:49","slug":"chauffeur-bilingue","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/chauffeur-bilingue\/","title":{"rendered":"Chauffeur Bilingue"},"content":{"rendered":"\n<p>Profil: recherche d&rsquo;un chauffeur bilingue dans la ville de Douala<\/p>\n\n\n\n<ul><li>Nombre de poste:1<\/li><li>Niveau acad\u00e9mique minimun: CEPE, BEPC ou plus<\/li><li>\u00catre titulaire d&rsquo;un permis B<\/li><li>R\u00e9sident au environ de Bonab\u00e9ri ou Deido<\/li><li>Respecter et faire respecter le code de la route<\/li><li>Savoir lire et \u00e9crit (anglais et fran\u00e7ais)<\/li><li>Respecter strictement les horaires et consignes de travail<\/li><li>Exp\u00e9rience professionnelle : 1 an minimum \u00e0 un poste similaire<\/li><li>\u00e2ge : 23 &#8211; 45 ans<\/li><li>Capable de travailler sous pression<\/li><\/ul>\n\n\n\n<p>Toutes les candidats int\u00e9ress\u00e9s sont pri\u00e9s de bien envoyer leur CV + photocopie permis de conduire cat\u00e9gorie B. via WhatsApp au num\u00e9ro 691092849<\/p>\n\n\n\n<p>D\u00e9lai de recevabilit\u00e9 des candidatures : LUNDI 5 DECEMBRE 2022<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Profil: recherche d&rsquo;un chauffeur bilingue dans la ville de Douala Nombre de poste:1 Niveau acad\u00e9mique minimun: CEPE, BEPC ou plus \u00catre titulaire d&rsquo;un permis B&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[4025],"tags":[],"villes":[135],"contrats":[234],"diplomes":[162,2259],"louma_meta":{"emploi_title":"Chauffeur Bilingue ","emplois_employeur":3046,"emplois_date_publication":"2022-11-30","emplois_heure_publication":"","emplois_date_cloture":"2022-12-30","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":" 691092849"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/36325"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=36325"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/36325\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=36325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=36325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=36325"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=36325"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=36325"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=36325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}