{"id":36189,"date":"2022-11-28T14:30:26","date_gmt":"2022-11-28T13:30:26","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=36189"},"modified":"2022-11-28T14:30:28","modified_gmt":"2022-11-28T13:30:28","slug":"controleur-interne-h-f","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/controleur-interne-h-f\/","title":{"rendered":"Contr\u00f4leur Interne H\/F"},"content":{"rendered":"\n<pre class=\"wp-block-code\"><code>Contr\u00f4leur Interne H\/F\n\nLieu\nDouala, Littoral\n\nPubli\u00e9\n0 jours\n\nCat\u00e9gorie du poste\nComptabilit\u00e9 \/ Gestion \/ Finance\n\nType de poste\nCDI - temps plein\n\nExp\u00e9rience\nNon pr\u00e9cis\u00e9\n\nPostuler\nPartager cette offre avec\n\nfacebook sharing buttontwitter sharing buttonlinkedin sharing buttonemail sharing button\nDescription du poste\n\nR\u00e9f\u00e9rence :AUD\/1022\/002780\n\nType de contrat : CDI\n\nM\u00e9tier\/Sp\u00e9cialit\u00e9 : Banque \/ Assurances\n\nLocalisation g\u00e9ographique :\nPays : Cameroun\nVille : Douala, R\u00e9gion du Littoral, CM\n\n\n\nNotre soci\u00e9t\u00e9 : \n\nActeur majeur du recrutement en Afrique Centrale, Apave International vous propose chaque semaine de nombreuses opportunit\u00e9s de carri\u00e8re au sein d'entreprises priv\u00e9es ou publiques et d'Institutions Internationales.\n\n\n\nMission : \n\nMISSIONS:\n\nGarantir la conformit\u00e9 r\u00e8glementaire g\u00e9n\u00e9rale;\nContr\u00f4le de la mise en conformit\u00e9;\nRenforcement et \u00e9volution du dispositif de contr\u00f4le interne;\nVeille r\u00e9glementaire : Assurer une veille normative et r\u00e8glementaire et \u00eatre charg\u00e9(e) de sa diffusion et de sa bonne compr\u00e9hension par l'ensemble des directions;\nACTIVITES:\n\nConcevoir et mettre en place le r\u00e9f\u00e9rentiel et le dispositif de conformit\u00e9;\nPilotage du contr\u00f4le et du dispositif de reporting de conformit\u00e9;\n\u00catre le\/la r\u00e9f\u00e9rent(e) des directions m\u00e9tier sur les questions de conformit\u00e9 r\u00e8glementaire;\nParticipation \u00e0 la formation des collaborateurs et diffusion de la culture de la conformit\u00e9;\nCompl\u00e9ter, renforcer et fiabiliser le dispositif de conformit\u00e9 du patrimoine;\nVeiller \u00e0 la compl\u00e9tude et \u00e0 la mise \u00e0 jour des plans d'action relatifs \u00e0 la conformit\u00e9 du patrimoine, et contr\u00f4ler leur mise en \u0153uvre;\nConstruire et piloter le plan d'audit externe de conformit\u00e9 du patrimoine;\nSuivre et compl\u00e9ter les proc\u00e9dures;\nD\u00e9finition et mise en place des plans de contr\u00f4les de niveau 1, et 2, et veiller \u00e0 leur respect;\nParticipation aux retours d'exp\u00e9rience op\u00e9rationnelle;\nToutes autres activit\u00e9s donn\u00e9es par le sup\u00e9rieur hi\u00e9rarchique.\n\n\n\n\nProfil : \n\nBac+4\/5 en comptabilit\u00e9, audit contr\u00f4le de gestion;\nAvoir des connaissances en finance comptabilit\u00e9 et analyses des risques;\nAvoir une vision transversale du m\u00e9tier;\nAvoir maximum 3 ans d'exp\u00e9rience en audit financier;\n\n\nNiveau d'\u00e9tudes : MASTER 2 \/ BAC+5\n\nSp\u00e9cialisation : Audit \/ Contr\u00f4le de gestion\n\nNiveau d'exp\u00e9rience : Exp\u00e9riment\u00e9 (de 3 \u00e0 5 ans)\n\nLangues : \nFran\u00e7ais : Ma\u00eetrise courante\nAnglais : Bonne pratique\nCrit\u00e8res du poste\n\nBac+4\/5 en comptabilit\u00e9, audit contr\u00f4le de gestion;\nAvoir des connaissances en finance comptabilit\u00e9 et analyses des risques;\nAvoir une vision transversale du m\u00e9tier;\nAvoir maximum 3 ans d'exp\u00e9rience en audit financier;\nPostuler<\/code><\/pre>\n","protected":false},"excerpt":{"rendered":"<p>Acteur majeur du recrutement en Afrique Centrale, Apave International vous propose chaque semaine de nombreuses opportunit\u00e9s de carri\u00e8re au sein d&rsquo;entreprises priv\u00e9es ou publiques et d&rsquo;Institutions Internationales.<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[21],"tags":[],"villes":[135],"contrats":[234],"diplomes":[162,212,159],"louma_meta":{"emploi_title":"Contr\u00f4leur Interne H\/F","emplois_employeur":2981,"emplois_date_publication":"2022-11-28","emplois_heure_publication":"","emplois_date_cloture":"2022-12-28","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"https:\/\/www.jobs.net\/jobs\/apave\/fr\/job\/Cameroon\/Contr-leur-Interne-H-F\/J3W48J710QD15W6ZWJS\/"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/36189"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=36189"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/36189\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/2982"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=36189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=36189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=36189"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=36189"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=36189"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=36189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}