{"id":35908,"date":"2022-11-15T11:41:44","date_gmt":"2022-11-15T10:41:44","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=35908"},"modified":"2022-11-15T11:41:46","modified_gmt":"2022-11-15T10:41:46","slug":"%f0%9d%90%91%f0%9d%90%9e%f0%9d%90%9c%f0%9d%90%ab%f0%9d%90%ae%f0%9d%90%ad%f0%9d%90%9e%f0%9d%90%a6%f0%9d%90%9e%f0%9d%90%a7%f0%9d%90%ad-%f0%9d%90%9d%f0%9d%90%ae%f0%9d%90%a7%f0%9d%90%9e-%f0%9d%90%ab","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/%f0%9d%90%91%f0%9d%90%9e%f0%9d%90%9c%f0%9d%90%ab%f0%9d%90%ae%f0%9d%90%ad%f0%9d%90%9e%f0%9d%90%a6%f0%9d%90%9e%f0%9d%90%a7%f0%9d%90%ad-%f0%9d%90%9d%f0%9d%90%ae%f0%9d%90%a7%f0%9d%90%9e-%f0%9d%90%ab\/","title":{"rendered":"\ud835\udc11\ud835\udc1e\ud835\udc1c\ud835\udc2b\ud835\udc2e\ud835\udc2d\ud835\udc1e\ud835\udc26\ud835\udc1e\ud835\udc27\ud835\udc2d \ud835\udc1d&rsquo;\ud835\udc2e\ud835\udc27\ud835\udc1e \ud835\udc2b\ud835\udc1e\ud835\udc2c\ud835\udc29\ud835\udc28\ud835\udc27\ud835\udc2c\ud835\udc1a\ud835\udc1b\ud835\udc25\ud835\udc1e \ud835\udc1d\ud835\udc1e \ud835\udc12\ud835\udc21\ud835\udc28\ud835\udc30\ud835\udc2b\ud835\udc28\ud835\udc28\ud835\udc26 \/ Point relais"},"content":{"rendered":"\n<p>\ud835\udc11\ud835\udc1e\ud835\udc1c\ud835\udc2b\ud835\udc2e\ud835\udc2d\ud835\udc1e\ud835\udc26\ud835\udc1e\ud835\udc27\ud835\udc2d \ud835\udc1d&rsquo;\ud835\udc2e\ud835\udc27\ud835\udc1e \ud835\udc2b\ud835\udc1e\ud835\udc2c\ud835\udc29\ud835\udc28\ud835\udc27\ud835\udc2c\ud835\udc1a\ud835\udc1b\ud835\udc25\ud835\udc1e \ud835\udc1d\ud835\udc1e \ud835\udc12\ud835\udc21\ud835\udc28\ud835\udc30\ud835\udc2b\ud835\udc28\ud835\udc28\ud835\udc26 \/ Point relais \ud83d\udc4d<br>Nous recherchons activement une femme pouvant assurer la gestion de notre showroom ci \u00e0 DOUALA\/AKWA<br>Niveau BTS au minimum, ou licence, nous voulons avant tout une personne soucieuse de d\u00e9velopper une activit\u00e9 qui d\u00e9marre.<br>Vous serez charg\u00e9e de<\/p>\n\n\n\n<ul><li>Accueillir les clients qui viennent pour se renseigner ou retirer des colis<\/li><li>Travailler la politique d&rsquo;exposition des produits du showroom<\/li><li>Assurer le retrait des colis et assister le client pour leur test avant retrait quand situation l&rsquo;exige<\/li><li>Coordonner vos actions avec l&rsquo;\u00e9quipe logistique pour le suivi des colis \u00e0 retirer en agence<\/li><li>Faire des rapports sur l&rsquo;activit\u00e9 du showroom\/point relais<\/li><\/ul>\n\n\n\n<p>Jeune, dynamique, motiv\u00e9 par l&rsquo;envi de participer \u00e0 un projet remplie de challenges, vous devez avoir<\/p>\n\n\n\n<ul><li>un fort sens de l&rsquo;\u00e9coute<\/li><li>le sens de l&rsquo;accueil et une politesse irr\u00e9prochable<\/li><li>un vrai esprit de la responsabilit\u00e9<br>\ud835\udc04\ud835\udc27\ud835\udc2f\ud835\udc28\ud835\udc32\ud835\udc1e\ud835\udc33 \ud835\udc1c\ud835\udc2f \ud835\udc1e\ud835\udc2d \ud835\udc25\ud835\udc1e\ud835\udc2d\ud835\udc2d\ud835\udc2b\ud835\udc1e \ud835\udc1d\ud835\udc1e \ud835\udc26\ud835\udc28\ud835\udc2d\ud835\udc22\ud835\udc2f\ud835\udc1a\ud835\udc2d\ud835\udc22\ud835\udc28\ud835\udc27 \u00e0 jobs@iziway.cm en pr\u00e9cisant dans le titre : Candidature Responsable Showroom<br>:profil r\u00e9serv\u00e9 uniquement aux femmes<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Nous recherchons activement une femme pouvant assurer la gestion de notre showroom ci \u00e0 DOUALA\/AKWA<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[21],"tags":[4],"villes":[135],"contrats":[234],"diplomes":[162,212],"louma_meta":{"emploi_title":"\ud835\udc11\ud835\udc1e\ud835\udc1c\ud835\udc2b\ud835\udc2e\ud835\udc2d\ud835\udc1e\ud835\udc26\ud835\udc1e\ud835\udc27\ud835\udc2d \ud835\udc1d'\ud835\udc2e\ud835\udc27\ud835\udc1e \ud835\udc2b\ud835\udc1e\ud835\udc2c\ud835\udc29\ud835\udc28\ud835\udc27\ud835\udc2c\ud835\udc1a\ud835\udc1b\ud835\udc25\ud835\udc1e \ud835\udc1d\ud835\udc1e \ud835\udc12\ud835\udc21\ud835\udc28\ud835\udc30\ud835\udc2b\ud835\udc28\ud835\udc28\ud835\udc26 \/ Point relais ","emplois_employeur":8793,"emplois_date_publication":"2022-11-15","emplois_heure_publication":"","emplois_date_cloture":"2022-11-30","emplois_heure_cloture":"","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"jobs@iziway.cm "},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/35908"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=35908"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/35908\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/8794"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=35908"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=35908"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=35908"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=35908"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=35908"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=35908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}