{"id":35864,"date":"2022-11-14T12:29:31","date_gmt":"2022-11-14T11:29:31","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=35864"},"modified":"2022-11-14T12:29:34","modified_gmt":"2022-11-14T11:29:34","slug":"formateur-formatrice-danglais","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/formateur-formatrice-danglais\/","title":{"rendered":"Formateur \/ Formatrice d&rsquo;anglais"},"content":{"rendered":"\n<pre class=\"wp-block-code\"><code>Titre du poste : Formateur \/ Formatrice d'anglais,\ndate d'expiration : 2022-11-17,\nentreprise : CE2I,\nPays : cameroun,\nvilles : Douala,\ncontact pour postuler : centredensen@gmail.com\n\n<p class=\"MsoNormal\"><span style=\"font-size: 14.0pt;line-height: 115%;font-family: 'Helvetica','sans-serif';color: #414042;background: white\">CE2I est l'un des leaders du soutien scolaire et de la formation professionnelle<\/span> au Cameroun<\/p> <p class=\"MsoNormal\"><span style=\"font-size: 14.0pt;line-height: 115%;font-family: 'Helvetica','sans-serif';color: #414042;background: white\">Nous recherchons un formateur en anglais pour dispenser 10h de cours en pr\u00e9sentiel par semaine dans le cadre de nos formations professionnelles <\/span><\/p> <p class=\"MsoNormal\"><span style=\"font-size: 14.0pt;line-height: 115%;font-family: 'Helvetica','sans-serif';color: #414042;background: white\">Vous enseignerez selon une m\u00e9thode \u00e0 laquelle vous serez form\u00e9(e) lors de votre embauche et tout au long de votre parcours . Vous aurez des supports de formation \u00e0 votre disposition pour pr\u00e9parer et animer vos cours. Vous interviendrez aupr\u00e8s d'un public d'adultes de niveaux d\u00e9butants, interm\u00e9diaires ou avanc\u00e9s par petits groupes sur le centre, <span>&nbsp;<\/span>par visio etc... <\/span><\/p><\/code><\/pre>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[21],"tags":[245],"villes":[135],"contrats":[234],"diplomes":[162,212],"louma_meta":{"emploi_title":"Formateur \/ Formatrice d'anglais","emplois_employeur":3046,"emplois_date_publication":"2022-11-14","emplois_heure_publication":"","emplois_date_cloture":"2022-11-30","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":" centredensen@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/35864"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=35864"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/35864\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=35864"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=35864"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=35864"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=35864"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=35864"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=35864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}