{"id":35825,"date":"2022-11-10T11:54:27","date_gmt":"2022-11-10T10:54:27","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=35825"},"modified":"2022-11-10T12:00:30","modified_gmt":"2022-11-10T11:00:30","slug":"responsable-regional-h-f","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/responsable-regional-h-f\/","title":{"rendered":"RESPONSABLE REGIONAL H\/F"},"content":{"rendered":"\n<p>AFRICA FOOD IMPORT SA recherche actuellement pour une de ses agences un(e) RESPONSABLE REGIONAL H\/F<br>Le\/La Responsable R\u00e9gional aura pour missions de :<\/p>\n\n\n\n<ul><li>Veiller \u00e0 l\u2019atteinte des objectifs de vente et d\u2019encaissement, \u00e0 la gestion et au d\u00e9veloppement des partenaires strat\u00e9giques ;<\/li><li>Assurer la profitabilit\u00e9 des partenaires strat\u00e9giques et le recrutement des nouveaux partenaires,<\/li><li>Centraliser et traiter \u00e9galement toutes les plaintes et r\u00e9clamations de son portefeuille client ;<\/li><li>Veiller au respect des proc\u00e9dures de ventes.<br>ACTIVITES<br>1- COMMERCIALES<\/li><li>animer et f\u00e9d\u00e9rer les efforts de son \u00e9quipe pour r\u00e9aliser les objectifs de son territoire ;<\/li><li>veiller \u00e0 la fixation des objectifs aux partenaires et assurer le suivi de leur r\u00e9alisation ;<\/li><li>analyser les stocks des Partenaires et s\u2019assurer de disposer au moins 15 jours de stocks pour chacun des SKU ;<\/li><li>Produire hebdomadairement les plans d\u00e9taill\u00e9s par SKU de facturation et d\u2019encaissement et assurer leur r\u00e9alisation;<\/li><li>mettre \u00e0 jour les diff\u00e9rents tableaux de bord de gestion et assurer le bon reporting de toutes les activit\u00e9s \u00e0 temps ;<\/li><li>s\u2019assurer journali\u00e8rement du bon d\u00e9nouement de toutes les transactions commerciales de son territoire ;<\/li><li>produire une analyse des tendances de ventes afin d\u2019anticiper sur les approvisionnements ;<\/li><li>suivre les r\u00e9clamations clients et faire le reporting chaque semaine ;<\/li><li>s\u2019assurer que tous ses partenaires gagnent des ristournes chaque fin de mois ;<\/li><li>Boucler les journ\u00e9es de Ventes (Transmission \u00e0 l\u2019agence) ;<br>2- COMPTABLES<\/li><li>veiller \u00e0 une tenue r\u00e9glementaire des documents de gestion des stocks et de vente des partenaires strat\u00e9giques ;<\/li><li>veiller \u00e0 une tenue extracomptable des comptes clients ;<\/li><li>Veiller \u00e0 la collecte et transmission des bordereaux de versements et liasse commerciale ;<\/li><li>Suivi des cr\u00e9ances ;<\/li><li>Produire la situation du risk analysis PS chaque mois avec les actions \u00e0 entreprendre<br>3- CONTROLES<\/li><li>assurer le respect des proc\u00e9dures et la protection du patrimoine du territoire dont il a la charge. &#8211; s\u2019assurer du bon respect des proc\u00e9dures commerciales<\/li><li>renforcer le dispositif de contr\u00f4le \u00e0 priori (conformit\u00e9 BL BC FACT. vs sp\u00e9cimen signature) Gestion logistique et administrative<br>T\u00e9l\u00e9phone utilis\u00e9 par l\u2019ex controleur interne -Assurer le suivi des livraisons des produits command\u00e9s.<\/li><\/ul>\n\n\n\n<p>PROFIL<\/p>\n\n\n\n<ul><li>Titulaire d\u2019un Bac + 5 en commerce, vente, management ou tout autre dipl\u00f4me \u00e9quivalent ;<\/li><li>Exp\u00e9rience professionnelle : 7ann\u00e9es d\u2019exp\u00e9rience \u00e0 un poste similaire ;<\/li><li>Age minimum : 34 ans<\/li><li>Avoir de bonnes connaissances des habitudes de l\u2019open market,<\/li><li>Avoir de bonnes connaissances des techniques de management ;<\/li><li>Avoir une aisance \u00e0 manipuler les fonds ;<\/li><li>Sens aigu du service et du contact (multiples interlocuteurs)<\/li><li>La pratique de la langue anglaise serait un atout.<\/li><li>Organis\u00e9 et rigoureux, dynamique et motiv\u00e9.<\/li><\/ul>\n\n\n\n<p>Vous appr\u00e9ciez travailler en \u00e9quipe et \u00eates r\u00e9sistant au stress.<\/p>\n\n\n\n<p>Votre r\u00e9activit\u00e9, votre disponibilit\u00e9, vous permettront de vous \u00e9panouir pleinement au sein de notre soci\u00e9t\u00e9.<\/p>\n\n\n\n<p>Dossier de candidature : CV, lettre de motivation<br>Deadline : 15 Novembre 2022<br>Envoyez votre dossier de candidature \u00e0 : recrutement@africafooddistribution.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>AFRICA FOOD IMPORT SA recherche actuellement pour une de ses agences un(e) RESPONSABLE REGIONAL H\/FLe\/La Responsable R\u00e9gional aura pour missions de : Veiller \u00e0 l\u2019atteinte&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[21],"tags":[],"villes":[2714],"contrats":[234],"diplomes":[162,212,159],"louma_meta":{"emploi_title":"RESPONSABLE REGIONAL H\/F","emplois_employeur":7626,"emplois_date_publication":"2022-11-10","emplois_heure_publication":"","emplois_date_cloture":"2022-11-15","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"recrutement@africafooddistribution.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/35825"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=35825"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/35825\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/7627"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=35825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=35825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=35825"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=35825"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=35825"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=35825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}