{"id":35688,"date":"2022-11-04T11:13:03","date_gmt":"2022-11-04T10:13:03","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=35688"},"modified":"2022-11-04T11:13:06","modified_gmt":"2022-11-04T10:13:06","slug":"gestionnaire-de-projets-h-f","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/gestionnaire-de-projets-h-f\/","title":{"rendered":"Gestionnaire de Projets H\/F"},"content":{"rendered":"\n<p>Gestionnaire de Projets H\/F<\/p>\n\n\n\n<p>Lieu<\/p>\n\n\n\n<p>Douala,&nbsp;LittoralPubli\u00e9<\/p>\n\n\n\n<p>2 joursCat\u00e9gorie du poste<\/p>\n\n\n\n<p>Administration\/Organisation\/Services G\u00e9n\u00e9raux, Transport \/ LogistiqueType de poste<\/p>\n\n\n\n<p>CDI &#8211; temps pleinExp\u00e9rience<\/p>\n\n\n\n<p>Non pr\u00e9cis\u00e9<\/p>\n\n\n\n<p><a href=\"https:\/\/application.careerbuilder1.eu\/apave\/apply\/cb1\/J3M2CW6TMXFFL40MGZB?IPath=TNJob&amp;Job_DID=J3M2CW6TMXFFL40MGZB&amp;SiteID=cbnsv&amp;VID=VX5BD07E50F82D11ECAFDA2BF8D25F83C223113H&amp;sc_cmp1=JS_JobDetails_ApplyNow&amp;TN_DID=TNKD38560K16M285NSH4&amp;language=fr\">Postuler<\/a><\/p>\n\n\n\n<p id=\"shareThisJDP\">Partager cette offre avec<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/platform-cdn.sharethis.com\/img\/facebook.svg\" alt=\"facebook sharing button\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/platform-cdn.sharethis.com\/img\/twitter.svg\" alt=\"twitter sharing button\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/platform-cdn.sharethis.com\/img\/linkedin.svg\" alt=\"linkedin sharing button\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/platform-cdn.sharethis.com\/img\/email.svg\" alt=\"email sharing button\" \/><\/figure>\n\n\n\n<p>Description du poste<\/p>\n\n\n\n<p>R\u00e9f\u00e9rence :AGE\/1122\/002791<\/p>\n\n\n\n<p>Type de contrat :&nbsp;CDI<\/p>\n\n\n\n<p>M\u00e9tier\/Sp\u00e9cialit\u00e9 :&nbsp;Environnement \/ D\u00e9veloppement Durable<\/p>\n\n\n\n<p>Localisation g\u00e9ographique :<br>Pays : Cameroun<br>Ville : Douala, R\u00e9gion du Littoral, CM<\/p>\n\n\n\n<p><strong>Notre soci\u00e9t\u00e9 :&nbsp;<\/strong><\/p>\n\n\n\n<p>Acteur majeur du recrutement en Afrique Centrale, Apave International vous propose chaque semaine de nombreuses opportunit\u00e9s de carri\u00e8re au sein d&rsquo;entreprises priv\u00e9es ou publiques et d&rsquo;Institutions Internationales.<\/p>\n\n\n\n<p><strong>Mission :&nbsp;<\/strong><\/p>\n\n\n\n<ul><li>Suivre la planification des r\u00e9unions et de l\u2019agenda de l\u2019\u00e9quipe, r\u00e9daction des comptes rendus et suivi des r\u00e9solutions qui en d\u00e9couleront.<\/li><li>G\u00e9rer les relations entre interlocuteurs internes et externes au projet<\/li><li>Veiller \u00e0 int\u00e9grer toute \u00e9volution du projet ayant un impact sur les d\u00e9lais, les ressources \u00e0 mobiliser et la documentation.<\/li><li>Animer son \u00e9quipe, contr\u00f4ler les livrables, assurer \u00e9galement la bonne coordination et collaboration.<\/li><li>Suivre (avancement calendaire et physique) les missions du D\u00e9partement des Projets (gestion de l\u2019accueil et du transport, gestion des t\u00e9l\u00e9phones portables\u2026);<\/li><li>&nbsp;Mettre \u00e0 jour les plannings, les plans de charges, les d\u00e9penses du projet ainsi que les fiches de risques et d\u2019opportunit\u00e9s ;<\/li><li>&nbsp;Contr\u00f4ler l&rsquo;ensemble des co\u00fbts des projets (engagements, d\u00e9penses, modifications et transferts budg\u00e9taires, provisions);<\/li><li>&nbsp;Collecter, archiver et envoyer des justificatifs n\u00e9cessaires au suivi financier et en particulier des cautions;<\/li><li>&nbsp;Mettre en place et maintenir un syst\u00e8me de gestion et d\u2019archivage des dossiers efficace et efficient en temps r\u00e9el.<\/li><\/ul>\n\n\n\n<p><strong>Profil :&nbsp;<\/strong><\/p>\n\n\n\n<ul><li>Minimum Bac +3 en Gestion;<\/li><li>une exp\u00e9rience en Gestion des projets serait un atout ind\u00e9niable&nbsp;<\/li><li>Connaissance des proc\u00e9dures de l\u2019administration publique et des appels<br>d\u2019offres;<\/li><li>Connaissance g\u00e9n\u00e9rale des techniques de gestion des projets;<\/li><li>Ma\u00eetrise des outils bureautiques classiques (Office 365, etc) et\/ou collaboratifs (Google: Docs, Sheet, Slide);<\/li><li>Bonne utilisation des outils de communication (t\u00e9l\u00e9phone, messagerie, agenda \u00e9lectronique\u2026);<\/li><li>Capacit\u00e9 d\u2019organisation, polyvalence;<\/li><li>Aptitude \u00e0 travailler en \u00e9quipe;<\/li><li>Sens de la confidentialit\u00e9.<\/li><\/ul>\n\n\n\n<p>Niveau d&rsquo;\u00e9tudes : LICENCE \/ BAC+3<\/p>\n\n\n\n<p>Sp\u00e9cialisation :&nbsp;[Autres]<\/p>\n\n\n\n<p>Niveau d&rsquo;exp\u00e9rience :&nbsp;Exp\u00e9riment\u00e9 (de 3 \u00e0 5 ans)<\/p>\n\n\n\n<p>Langues :&nbsp;<br>Fran\u00e7ais&nbsp;:&nbsp;Bonne pratique<br>Anglais&nbsp;:&nbsp;Bonne pratique<\/p>\n\n\n\n<p>Crit\u00e8res du poste<\/p>\n\n\n\n<ul><li>Minimum Bac +3 en Gestion;<\/li><li>une exp\u00e9rience en Gestion des projets serait un atout ind\u00e9niable&nbsp;<\/li><li>Connaissance des proc\u00e9dures de l\u2019administration publique et des appels<br>d\u2019offres;<\/li><li>Connaissance g\u00e9n\u00e9rale des techniques de gestion des projets;<\/li><li>Ma\u00eetrise des outils bureautiques classiques (Office 365, etc) et\/ou collaboratifs (Google: Docs, Sheet, Slide);<\/li><li>Bonne utilisation des outils de communication (t\u00e9l\u00e9phone, messagerie, agenda \u00e9lectronique\u2026);<\/li><li>Capacit\u00e9 d\u2019organisation, polyvalence;<\/li><li>Aptitude \u00e0 travailler en \u00e9quipe;<\/li><li>Sens de la confidentialit\u00e9.<\/li><\/ul>\n\n\n\n<p><a href=\"https:\/\/application.careerbuilder1.eu\/apave\/apply\/cb1\/J3M2CW6TMXFFL40MGZB?IPath=TNJob&amp;Job_DID=J3M2CW6TMXFFL40MGZB&amp;SiteID=cbnsv&amp;VID=VX5BD07E50F82D11ECAFDA2BF8D25F83C223113H&amp;sc_cmp1=JS_JobDetails_ApplyNow&amp;TN_DID=TNKD38560K16M285NSH4&amp;language=fr\">Postuler<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gestionnaire de Projets H\/F Lieu Douala,&nbsp;LittoralPubli\u00e9 2 joursCat\u00e9gorie du poste Administration\/Organisation\/Services G\u00e9n\u00e9raux, Transport \/ LogistiqueType de poste CDI &#8211; temps pleinExp\u00e9rience Non pr\u00e9cis\u00e9 Postuler Partager&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[21],"tags":[],"villes":[135],"contrats":[234],"diplomes":[162,212],"louma_meta":{"emploi_title":"Gestionnaire de Projets H\/F","emplois_employeur":2981,"emplois_date_publication":"2022-11-04","emplois_heure_publication":"","emplois_date_cloture":"2022-11-30","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"https:\/\/application.careerbuilder1.eu\/apave\/apply\/cb1\/J3M2CW6TMXFFL40MGZB?IPath=TNJob&Job_DID=J3M2CW6TMXFFL40MGZB&SiteID=cbnsv&VID=VX5BD07E50F82D11ECAFDA2BF8D25F83C223113H&sc_cmp1=JS_JobDetails_ApplyNow&TN_DID=TNKD38560K16M285NSH4&language=fr"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/35688"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=35688"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/35688\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/2982"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=35688"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=35688"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=35688"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=35688"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=35688"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=35688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}