{"id":35377,"date":"2022-10-24T19:53:16","date_gmt":"2022-10-24T17:53:16","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=35377"},"modified":"2022-10-24T19:53:19","modified_gmt":"2022-10-24T17:53:19","slug":"responsable-de-la-maintenance","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/responsable-de-la-maintenance\/","title":{"rendered":"RESPONSABLE DE LA MAINTENANCE"},"content":{"rendered":"\n<pre class=\"wp-block-code\"><code>PUBLICATION DE RECRUTEMENT (INTERNE ET EXTERNE)\nENTITE : AFRICA FOOD MANUFACTURE DIVISON SEMOULERIE\nINTITULE DU POSTE : RESPONSABLE DE LA MAINTENANCE\nDIRECTION\/DEPARTEMENT : MAINTENANCE\nNOMBRE DE POSTE : 01\nLIEU D\u2019AFFECTATION : DOUALA\nCONTRAT : PERMANENT\n MISSIONS DU POSTE :\nLe Responsable maintenance g\u00e8re l'am\u00e9lioration de l'\u00e9quipement de production et son\nadaptation aux \u00e9volutions de l'organisation ou des technologies. Il est responsable d'un budget\npour garantir \u00e0 l'unit\u00e9 de production et plus g\u00e9n\u00e9ralement \u00e0 l'entreprise, le bon fonctionnement\nde ses \u00e9quipements, sa s\u00e9curit\u00e9 et l'am\u00e9lioration de ses performances.\n ACTIVITES\nLe Responsable maintenance sera appel\u00e9 \u00e0 :\nOrganiser, planifier, suivre le travail de maintenance\n\uf0b7 Elaborer le planning de maintenance pr\u00e9ventive et r\u00e9glementaire des diff\u00e9rents \u00e9quipements en\ng\u00e9rant les priorit\u00e9s, la s\u00e9curit\u00e9 et les contraintes de la production, avec l'aide ou non d'un syst\u00e8me\nde GMAO (Gestion de Maintenance Assist\u00e9e par Ordinateur)\n\uf0b7 R\u00e9agir en cas de panne grave et r\u00e9soudre les probl\u00e8mes rapidement\n\uf0b7 R\u00e9soudre les anomalies identifi\u00e9es par la production\/maintenance (tableaux des anomalies)\n\uf0b7 Organiser les Plong\u00e9es sous-marine pluridisciplinaire avant chaque arr\u00eat de production pour\nmaintenance (tour de terrain structur\u00e9)\n\uf0b7 G\u00e9rer les relations avec les constructeurs et les fournisseurs de pi\u00e8ces et d'outils pour la maintenance\n\uf0b7 Contr\u00f4ler les interventions r\u00e9alis\u00e9es, proposer des am\u00e9liorations des performances des machines en\ntermes de co\u00fbts et de taux d'utilisation\n\uf0b7 Piloter les activit\u00e9s de 5s dans son d\u00e9partement\n\uf0b7 Faire le point de l\u2019outillage du d\u00e9partement maintenance et proposer de nouveaux outils pour\nam\u00e9liorer le travail d\u2019entretien des \u00e9quipements\nAPPEL A CANDIDATURE\nAFMSFORSH047A\nD\u2019octobre 2022\nFORMULAIRE Page 2 sur 4\n\uf0b7 Veiller \u00e0 la mise \u00e0 jour des plaques de maintenance aux pieds des machines\n\uf0b7 Animer le rituel journalier du d\u00e9partement maintenance (suivant les 6 axes de la performance)\n\uf0b7 D\u00e9ployer le management visuel sur les \u00e9quipements de son p\u00e9rim\u00e8tre\n\uf0b7 G\u00e9rer le budget maintenance.\nMise en place et suivi de la maintenance des \u00e9quipements techniques :\n\u2022 Plan de maintenance pr\u00e9ventive des \u00e9quipements de production et annexes (chaudi\u00e8res,\nSchiller, compresseurs d\u2019air, traitement des eaux,\u2026)\n\u2022 Plan de maintenance r\u00e8glementaire des \u00e9quipements (soupapes, ballons, sondes, ballons,\npalan, chariots)\n\u2022 Contr\u00f4le de la qualit\u00e9 de la prestation\n\u2022 Veille technologique et r\u00e8glementaire\nSuivi des consommations et optimisation des co\u00fbts:\n\u2022 Economie d\u2019\u00e9nergies eau, air, vapeur, gasoil, froid (Lean, r\u00e9duction des gaspillages)\n\u2022 Optimiser la consommation des pi\u00e8ces de rechange lors de la maintenance pr\u00e9ventive et\ncorrective\nAnimer son \u00e9quipe\n\uf0b7 Organiser un point journalier avec les \u00e9quipes de maintenance (rituel de maintenance)\n\uf0b7 Suivre l\u2019\u00e9volution de r\u00e9solution des anomalies (gestion des points bloquants de correction\ndes anomalies)\n\uf0b7 Veiller au respect du planning de formation interne\/externe de la Direction Technique\nAdjointe\nAnticiper les \u00e9volutions\n\uf0b7 Garant de la gestion documentaire technique des \u00e9quipements sous sa responsabilit\u00e9.\n\uf0b7 Pr\u00e9parer les budgets \u00e0 court, moyen et long terme pour le d\u00e9veloppement, la recherche et\nles investissements\n\uf0b7 N\u00e9gocier et g\u00e9rer des projets d'investissements\n EXIGENCES DU POSTE ET COMPETENCES REQUISES\n PROFIL\n\u2022 Niveau acad\u00e9mique : BAC +5 en Maintenance industriel ou \u00e9quivalent dans le domaine\nindustriel (conception, architecture, construction, fabrication m\u00e9canique...)\n\u2022 Formation et\/ou qualification compl\u00e9mentaires : Gestion des Projets, Dimensionnement\nde structure, utilisation des logiciels de Gestion (SAGE \u2026)\nAPPEL A CANDIDATURE\nAFMSFORSH047A\nD\u2019octobre 2022\nFORMULAIRE Page 3 sur 4\n\u2022 Exp\u00e9rience professionnelle : 05 ans minimum d\u2019exp\u00e9rience dans le domaine de la\nmaintenance de machines agroindustrielles\n\u2022 Age maximum: 40 ans\nCOMPETENCES TECHNIQUES\nLa maintenance et l\u2019innovation sont les cl\u00e9s d\u2019une garantie de bon fonctionnement de nos\n\u00e9quipements de production et d\u2019un d\u00e9veloppement industriel certain. Par cons\u00e9quent, le\nResponsable de Maintenance doit avoir les comp\u00e9tences requises suivantes :\n\uf0b7 Bonne maitrise des \u00e9quipements de production industrielle\n\uf0b7 Gestion de la maintenance pr\u00e9ventive des \u00e9quipements (anticiper sur les pannes)\n\uf0b7 Pilotage et suivi des compteurs horaires des machines (maintenance conditionnelle)\n\uf0b7 Analyser les causes racines de dysfonctionnements majeurs des \u00e9quipements\n\uf0b7 Capacit\u00e9 d\u2019analyse d\u00e9cisionnelle face \u00e0 un probl\u00e8me\n\uf0b7 Maitrise de la gestion des pi\u00e8ces de rechanges (anticiper sur les besoins)\n\uf0b7 Bonnes habilet\u00e9s de communication;\n\uf0b7 S\u2019adapter aux nouvelles technologies;\n\uf0b7 Anticiper les probl\u00e8mes et savoir d\u00e9celer les dysfonctionnements le plus en amont\npossible ;\n\uf0b7 Echanger et synth\u00e9tiser des informations provenant de l\u2019environnement de travail ;\n\uf0b7 Int\u00e9grit\u00e9 et \u00e9thique du travail impeccable ;\n\uf0b7 Autonomie, sens des responsabilit\u00e9s, organisation et minutie ;\n\uf0b7 Capacit\u00e9 \u00e0 travailler sous pression dans un environnement en constante \u00e9volution\n\nAPTITUDES ET ATTITUDES\n\u2022 Avoir un esprit critique;\n\u2022 Capable de travailler en \u00e9quipe;\n\u2022 R\u00e9agir rapidement, avec calme et ma\u00eetrise de soi, en pr\u00e9sence d\u2019un \u00e9v\u00e8nement soudain ;\n\u2022 bonne condition physique (travail debout et accroupi, port de charges),\n\u2022 bonne capacit\u00e9 de m\u00e9morisation des pi\u00e8ces et de leurs emplacements ;\n\u2022 Communiquer ais\u00e9ment;\n\u2022 Etre vif, vigilent et rigoureux;\n\u2022 Faire preuve d\u2019initiatives;\n\u2022 R\u00e9sistance au stress;\n\u2022 Supporter des t\u00e2ches r\u00e9p\u00e9titives;\n\u2022 Faire preuve de mobilit\u00e9;\n\u2022 Pas Allergique;\n\u2022 Travailler dans un environnement propre et bien rang\u00e9 (5S)\nAPPEL A CANDIDATURE\nAFMSFORSH047A\nD\u2019octobre 2022\nFORMULAIRE Page 4 sur 4\n\u2022 Avoir le sens LEAN (\u00e9conomie d\u2019\u00e9nergie, eviler les gaspillages)\n\u2022 Bonne capacit\u00e9 \u00e0 planifier ses activit\u00e9s et les suivre au quotidien.\n SOUMISSION DE CANDIDATURE\n\uf0b7 Curriculum vitae mis \u00e0 jour avec r\u00e9f\u00e9rences ;\n\uf0b7 Lettre de motivation ;\nLes dossiers de candidatures seront re\u00e7us au plus tard le 31 OCTOBRE \u00e0 l\u2019adresse ci-dessous:\nrecrutement@africafoodmanufacture.com\nIl est recommand\u00e9 aux candidats de postuler en mentionnant en objet l\u2019intitul\u00e9 du poste publi\u00e9.\nDELAI DE RECEVABILITE DES CANDIDATURES LUNDI 31 OCTOBRE 2022. <\/code><\/pre>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[21],"tags":[],"villes":[135],"contrats":[234],"diplomes":[162,212],"louma_meta":{"emploi_title":"RESPONSABLE DE LA MAINTENANCE","emplois_employeur":20640,"emplois_date_publication":"2022-10-24","emplois_heure_publication":"","emplois_date_cloture":"2022-10-31","emplois_heure_cloture":"","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"recrutement@africafoodmanufacture.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/35377"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=35377"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/35377\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/20654"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=35377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=35377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=35377"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=35377"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=35377"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=35377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}