{"id":35087,"date":"2022-10-13T15:57:23","date_gmt":"2022-10-13T13:57:23","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=35087"},"modified":"2022-10-13T15:57:25","modified_gmt":"2022-10-13T13:57:25","slug":"responsable-commercial-et-des-commerciaux","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/responsable-commercial-et-des-commerciaux\/","title":{"rendered":"Responsable Commercial et des Commerciaux\u00a0"},"content":{"rendered":"\n<p>Wi \u00c9vent&rsquo;s Production<\/p>\n\n\n\n<p>offre d&#8217;emploi.<\/p>\n\n\n\n<p>Recherche un Responsable Commercial et des Commerciaux..<\/p>\n\n\n\n<p>Qualification:<\/p>\n\n\n\n<p>Homme\/Femme<\/p>\n\n\n\n<p>Qualit\u00e9 de persuasion<\/p>\n\n\n\n<p>minimum bac<\/p>\n\n\n\n<p>n\u00e9cessaires<\/p>\n\n\n\n<p>dettre de motivation adress\u00e9e au DRH avoir un t\u00e9l\u00e9phone portable Android eplan de localisation<\/p>\n\n\n\n<p>691120190<\/p>\n\n\n\n<p>Date limite de d\u00e9p\u00f4t 14 novembre Dossiers \u00e0 d\u00e9pos\u00e9 \u00e0 l&rsquo;agence ndogbong Station mrs<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wi \u00c9vent&rsquo;s Production offre d&#8217;emploi. Recherche un Responsable Commercial et des Commerciaux.. Qualification: Homme\/Femme Qualit\u00e9 de persuasion minimum bac n\u00e9cessaires dettre de motivation adress\u00e9e au&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[1273],"tags":[],"villes":[135],"contrats":[234],"diplomes":[163,212],"louma_meta":{"emploi_title":"Responsable Commercial et des Commerciaux","emplois_employeur":3046,"emplois_date_publication":"2022-10-13","emplois_heure_publication":"","emplois_date_cloture":"2022-11-14","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"","emploi_email":"691120190"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/35087"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=35087"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/35087\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=35087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=35087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=35087"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=35087"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=35087"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=35087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}