{"id":35020,"date":"2022-10-12T03:14:56","date_gmt":"2022-10-12T01:14:56","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=35020"},"modified":"2022-10-12T03:14:58","modified_gmt":"2022-10-12T01:14:58","slug":"01-responsable-juridique-h-fref-rj0122","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/01-responsable-juridique-h-fref-rj0122\/","title":{"rendered":"01 RESPONSABLE JURIDIQUE H\/F(R\u00e9f. RJ0122)"},"content":{"rendered":"\n<pre class=\"wp-block-code\"><code>01 RESPONSABLE JURIDIQUE H\/F(R\u00e9f. RJ0122)\nPoste bas\u00e9 \u00e0 Douala\nOFFRE D\u2019EMPLOI\nBASSAGAL CONSULTING AFRICA recrute pour un de ses clients, du secteur de la grande distribution:\nRattach\u00e9 \u00e0 la Direction Administrative et Financi\u00e8re, vous aurez pour missions principales : \uf0b7 Prot\u00e9ger les int\u00e9r\u00eats de l\u2019entreprise sur le plan administratif, commercial, fiscal, social ; \uf0b7 \u00c9valuer les risques des op\u00e9rations r\u00e9alis\u00e9es et imaginer les montages juridiques les plus avantageuxpourl\u2019entreprise ; \uf0b7 S\u2019assurer que les projets etles d\u00e9cisions prises dansle cadre des contrats(travail, commerciaux) oudecontentieux sont conformes \u00e0 la l\u00e9gislation ; \uf0b7 Veiller \u00e0 l\u2019application de la loi aupr\u00e8s de tous lesservices (op\u00e9rations, d\u00e9veloppements int\u00e9gr\u00e9s et franchises,achats,ressources humaines, etc.) ; \uf0b7 V\u00e9rifierlal\u00e9galit\u00e9desop\u00e9rationsdel\u2019entreprise; \uf0b7 Conseillerl\u2019entreprise dansses prises de d\u00e9cisions; \uf0b7 Op\u00e9rer une veille juridique pour proc\u00e9der aux adaptations n\u00e9cessaires etsaisir de nouvelles opportunit\u00e9s; \uf0b7 D\u00e9fendre lesint\u00e9r\u00eats de l\u2019entreprise en cas d\u2019actions \u00e0 son encontre ; \uf0b7 Exercer un r\u00f4le pr\u00e9ventif aupr\u00e8s de l\u2019entreprise afin de lui \u00e9viter d\u2019encourir des risques juridiques ;\nPROFIL : \uf0b7 Justifier d\u2019une formation de l\u2019enseignementsup\u00e9rieur en droit priv\u00e9 ; \uf0b7 Justifierd\u2019unesolideconnaissanceendroitdesaffairesetendroitsocial; \uf0b7 Avoir une bonne connaissance du monde de l\u2019entreprise, de l\u2019\u00e9conomie et de la finance ; \uf0b7 Rigueur et objectivit\u00e9; \uf0b7 Bon relationnel ; \uf0b7 Bonne pr\u00e9sentation ; \uf0b7 Bonne expression \u00e9crite et verbale. Les candidat(e)s int\u00e9ress\u00e9 (e)s devront envoyer leur CV en pr\u00e9cisant la r\u00e9f\u00e9rence RJ0122 \u00e0 l\u2019adressesuivante:yannick.billigha@bassagal-consulting.com\nLa date limite de recevabilit\u00e9 des candidatures est fix\u00e9e au 14 Octobre 2022\nNB : seuls les candidats shortlist\u00e9s seront contact\u00e9s<\/code><\/pre>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[235],"tags":[],"villes":[135],"contrats":[234],"diplomes":[162,212],"louma_meta":{"emploi_title":"01 RESPONSABLE JURIDIQUE H\/F(R\u00e9f. RJ0122)","emplois_employeur":4772,"emplois_date_publication":"2022-10-12","emplois_heure_publication":"","emplois_date_cloture":"2022-10-31","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":":yannick.billigha@bassagal-consulting.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/35020"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=35020"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/35020\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/4773"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=35020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=35020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=35020"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=35020"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=35020"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=35020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}