{"id":35018,"date":"2022-10-12T03:11:58","date_gmt":"2022-10-12T01:11:58","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=35018"},"modified":"2022-10-12T03:12:00","modified_gmt":"2022-10-12T01:12:00","slug":"agent-commercial-15","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/agent-commercial-15\/","title":{"rendered":"Agent Commercial"},"content":{"rendered":"\n<pre class=\"wp-block-code\"><code>Titre du poste : Agent Commercial,\ndate d'expiration : 2022-11-01,\nNouvelle entreprise : NARES SARL\nPays : cameroun,\nvilles : Yaound\u00e9 et Douala,\ncontact pour postuler : naressarl21@gmail.com\n\n<pre class=\"wp-block-code\"><code>Une entreprise camerounaise recherche pour la commercialisation de ses produits, des agents commerciaux ayant une exp\u00e9rience dans la vente des produits ou services dans les bureaux et Administrations.<br>Envoyez les CV \u00e0 l'adresse naressarl21@gmail.com<\/code><\/pre><\/code><\/pre>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[1273],"tags":[],"villes":[136],"contrats":[234],"diplomes":[162,212],"louma_meta":{"emploi_title":" Agent Commercial","emplois_employeur":33227,"emplois_date_publication":"2022-10-12","emplois_heure_publication":"","emplois_date_cloture":"2022-10-31","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":" naressarl21@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/35018"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=35018"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/35018\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/33228"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=35018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=35018"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=35018"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=35018"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=35018"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=35018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}