{"id":34911,"date":"2022-10-07T05:26:34","date_gmt":"2022-10-07T03:26:34","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=34911"},"modified":"2022-10-07T05:26:36","modified_gmt":"2022-10-07T03:26:36","slug":"commercial-30","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/commercial-30\/","title":{"rendered":"Commercial"},"content":{"rendered":"\n<p>ROYAL DELIVERY YANGO<\/p>\n\n\n\n<p>Poste COMMERCIAL<\/p>\n\n\n\n<p>ROYAL HOLDING SARL est une entreprise de services sp\u00e9cialis\u00e9 dans le transport de personnes et colis op\u00e9rant sous le nom commercial ROYAL DELIVERY. <br><\/p>\n\n\n\n<p>Elle exploite une licence YANGO au CAMEROUN et dans la sous-r\u00e9gion Afrique Cen trale. Elle ambitionne d&rsquo;\u00eatre un leader dans son domaine \u00e0 l&rsquo;horizon 2032. <br><\/p>\n\n\n\n<p>Afin de renforcer son \u00e9quipe, elle recherche un profil pour le poste de COMMERCIAL<\/p>\n\n\n\n<p>Activit\u00e9s principales<\/p>\n\n\n\n<p>\u26ab Etablir un plan de prospection personnel (d\u00e9placements physiques, t\u00e9l\u00e9phone, mai ling\u2026)<\/p>\n\n\n\n<p>D\u00e9terminer les besoins de client pour proposer une offre adapt\u00e9e<\/p>\n\n\n\n<p>D\u00e9velopper un argumentaire de vente efficace et convaincant<\/p>\n\n\n\n<p>Informer et communiquer avec l&rsquo;\u00e9quipe marketing<\/p>\n\n\n\n<p>. Conclure les ventes, g\u00e9rer l&rsquo;aspect admi nistratif<\/p>\n\n\n\n<p>Faire le suivi apr\u00e8s cr\u00e9ation des comptes<\/p>\n\n\n\n<p>Objectif commercial<\/p>\n\n\n\n<p>Recruter et activer 150 chauffeurs\/mois<\/p>\n\n\n\n<p>Savoir faire<\/p>\n\n\n\n<p>Techniques commerciales<\/p>\n\n\n\n<p>M\u00e9thodes de prospection<\/p>\n\n\n\n<p>\u26ab Techniques de communication Argumentation commerciale<\/p>\n\n\n\n<p>\u2022 Droit commercial<\/p>\n\n\n\n<p>Outils bureautique et gestion des applications de derni\u00e8re g\u00e9n\u00e9ration<\/p>\n\n\n\n<p>Connaissances<\/p>\n\n\n\n<p>Variabilit\u00e9 de poste<\/p>\n\n\n\n<p>\u2022 Le commercial peut exercer son activit\u00e9 sur le terrain, en face \u00e0 face ou par t\u00e9l\u00e9 phone. Il peut \u00eatre en contact direct avec l&rsquo;utilisateur ou avoir \u00e0 faire \u00e0 des interm\u00e9 diaires.<\/p>\n\n\n\n<p>Conditions d&rsquo;exercice<\/p>\n\n\n\n<p>En vente et n\u00e9gociation commer ciale<\/p>\n\n\n\n<p>\u26ab connaissance parfaite du produit ou du service<\/p>\n\n\n\n<p>. Connaissance g\u00e9n\u00e9rale du sec teur d&rsquo;activit\u00e9<\/p>\n\n\n\n<p>\u2022 Technique de n\u00e9gociation<\/p>\n\n\n\n<p>Pour postuler,<\/p>\n\n\n\n<p>envoyer CV + lettre de motivation via WhatsApp au 671 71 94 28 avant le 16\/NOV<\/p>\n\n\n\n<p>\u2022Liaisons + Relations<\/p>\n\n\n\n<p>Externes Client (direct\/indirect), Parte naires (techniques\/commerciaux)<\/p>\n\n\n\n<p>Internes support au business (contr\u00f4le de gestion, ressources humaines, juridique, marketing\u2026) service techniques. Lieux de travail<\/p>\n\n\n\n<p>Il peut \u00eatre tr\u00e8s s\u00e9dentaire ou tr\u00e8s mobile<\/p>\n\n\n\n<p>Royal Delivery<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROYAL DELIVERY YANGO Poste COMMERCIAL ROYAL HOLDING SARL est une entreprise de services sp\u00e9cialis\u00e9 dans le transport de personnes et colis op\u00e9rant sous le nom&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[1273],"tags":[],"villes":[135],"contrats":[234],"diplomes":[162],"louma_meta":{"emploi_title":"Commercial ","emplois_employeur":3046,"emplois_date_publication":"2022-10-07","emplois_heure_publication":"","emplois_date_cloture":"2022-10-14","emplois_heure_cloture":"","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"671 71 94 28"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/34911"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=34911"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/34911\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=34911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=34911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=34911"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=34911"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=34911"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=34911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}