{"id":34714,"date":"2022-09-29T16:26:06","date_gmt":"2022-09-29T14:26:06","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=34714"},"modified":"2022-09-29T16:26:08","modified_gmt":"2022-09-29T14:26:08","slug":"un-e-sales-officer","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/un-e-sales-officer\/","title":{"rendered":"UN (E ) SALES OFFICER"},"content":{"rendered":"\n<pre class=\"wp-block-code\"><code> \n\nSUNDA INTERNATIONAL par le biais de sa filiale HOMEPRO CAMEROON recherche pour des besoins de service Un (e ) SALES OFFICER\t   \n\t   \nCARACTERISTIQUES DU POSTE\t   \n\nIntitul\u00e9 du poste&nbsp;:   SALES OFFICER  \nDomaine d\u2019activit\u00e9&nbsp;:    COMMERCE \nLocalisation du poste&nbsp;:   DOUALA \nMission Principale&nbsp;: D\u00e9velopper des canaux de march\u00e9 pour les produits, promouvoir les produits, r\u00e9aliser la vente et l\u2019objectif de l\u2019entreprise, maintenir une bonne communication avec les clients, saisir les besoins des clients.  \t   \nPROFIL DU CANDIDAT\t   \nFormation&nbsp;: Ventes\/Commerce international ou toute fili\u00e8re relative \u00e0 l\u2019action commerciale\/n\u00e9gociation commerciale\nNiveau de formation&nbsp;: BACC + 3\nQualit\u00e9s Personnelles&nbsp;: bonne expression \u00e9crite et orale, m\u00e9thodique, rigoureuse, d\u00e9vou\u00e9e, disciplin\u00e9e et ponctuelle&nbsp;; \u00eatre honn\u00eate, Ambitieux responsable de travail, s\u00e9rieux et stable, ayant le principe de travail&nbsp;; la conscience de garder les secrets et de travailler sous pression. Avoir des capacit\u00e9s d\u2019analyse, de jugement de planning et de communication, Capacit\u00e9 forte de communication et d\u2019ex\u00e9cution\nExp\u00e9rience dans La commercialisation en gros des produits de quincaillerie mais surtout dans les produits du Kitchen House&nbsp;: Jeux des tasses, assiettes, verres, thermos, cuill\u00e8res, fourchettes.\nMaitrise du march\u00e9 des produits du kitchen house et de la concurrence (Bien connaitre les prix pratiqu\u00e9s) \nExp\u00e9rience Professionnelle&nbsp;: 2 ans et plus \nAge&nbsp;: 25 ans \u2013 35 ans\nEnvironnement de bureau et sur terrain\nEtre bilingue est un atout\t   \nMISSIONS \/FINALITE DU POSTE\t   \n\n-Chercher les clients potentiels et connaitre les informations basiques des clients\n-R\u00e9aliser le business \n- Pr\u00e9senter les produits, les nouveaut\u00e9s et les prix \n- Accomplir les commandes \u00e0 l\u2019heure  \n- Visiter les clients r\u00e9guli\u00e8rement, maintenir la relation de client\u00e8le et rapporter les conseils des clients\n-Collecter les infos de marche et des concurrents\n- Solder le compte de clients en temps\n- Mesurer la norme des produits \n- Enqu\u00eater sur la variation des prix sur le march\u00e9 et sur les mouvements des concurrents\n\t   \nDEPOT DU DOSSIER\t   \n\nBien vouloir d\u00e9poser votre CV \u00e0 l\u2019adresse&nbsp;: recruitment.cm@sunda.com au plus tard 14 Octobre 2022 en mentionnant en objet l\u2019intitul\u00e9 du poste.\n \t \n<\/code><\/pre>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[21,1273],"tags":[],"villes":[135],"contrats":[],"diplomes":[212],"louma_meta":{"emploi_title":"UN (E ) SALES OFFICER","emplois_employeur":19006,"emplois_date_publication":"2022-09-29","emplois_heure_publication":"","emplois_date_cloture":"2022-10-14","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"recruitment.cm@sunda.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/34714"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=34714"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/34714\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/19007"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=34714"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=34714"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=34714"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=34714"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=34714"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=34714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}