{"id":34421,"date":"2022-09-22T05:22:09","date_gmt":"2022-09-22T03:22:09","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=34421"},"modified":"2022-09-22T05:22:10","modified_gmt":"2022-09-22T03:22:10","slug":"charge-de-la-communication-778","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/charge-de-la-communication-778\/","title":{"rendered":"CHARGE DE LA COMMUNICATION (778)"},"content":{"rendered":"\n<h1 class=\"wp-block-heading\">Opportunit\u00e9s de carri\u00e8re&nbsp;: CHARGE DE LA COMMUNICATION (778)<\/h1>\n\n\n\n<p>Identifiant de demande de recrutement&nbsp;<strong>778<\/strong>&nbsp;&#8211;&nbsp;Publi\u00e9&nbsp;<strong>19\/09\/2022<\/strong>&nbsp;&#8211;&nbsp;<strong>DIRECTION MARKETING &amp; COMMUNICATION<\/strong>&nbsp;&#8211;&nbsp;<strong>Soci\u00e9t\u00e9 G\u00e9n\u00e9rale Cameroun<\/strong>&nbsp;&#8211;&nbsp;<strong>SERVICE COMMUNICATION<\/strong>&nbsp;&#8211;&nbsp;<strong>AGENCE SIEGE<\/strong><\/p>\n\n\n\n<p><a href=\"void(0)\">\ue099 &nbsp;Aper\u00e7u avant impression du descriptif de poste<\/a><\/p>\n\n\n\n<p>Postuler&nbsp;Enregistrer le poste&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Missions<\/h2>\n\n\n\n<p>Le Charg\u00e9 de communication a pour mission la mise en oeuvre op\u00e9rationnelle du plan de communication interne et externe de l&rsquo;entreprise.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Activit\u00e9s principales<\/h2>\n\n\n\n<p>Le Charg\u00e9 de Communication a pour activit\u00e9s principales :<\/p>\n\n\n\n<p>Ev\u00e9nementiel<\/p>\n\n\n\n<ul><li>Effectue un suivi op\u00e9rationnel rigoureux des projets et des \u00e9v\u00e9nements internes et externes<\/li><li>Etabli avec les diff\u00e9rents partenaires un cahier de charges \u00e0 soumettre et recherche la solution ayant le meilleur rapport qualit\u00e9\/prix\/s\u00e9curit\u00e9&nbsp;<\/li><li>Partie prenante et force de proposition&nbsp; dans la cr\u00e9ation du concept \u00e9v\u00e9nementiel&nbsp;<\/li><\/ul>\n\n\n\n<p>Sponsoring&nbsp;<\/p>\n\n\n\n<ul><li>Contribue \u00e0 la mise en oeuvre des programmes en assurant la pr\u00e9paration, l&rsquo;organisation et la gestion des op\u00e9rations \u00e9v\u00e9nementielles li\u00e9es au sponsoring<\/li><li>Assure la visibilit\u00e9 de la marque sur toutes les prises de parole et s&rsquo;assure de la de la reprise de parole en communication interne et\/ou institutionnelle&nbsp;<\/li><li>Traite les diff\u00e9rentes demande de partenariat et assure le suivi<\/li><\/ul>\n\n\n\n<p>Administration &amp;&nbsp; Reporting&nbsp;<\/p>\n\n\n\n<ul><li>Elabore le budget et a en charge sa mise en oeuvre&nbsp;&nbsp;<\/li><li>R\u00e9alise les reportings sur les projets pour une consolidation globale<\/li><li>assure une activit\u00e9 de veille de son domaine<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Profil<\/h2>\n\n\n\n<p>Minimum Bac +4 en Communication ou discipline \u00e9quivalente<\/p>\n\n\n\n<p>Minimum 3 ans d&rsquo;exp\u00e9rience dans le domaine de la Communication&nbsp;<\/p>\n\n\n\n<p>Une exp\u00e9rience dans le domaine bancaire est souhaitable&nbsp;<\/p>\n\n\n\n<p>Postuler<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Opportunit\u00e9s de carri\u00e8re&nbsp;: CHARGE DE LA COMMUNICATION (778) Identifiant de demande de recrutement&nbsp;778&nbsp;&#8211;&nbsp;Publi\u00e9&nbsp;19\/09\/2022&nbsp;&#8211;&nbsp;DIRECTION MARKETING &amp; COMMUNICATION&nbsp;&#8211;&nbsp;Soci\u00e9t\u00e9 G\u00e9n\u00e9rale Cameroun&nbsp;&#8211;&nbsp;SERVICE COMMUNICATION&nbsp;&#8211;&nbsp;AGENCE SIEGE \ue099 &nbsp;Aper\u00e7u avant impression du&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[21],"tags":[],"villes":[135],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"CHARGE DE LA COMMUNICATION (778)","emplois_employeur":3502,"emplois_date_publication":"2022-09-22","emplois_heure_publication":"","emplois_date_cloture":"2022-10-06","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"https:\/\/career55.sapsf.eu\/sfcareer\/jobreqcareerpvt?jobId=778&company=sgafricanb&st=2579303EACA7AE86F582103584D3A588BBF28E7A"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/34421"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=34421"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/34421\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/23563"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=34421"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=34421"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=34421"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=34421"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=34421"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=34421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}