{"id":33989,"date":"2022-09-12T14:59:35","date_gmt":"2022-09-12T12:59:35","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=33989"},"modified":"2022-09-12T14:59:36","modified_gmt":"2022-09-12T12:59:36","slug":"plusieurs-account-manager","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/plusieurs-account-manager\/","title":{"rendered":"Plusieurs Account Manager"},"content":{"rendered":"\n<p>Une soci\u00e9t\u00e9 financi\u00e8re recherche des #Account #Manager pour lancement de ses activit\u00e9s, jeunes, dynamiques et passionn\u00e9s par la finance et l&rsquo;asset management.<\/p>\n\n\n\n<p>Missions du poste:<\/p>\n\n\n\n<p>\u2705 Recruter et fid\u00e9liser les clients<\/p>\n\n\n\n<p>\u2705 Analyser les besoins des clients et mettre en place une strat\u00e9gie d&rsquo;acquisition<\/p>\n\n\n\n<p>\u2705 Assurer la satisfaction du client \u00e0 l&rsquo;usage du produit ou du service acquis.<\/p>\n\n\n\n<p>Profil:<\/p>\n\n\n\n<p>Bac+3 minimum en Finance, Banque &amp; Finance, Marketing, etc.<br>Connaissance des techniques de ventes<br>Etre bilingue<br>Avoir un tr\u00e8s bon relationnel<br>Etre organis\u00e9 et dote d&rsquo;une facilit\u00e9 d&rsquo;adaptation.<br>Ma\u00eetrise des secteurs d\u2019activit\u00e9 de ses clients et de son entreprise<br>Avoir une exp\u00e9rience en banque serait un atout.<\/p>\n\n\n\n<p>Pour faire partir de l&rsquo;\u00e9quipe, merci de bien vouloir envoyez votre CV par mail \u00e0 l&rsquo;adresse: careers@digicapitalafrica.com au plutard le 14\/09\/22.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une soci\u00e9t\u00e9 financi\u00e8re recherche des #Account #Manager pour lancement de ses activit\u00e9s, jeunes, dynamiques et passionn\u00e9s par la finance et l&rsquo;asset management.<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[21],"tags":[],"villes":[136],"contrats":[234],"diplomes":[212],"louma_meta":{"emploi_title":"Plusieurs Account Manager","emplois_employeur":3046,"emplois_date_publication":"2022-09-12","emplois_heure_publication":"","emplois_date_cloture":"2022-09-14","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"careers@digicapitalafrica.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/33989"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=33989"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/33989\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=33989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=33989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=33989"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=33989"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=33989"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=33989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}