{"id":33834,"date":"2022-09-06T12:15:37","date_gmt":"2022-09-06T10:15:37","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=33834"},"modified":"2022-09-06T12:15:39","modified_gmt":"2022-09-06T10:15:39","slug":"analyste-senior","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/analyste-senior\/","title":{"rendered":"ANALYSTE SENIOR"},"content":{"rendered":"\n<p>OFFRE D&rsquo;EMPLOI<\/p>\n\n\n\n<p>AFG \u00e0 Capital atlantic group<\/p>\n\n\n\n<p>AFG CAPITAL S.A. est une filiale de Atlantic Financial Group, Elle est sp\u00e9cialis\u00e9e dans l&rsquo;origination, la structuration, la distribution des produits financiers sp\u00e9cifiques et le conseil en ing\u00e9nierie financi\u00e8re. AFG CAPITAL S.A. est une soci\u00e9t\u00e9 de bourse (SDB) agr\u00e9\u00e9e par la Commission de Surveillance du March\u00e9 de l&rsquo;Afrique Centrale (COSUMAF), Elle conduit \u00e0 ce titre des op\u00e9rations sur les valeurs mobili\u00e8res en zone CEMAC<\/p>\n\n\n\n<p>ANALYSTE SENIOR<\/p>\n\n\n\n<p>QUALIFICATIONS ET EXPERIENCE<\/p>\n\n\n\n<p>\u2022 Minimum Bac + 4 en Finance, Banque, Economie, Gestion, Administration ou dans des disciplines<\/p>\n\n\n\n<p>connexes<\/p>\n\n\n\n<p>Exp\u00e9rience minimum de 03 ans \u00e0 un poste similaire Une exp\u00e9rience dans le march\u00e9 des capitaux serait un atout<\/p>\n\n\n\n<p>\u2022 Le bilinguisme (fran\u00e7ais-anglais) serait un atout<\/p>\n\n\n\n<p>ACTIVITES PRINCIPALES<\/p>\n\n\n\n<p>L&rsquo;Analyste Senior est principalement charg\u00e9 de:<\/p>\n\n\n\n<p>\u2022 Pr\u00e9parer les pr\u00e9sentations (teasers) et notes<\/p>\n\n\n\n<p>d&rsquo;informations \u00e0 destination des autorit\u00e9s de r\u00e9gulation des march\u00e9s pour l&rsquo;obtention des visas et \u00e0 l&rsquo;intention des banques et investisseurs potentiels pour les lev\u00e9es des fonds<\/p>\n\n\n\n<p>\u2022 Pr\u00e9parer<\/p>\n\n\n\n<p>les<\/p>\n\n\n\n<p>accords de confidentialit\u00e9<\/p>\n\n\n\n<p>et les<\/p>\n\n\n\n<p>lettres\/contrats de mandat \u2022 Concevoir et proposer des mod\u00e8les financiers<\/p>\n\n\n\n<p>R\u00e9diger le cas \u00e9ch\u00e9ant, les dossiers de cr\u00e9dit en collaboration avec les banques commerciales de la zone<\/p>\n\n\n\n<p>Participer au recueil de la documentation\/garanties tout en assurant leur revue juridique<\/p>\n\n\n\n<p>\u26ab Produire et diffuser sur une base hebdomadaire les divers\u26ab rapports d&rsquo;activit\u00e9s, rapport de performances \u00e0 l&rsquo;intention des investisseurs ainsi que les reportings \u00e0 l&rsquo;attention des autorit\u00e9s de r\u00e9gulation<\/p>\n\n\n\n<p>LIEU: Douala<\/p>\n\n\n\n<p>D\u00c9LAI: Vendredi 09 septembre 2022<\/p>\n\n\n\n<p>.<\/p>\n\n\n\n<p>MISSION PRINCIPALE<\/p>\n\n\n\n<p>Assister la ligne commerciale (March\u00e9s des Capitaux, Corporate &amp; Investment Banking) relativement \u00e0 l&rsquo;origination des dossiers de lev\u00e9es de fonds via les march\u00e9s en zone CEMAC ou le syst\u00e8me bancaire<\/p>\n\n\n\n<p>COMP\u00c9TENCES REQUISES<\/p>\n\n\n\n<p>\u26ab Bonne connaissance de l&rsquo;environnement \u00e9conomique et financier de la zone CEMAC<\/p>\n\n\n\n<p>Solides connaissances des techniques et pratiques de<\/p>\n\n\n\n<p>cr\u00e9dit et des normes r\u00e9glementaires en mati\u00e8re de cr\u00e9dit <\/p>\n\n\n\n<p>\u26ab Bonnes connaissances des march\u00e9s financiers<\/p>\n\n\n\n<p>\u2022 Maitrise des techniques d&rsquo;analyse financi\u00e8re<\/p>\n\n\n\n<p>d&rsquo;entreprise et de march\u00e9<\/p>\n\n\n\n<p>\u26ab Maitrise des techniques de r\u00e9daction des teasers et des<\/p>\n\n\n\n<p>notes d&rsquo;informations<\/p>\n\n\n\n<p>\u26ab Bonne expression orale<\/p>\n\n\n\n<p>\u26ab Maitrise de la suite bureautique Microsoft Office et particuli\u00e8rement Power Point et Excel<\/p>\n\n\n\n<p>Int\u00e9grit\u00e9 \/ Autonomie \/ Organisation\/ M\u00e9thode \/ Rigueur\/Discr\u00e9tion<\/p>\n\n\n\n<p>Capacit\u00e9 \u00e0 travailler sous pression\/Orientation r\u00e9sultat<\/p>\n\n\n\n<p>Bonne capacit\u00e9 d&rsquo;analyse et de synth\u00e8se<\/p>\n\n\n\n<p>D\u00c9P\u00d4T DES CANDIDATURES<\/p>\n\n\n\n<p>Envoyez votre curriculum vitae \u00e0<\/p>\n\n\n\n<p>afg-capital.rh@atlantic-group.net en pr\u00e9cisant en objet : \u00ab\u00a0Analyste Senior\u00a0\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>OFFRE D&rsquo;EMPLOI AFG \u00e0 Capital atlantic group AFG CAPITAL S.A. est une filiale de Atlantic Financial Group, Elle est sp\u00e9cialis\u00e9e dans l&rsquo;origination, la structuration, la&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[23],"tags":[4],"villes":[135],"contrats":[234],"diplomes":[162,212],"louma_meta":{"emploi_title":"ANALYSTE SENIOR","emplois_employeur":2974,"emplois_date_publication":"2022-09-06","emplois_heure_publication":"","emplois_date_cloture":"2022-09-09","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"1","emploi_email":"afg-capital.rh@atlantic-group.net"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/33834"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=33834"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/33834\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/2197"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=33834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=33834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=33834"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=33834"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=33834"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=33834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}