{"id":33457,"date":"2022-08-24T09:03:04","date_gmt":"2022-08-24T07:03:04","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=33457"},"modified":"2022-08-24T09:03:05","modified_gmt":"2022-08-24T07:03:05","slug":"teleconseillere","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/teleconseillere\/","title":{"rendered":"T\u00e9l\u00e9conseill\u00e8re"},"content":{"rendered":"\n<pre class=\"wp-block-code\"><code>Titre du poste : T\u00e9l\u00e9conseill\u00e8re,\ndate d'expiration : 2022-08-20,\nentreprise  : Sky investment,\nPays : cameroun,\nvilles : douala,\ncontact pour postuler : skyrecruits52@gmail.com\n\n<span style=\"font-size: 13.5pt;line-height: 107%;font-family: 'Segoe UI', 'sans-serif'\">La t\u00e9l\u00e9conseill\u00e8re travaillera avec un t\u00e9l\u00e9phone et\/ou un ordinateur. elle r\u00e9pondra aux appels entrants pour une entreprise de paris sportifs&nbsp;<\/span><span style=\"font-size: 11.0pt;line-height: 107%;font-family: 'Calibri','sans-serif'\"><a href=\"http:\/\/www.koolbet237.com\/\"><span style=\"font-size: 13.5pt;line-height: 107%;font-family: 'Segoe UI','sans-serif';color: blue\">www.koolbet237.com<\/span><\/a><\/span><span style=\"font-size: 13.5pt;line-height: 107%;font-family: 'Segoe UI', 'sans-serif'\">. Elle orientera les clients dans l'utilisation du site, dans la manipulation des options de paris et bien d'autres. Elle jouera le r\u00f4le de \"lien direct\" avec la client\u00e8le.<\/span><\/code><\/pre>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[335],"tags":[],"villes":[135],"contrats":[234],"diplomes":[162,212],"louma_meta":{"emploi_title":"T\u00e9l\u00e9conseill\u00e8re","emplois_employeur":3046,"emplois_date_publication":"2022-08-24","emplois_heure_publication":"","emplois_date_cloture":"2022-08-31","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"","emploi_email":"skyrecruits52@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/33457"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=33457"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/33457\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=33457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=33457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=33457"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=33457"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=33457"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=33457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}