{"id":33132,"date":"2022-08-16T01:56:06","date_gmt":"2022-08-15T23:56:06","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=33132"},"modified":"2022-08-16T11:07:51","modified_gmt":"2022-08-16T09:07:51","slug":"stage-professionnel-en-comptabilite-fiscalite-2","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/stage-professionnel-en-comptabilite-fiscalite-2\/","title":{"rendered":"STAGE PROFESSIONNEL EN COMPTABILITE-FISCALITE"},"content":{"rendered":"\n<p>STAGE PROFESSIONNEL EN COMPTABILITE-FISCALITE<\/p>\n\n\n\n<p>Vous \u00eates \u00e9tudiant, vous \u00eates jeune dipl\u00f4m\u00e9, vous \u00eates travailleur, le cabinet AUDITING &amp; PATRIMONIAL CONSULTING SARL vous offre la possibilit\u00e9 de mieux vous ins\u00e9rer dans le monde de la comptabilit\u00e9, fiscalit\u00e9 et finance gr\u00e2ce \u00e0 un stage professionnel de perfectionement vous permettant d&rsquo;acqu\u00e9rir des comp\u00e9tences pratiques indispensables. \u00e0 savoir :<\/p>\n\n\n\n<p>I- LA COMPTABILITE DES ENTREPRISES DE SERVICES\/COMMERCIALES\/ INDUSTRIELLES<\/p>\n\n\n\n<ul><li>Mise en place du syst\u00e8me de la documentation et de l&rsquo;organisation comptable<\/li><li>Param\u00e9trage du logiciel sage comptabilit\u00e9 i7<\/li><li>Param\u00e9trage du logiciel sage gestion commerciale i7<\/li><li>Param\u00e9trage du logiciel sage saisie de caisse d\u00e9centralis\u00e9e i7<\/li><li>Impr\u00e9gnation \u00e0 EXCEL<\/li><li>Mise en place des proc\u00e9dures comptabes<\/li><li>Enregistrement des op\u00e9rations comptables<\/li><li>Contr\u00f4le de la coh\u00e9rence de la balance des comptes\/Inventaires<\/li><li>Montage des \u00e9tats finaciers<\/li><li>R\u00e9daction des rapports de gestion et pr\u00e9sentation POWERPOINT<\/li><\/ul>\n\n\n\n<p>II- LA FISCALITE DE CREATION D&rsquo;ENTREPRISE<\/p>\n\n\n\n<ul><li>Proc\u00e9dures de cr\u00e9ation d&rsquo;entreprise<\/li><li>Edition de la carte de contribuable<\/li><li>R\u00e9daction du contrat de bail<\/li><li>Paiement des droits d&rsquo;enregistrement<\/li><li>D\u00e9claration des pr\u00e9comptes sur loyer<br>d\u00e9claration de la taxe fonci\u00e8re<\/li><\/ul>\n\n\n\n<p>III- LA FISCALITE MENSUELLE<\/p>\n\n\n\n<ul><li>Calcul et d\u00e9clarations \/ t\u00e9l\u00e9d\u00e9claration des imp\u00f4ts<\/li><li>Traitement des salaires dans EXCEL<br>t\u00e9l\u00e9d\u00e9caration CNPS<\/li><\/ul>\n\n\n\n<p>IV- LA FISCALITE DE FIN D&rsquo;EXERCICE<\/p>\n\n\n\n<ul><li>Montage de la DSF<br>renouvellement du dossier fiscal<\/li><li>Gestion des contentieux fiscaux<\/li><\/ul>\n\n\n\n<p>DUREE DU STAGE: 06 mois<br>D\u00e9but : septembre 2022<\/p>\n\n\n\n<p>LOCALISATION : Douala-Beedi, \u00e0 proximit\u00e9 de la boulangerie MALANGUE<\/p>\n\n\n\n<p>Postulez par e-mail en envoyant votre CV et une lettre de motivation \u00e0 l&rsquo;adresse suivante: cabinetapcsarl@gmail.com<br>Pr\u00e9ciser en objet : STAGIAIRE APC<\/p>\n\n\n\n<p>TELEPHONE: 694182386 \/ 681368566<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vous \u00eates \u00e9tudiant, vous \u00eates jeune dipl\u00f4m\u00e9, vous \u00eates travailleur, le cabinet AUDITING &amp; PATRIMONIAL CONSULTING SARL vous offre la possibilit\u00e9 de mieux vous ins\u00e9rer dans le monde de la comptabilit\u00e9, fiscalit\u00e9 et finance gr\u00e2ce \u00e0 un stage professionnel de perfectionement vous permettant d&rsquo;acqu\u00e9rir des comp\u00e9tences pratiques indispensables. <\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[402],"tags":[1641,7],"villes":[135],"contrats":[152],"diplomes":[212,159],"louma_meta":{"emploi_title":"STAGE PROFESSIONNEL EN COMPTABILITE-FISCALITE","emplois_employeur":15864,"emplois_date_publication":"2022-08-16","emplois_heure_publication":"","emplois_date_cloture":"2022-08-31","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"cabinetapcsarl@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/33132"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=33132"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/33132\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/15865"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=33132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=33132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=33132"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=33132"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=33132"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=33132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}