{"id":33038,"date":"2022-08-12T05:01:14","date_gmt":"2022-08-12T03:01:14","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=33038"},"modified":"2022-08-12T05:01:17","modified_gmt":"2022-08-12T03:01:17","slug":"un-e-chef-fe-de-projet-sante-nutrition-a-maroua","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/un-e-chef-fe-de-projet-sante-nutrition-a-maroua\/","title":{"rendered":"Un.e Chef.fe de Projet Sant\u00e9 Nutrition \u00e0 Maroua\u00a0"},"content":{"rendered":"\n<p>CAMEROUN HOUNAISE CROIX ROUGE<\/p>\n\n\n\n<p>CAMEROON CROSS RED<\/p>\n\n\n\n<p>Bon pour<\/p>\n\n\n\n<p>croix-rouge fran\u00e7aise<\/p>\n\n\n\n<p>offichage<\/p>\n\n\n\n<p>SG<\/p>\n\n\n\n<p>La Croix-Rouge Camerounaise et la Croix-Rouge fran\u00e7aise recrutent <strong>Un.e Chef.fe de Projet Sant\u00e9 Nutrition \u00e0 Maroua<\/strong><\/p>\n\n\n\n<p>(URGENT)<\/p>\n\n\n\n<p>Informations sur le poste<\/p>\n\n\n\n<p>Intitul\u00e9 du poste<\/p>\n\n\n\n<p>Chef.fe de Projet Sant\u00e9\/Nutrition<\/p>\n\n\n\n<p>Rattachement hi\u00e9rarchique<\/p>\n\n\n\n<p>CHEF DE SOUS-DELEGATION<\/p>\n\n\n\n<p>MAROUA, REGION DE L&rsquo;EXTREME NORD<\/p>\n\n\n\n<p>Localisation du poste Horaires de travail<\/p>\n\n\n\n<p>Selon le planning de service<\/p>\n\n\n\n<p>Dur\u00e9e de la mission<\/p>\n\n\n\n<p>Date d&rsquo;arriv\u00e9e souhait\u00e9e<\/p>\n\n\n\n<p>Contrat \u00e0 dur\u00e9e d\u00e9termin\u00e9e (7 mois) renouvelable<\/p>\n\n\n\n<p>D\u00e8s que possible<\/p>\n\n\n\n<p>Nombre de postes<\/p>\n\n\n\n<p>01<\/p>\n\n\n\n<p>DATE LIMITE DE DEPOT DES CANDIDATURES<\/p>\n\n\n\n<p>21\/08\/2022<\/p>\n\n\n\n<p>Pr\u00e9sentation de l&rsquo;entreprise<\/p>\n\n\n\n<p>La Croix-Rouge fran\u00e7aise (CRf) et la Croix-Rouge Camerounaise (CRC) sont des associations humanitaires, auxiliaires des pouvoirs publics, qui apportent aide et assistance aux personnes vuln\u00e9rables.<\/p>\n\n\n\n<p>Depuis 2010, la Croix-Rouge fran\u00e7aise (CRf) est pr\u00e9sente au Cameroun et intervient dans les domaines de la sant\u00e9, de la nutrition et de la s\u00e9curit\u00e9 alimentaire et moyens d&rsquo;existence (SAME) dans les r\u00e9gions de l&rsquo;Est et de l&rsquo;Extr\u00eame-Nord.<\/p>\n\n\n\n<p>Contexte du recrutement<\/p>\n\n\n\n<p>Ouverture du poste.<\/p>\n\n\n\n<p>Pr\u00e9sentation du poste<\/p>\n\n\n\n<ol><li>Objectif\/R\u00e9sum\u00e9 du poste.<\/li><\/ol>\n\n\n\n<p>Sous la responsabilit\u00e9 et la supervision du Chef de Sous-D\u00e9l\u00e9gation, et en collaboration avec l&rsquo;\u00e9quipe CRC\/CRf de Maroua, le Chef de Projet Sant\u00e9\/Nutrition est charg\u00e9e du suivi et de la coordination des Projets de Sant\u00e9 et de Nutrition de la Sous D\u00e9l\u00e9gation de la CRf\u00e0 Maroua.<\/p>\n\n\n\n<p>II. Localisation du Poste<\/p>\n\n\n\n<p>Ce poste est ouvert aux personnes ayant le profil requis et le candidat retenu devra r\u00e9sider \u00e0 Maroua par ses propres moyens ; il n&rsquo;est donc pas soumis \u00e0 d\u00e9localisation. Le candidat retenu \u00e0 l&rsquo;issue du processus de recrutement ne pourra par cons\u00e9quent pr\u00e9tendre au statut de salari\u00e9 d\u00e9localis\u00e9.<\/p>\n\n\n\n<p>III. Responsabilit\u00e9s<\/p>\n\n\n\n<p>A. Planification, coordination, mise en \u0153uvre et supervision des activit\u00e9s des soins de sant\u00e9 primaire, secondaire ainsi que la pr\u00e9vention et de surveillance \u00e9pid\u00e9miologique<\/p>\n\n\n\n<p>Assure la planification des activit\u00e9s du projet Accompagne les staffs Wash dans la mise en place du Wash in Heath. Participer \u00e0 \u00e0 l&rsquo;\u00e9laboration des PAI et l&rsquo;\u00e9valuation des staffs sous sa responsabilit\u00e9; interm\u00e9diaire et final) du projet Contribue \u00e0 maintenir l&rsquo;image technique de la CRf dans la zone.<\/p>\n\n\n\n<p>Appui le SERA dans la mise \u00e0 jour des outils de collecte et de suivi des activit\u00e9s; &#8211; Supervise la gestion des m\u00e9dicaments, consommable et \u00e9quipements m\u00e9dicaux<\/p>\n\n\n\n<p>B. Appuie \u00e0 la planification et \u00e0 la mise en \u0153uvre des activit\u00e9s Wash<\/p>\n\n\n\n<p>Appuie la planification des activit\u00e9s sant\u00e9 Wash du projet Encadre l&rsquo;\u00e9quipe Wash dans la planification, la mise en \u0153uvre et le suivi des activit\u00e9s Wash<\/p>\n\n\n\n<p>Participe \u00e0 l&rsquo;organisation et \u00e0 la pr\u00e9paration des sessions de formations et autres \u00e9v\u00e9nements li\u00e9s aux activit\u00e9s Wash<\/p>\n\n\n\n<p>C. Bonne gestion manag\u00e9riale de ses \u00e9quipes, accompagnement et renforcement des comp\u00e9tences de l&rsquo;ensemble du personnel sur le projet Valide le planning de supervision des salari\u00e9s sous sa responsabilit\u00e9;<\/p>\n\n\n\n<p>Fait des supervisions formatives des agents de sant\u00e9 en vue de v\u00e9rifier le bon remplissage des outils de suivi et les donn\u00e9es chaque semaine et chaque fin de mois;<\/p>\n\n\n\n<p>Participe au suivi budg\u00e9taire, au suivi du plan d&rsquo;achat Il ou elle a une responsabilit\u00e9 financi\u00e8re en fonction de la grille de validation de la CRf.<\/p>\n\n\n\n<p>D. Conception des outils, collecte, r\u00e9daction et analyse des rapports Collecte et analyse les donn\u00e9es relatives aux activit\u00e9s du projet<\/p>\n\n\n\n<p>Contribue \u00e0 la r\u00e9daction des rapports des activit\u00e9s du projet Contribue \u00e0 la r\u00e9daction des rapports internes (rapport mensuel) et externes (rapport<\/p>\n\n\n\n<p>Participe \u00e0 la conception des documents techniques et supports de communication<\/p>\n\n\n\n<p>E. Appuie de ses \u00e9quipes sur les activit\u00e9s de coordination et de repr\u00e9sentation<\/p>\n\n\n\n<p>Contribue \u00e0 la qualit\u00e9 des relations avec les partenaires; garantit le respect des principes et des valeurs de la CRf en termes de partenariat.<\/p>\n\n\n\n<ul><li>Participe aux r\u00e9unions ou ateliers techniques au niveau r\u00e9gional et s&rsquo;assure de la synergie des actions de la CRC\/CRf avec les diff\u00e9rents partenaires de mise en \u0153uvre.<\/li><\/ul>\n\n\n\n<p>Qualification et exp\u00e9rience<\/p>\n\n\n\n<p>meroon Bed Cross<\/p>\n\n\n\n<p>Dipl\u00f4me \/Niveau d&rsquo;\u00e9tude :<\/p>\n\n\n\n<ul><li>\u00catre titulaire d&rsquo;un Doctorat d&rsquo;\u00e9tat en M\u00e9decine ou d&rsquo;un dipl\u00f4me sup\u00e9rieur;<\/li><\/ul>\n\n\n\n<p>Avoir au moins 5 ans d&rsquo;exp\u00e9rience en gestion de projets humanitaires; &#8211; B\u00e9n\u00e9ficier d&rsquo;une exp\u00e9rience en sant\u00e9 publique et en approche communautaire serait un<\/p>\n\n\n\n<p>atout.<\/p>\n\n\n\n<p>Comp\u00e9tences et exp\u00e9riences indispensables:<\/p>\n\n\n\n<ul><li>Capacit\u00e9 \u00e0 travailler en coop\u00e9ration avec les services d\u00e9concentr\u00e9s et d\u00e9centralis\u00e9s de l&rsquo;Etat Maitrise de la gestion du cycle de projet avec forte implication communautaire;<\/li><\/ul>\n\n\n\n<p>La connaissance des probl\u00e9matiques sanitaires notamment sur le SRMNE (Sant\u00e9 Reproductive, des M\u00e8res, des Nouveau-n\u00e9s et des Enfants) et la nutrition du Cameroun est un atout.<\/p>\n\n\n\n<p>Capacit\u00e9 \u00e0 int\u00e9grer diff\u00e9rents secteurs d&rsquo;intervention au sein d&rsquo;activit\u00e9<\/p>\n\n\n\n<p>Une connaissance du fonctionnement d&rsquo;un district sanitaire<\/p>\n\n\n\n<p>Avoir une excellente connaissance des probl\u00e9matiques en sant\u00e9 publique et en<\/p>\n\n\n\n<p>participation communautaire;<\/p>\n\n\n\n<p>Parler le fulfulde;<\/p>\n\n\n\n<ul><li>Maitrise du contexte de l&rsquo;extr\u00eame nord du Cameroun pr\u00e9cis\u00e9ment le Diamar\u00e9 ; Parfaite ma\u00eetrise de la langue fran\u00e7aise.<\/li><\/ul>\n\n\n\n<p>Connaissances sp\u00e9cifiques:<\/p>\n\n\n\n<ul><li>Une connaissance du Mouvement Croix-Rouge \/ Croissant-Rouge au travers d&rsquo;une<\/li><\/ul>\n\n\n\n<p>exp\u00e9rience pr\u00e9alable est un r\u00e9el avantage;<\/p>\n\n\n\n<p>Une connaissance des probl\u00e9matiques sanitaires notamment sur le SRMNE (Sant\u00e9<\/p>\n\n\n\n<p>Reproductive, des M\u00e8res, des Nouveau-n\u00e9s et des Enfants) et la nutrition du Cameroun<\/p>\n\n\n\n<p>est un atout;<\/p>\n\n\n\n<p>Une Parfaite ma\u00eetrise de la langue fran\u00e7aise;<\/p>\n\n\n\n<p>Une bonne connaissance de l&rsquo;anglais serait un atout.<\/p>\n\n\n\n<p>Comp\u00e9tences et exp\u00e9riences appr\u00e9ci\u00e9es:<\/p>\n\n\n\n<ul><li>Ma\u00eetrise du pack Office (Word, Excel, Power Point), Internet, Epi-Info;<\/li><\/ul>\n\n\n\n<p>Capacit\u00e9 de reporting;<\/p>\n\n\n\n<p>Avoir des capacit\u00e9s d&rsquo;analyse et de synth\u00e8se; Connaissance des r\u00e8gles bailleurs et capacit\u00e9s de reporting:<\/p>\n\n\n\n<p>Connaissance de l&rsquo;approche multisectoriel en sant\u00e9\/nutritionnel Bonnes qualit\u00e9s p\u00e9dagogiques et de n\u00e9gociation<\/p>\n\n\n\n<p>Page 3\/4<\/p>\n\n\n\n<p>Processus de recrutement<\/p>\n\n\n\n<p>Toute personne int\u00e9ress\u00e9e par cette offre est pri\u00e9e de transmettre son dossier par mail \u00e0 l&rsquo;adresse: recruitcrfyaounde@gmail.com. Il s&rsquo;agit de : sous format PDF<\/p>\n\n\n\n<ul><li>Un Curriculum Vitae (CV) actualis\u00e9 avec trois r\u00e9f\u00e9rences professionnelles<\/li><li>Une lettre de motivation (LM)<\/li><\/ul>\n\n\n\n<p>Veuillez mettre en objet du mail de soumission: Chef de Projet Sant\u00e9 Nutrition Maroua<\/p>\n\n\n\n<p>Le recrutement \u00e9tant en urgence, la s\u00e9lection et la validation se feront au fur et \u00e0 mesure<\/p>\n\n\n\n<p>de la r\u00e9ception des candidatures.<\/p>\n\n\n\n<p>La candidature devra \u00eatre adress\u00e9e \u00e0 M. le Chef de D\u00e9l\u00e9gation de la Croix-Rouge fran\u00e7aise.<\/p>\n\n\n\n<p>Au vu du nombre de dossiers que nous recevons, nous sommes dans l&rsquo;incapacit\u00e9 de r\u00e9pondre individuellement \u00e0 chacun. Par cons\u00e9quent, si vous n&rsquo;avez pas de nouvelles de notre part sous 30 jours, veuillez consid\u00e9rer que votre candidature n&rsquo;a pas \u00e9t\u00e9 retenue. Seuls les candidat.e.s pr\u00e9s\u00e9lectionn\u00e9.e.s sur dossier seront convoqu\u00e9.e.s \u00e0 un test \u00e9crit dans les locaux de la CRF. Les dossiers non s\u00e9lectionn\u00e9s ne seront pas retourn\u00e9s aux candidats.<\/p>\n\n\n\n<p>Politique de lutte contre le financement du terrorisme et le blanchiment : en postulant \u00e0 cette offre, vous donnez l&rsquo;autorisation \u00e0 la CRC\/CRf de proc\u00e9der \u00e0 une v\u00e9rification afin de s&rsquo;assurer que vous ne figurez pas sur les listes d&rsquo;exclusion pour la r\u00e9ception de fonds de certains gouvernements, organisations internationales et bailleurs de fonds. Ces v\u00e9rifications sont effectu\u00e9es avant qu&rsquo;on ne vous propose le poste et une fois par an apr\u00e8s votre embauche; ceci afin de pr\u00e9venir les risques et r\u00e9pondre aux obligations en termes de lutte contre le financement du terrorisme et le blanchiment d&rsquo;argent.<\/p>\n\n\n\n<p>Page 4\/4<\/p>\n\n\n\n<p>Page 2\/4<\/p>\n\n\n\n<p>Page 1\/4<\/p>\n\n\n\n<p>Cress<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CAMEROUN HOUNAISE CROIX ROUGE CAMEROON CROSS RED Bon pour croix-rouge fran\u00e7aise offichage SG La Croix-Rouge Camerounaise et la Croix-Rouge fran\u00e7aise recrutent Un.e Chef.fe de Projet&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[21],"tags":[],"villes":[141],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"Un.e Chef.fe de Projet Sant\u00e9 Nutrition \u00e0 Maroua","emplois_employeur":3172,"emplois_date_publication":"2022-08-12","emplois_heure_publication":"","emplois_date_cloture":"2022-08-31","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"recruitcrfyaounde@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/33038"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=33038"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/33038\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/24750"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=33038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=33038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=33038"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=33038"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=33038"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=33038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}