{"id":32799,"date":"2022-08-06T03:47:51","date_gmt":"2022-08-06T01:47:51","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=32799"},"modified":"2022-08-06T03:47:54","modified_gmt":"2022-08-06T01:47:54","slug":"volontariat-en-relations-publiques-et-communication-2","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/volontariat-en-relations-publiques-et-communication-2\/","title":{"rendered":"Volontariat en Relations Publiques et communication"},"content":{"rendered":"\n<pre class=\"wp-block-code\"><code>Titre du poste : Volontariat en Relations Publiques et communication,\ndate d'expiration : 2022-08-28,\nentreprise : Association Go For Leaders,\nPays : cameroun,\nvilles : Yaound\u00e9,\ncontact pour postuler : goforleaders@gmail.com\n\n<span style=\"text-align: center;color: #050505;font-family: 'Segoe UI Historic', 'Segoe UI', Helvetica, Arial, sans-serif;font-size: 15px;background-color: #ffffff\">Volontariat: L'Association Go For Leaders recherche des jeunes \u00e2g\u00e9(e)s entre 21 et 24 ans bas\u00e9(e)s a Yaound\u00e9 au Cameroun et ayant des connaissances en communication et r\u00e9alisation des lives(directes) sur les r\u00e9seaux sociaux. Envoyez-nous inbox une courte vid\u00e9o live (direct) qui vous pr\u00e9sente ou qui nous dira qui vous \u00eates et ce que vous faites dans la vie. Vous pouvez nous joindre aux adresses suivantes:<br><\/span><span style=\"color: #212529;font-family: SFMono-Regular, Menlo, Monaco, Consolas, 'Liberation Mono', 'Courier New', monospace;font-size: 14px;text-align: center;background-color: #f3f3f3\">Facebook:&nbsp;&nbsp;https:\/\/www.facebook.com\/inGOFLE<\/span><br style=\"color: #212529;font-family: SFMono-Regular, Menlo, Monaco, Consolas, 'Liberation Mono', 'Courier New', monospace;font-size: 14px;text-align: center;background-color: #f3f3f3\"><span style=\"color: #212529;font-family: SFMono-Regular, Menlo, Monaco, Consolas, 'Liberation Mono', 'Courier New', monospace;font-size: 14px;text-align: center;background-color: #f3f3f3\">Telegram: +237679191251<\/span><br style=\"color: #212529;font-family: SFMono-Regular, Menlo, Monaco, Consolas, 'Liberation Mono', 'Courier New', monospace;font-size: 14px;text-align: center;background-color: #f3f3f3\"><span style=\"color: #212529;font-family: SFMono-Regular, Menlo, Monaco, Consolas, 'Liberation Mono', 'Courier New', monospace;font-size: 14px;text-align: center;background-color: #f3f3f3\">E-mail: owoundi@hotmail.fr<\/span><\/code><\/pre>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[21],"tags":[],"villes":[136],"contrats":[234],"diplomes":[162,212],"louma_meta":{"emploi_title":"Volontariat en Relations Publiques et communication","emplois_employeur":3046,"emplois_date_publication":"2022-08-06","emplois_heure_publication":"","emplois_date_cloture":"2022-08-31","emplois_heure_cloture":"","emplois_experience_min":"","emplois_experience_max":"","emploi_email":" goforleaders@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/32799"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=32799"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/32799\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=32799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=32799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=32799"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=32799"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=32799"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=32799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}