{"id":32714,"date":"2022-08-03T03:14:38","date_gmt":"2022-08-03T01:14:38","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=32714"},"modified":"2022-08-03T03:14:42","modified_gmt":"2022-08-03T01:14:42","slug":"avis-de-recrutement-massif-aides-pour-services-domestiques-bureautiques-h-f","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/avis-de-recrutement-massif-aides-pour-services-domestiques-bureautiques-h-f\/","title":{"rendered":"AVIS DE RECRUTEMENT MASSIF AIDES POUR SERVICES DOMESTIQUES \/BUREAUTIQUES H\/F\u00a0"},"content":{"rendered":"\n<p>RO RES<\/p>\n\n\n\n<p>DAMES PRO RES<\/p>\n\n\n\n<p>AVIS DE RECRUTEMENT MASSIF AIDES POUR SERVICES DOMESTIQUES \/BUREAUTIQUES H\/F<\/p>\n\n\n\n<p>Exp\u00e9rience: 0-1 an<\/p>\n\n\n\n<p>Age: 18-40 ans<\/p>\n\n\n\n<p>Ville :Douala-Yaound\u00e9 Cameroun Entreprise: DAMES PROPRES Contact pour postuler: damespropres@gmail.com<\/p>\n\n\n\n<p>Date d&rsquo;expiration : 2022-08-30<\/p>\n\n\n\n<p>DAMES PROPRES est une agence de conciergerie (Nettoyage, rangement,<\/p>\n\n\n\n<p>repassage, lessive, vaisselle, Entretien des locaux, Nettoyage apr\u00e8s f\u00eate, Pack rangement\/nettoyage am\u00e9nagement classique, Pack rangement\/nettoyage d\u00e9m\u00e9nagement classique, Placement du personnel, D\u00e9coration, Ev\u00e9nement, etc\u2026.) qualifi\u00e9e dans le placement des personnes d&rsquo;aides \u00e0 domicile.<\/p>\n\n\n\n<p>Parce que le temps libre de nos clients est pr\u00e9cieux et qu&rsquo;ils veulent le consacrer \u00e0 leur famille, loisirs, occupation et travail. Et Parce que la r\u00e9alisation de leurs projets, petits ou grands, m\u00e9rite le support d&rsquo;une assistance personnelle.<\/p>\n\n\n\n<p>Nous aidons nos clients \u00e0 la conciliation entre vie professionnelle et vie personnelle. Notre exp\u00e9rience fait de nous des leaders dans ce secteur d&rsquo;activit\u00e9s.<\/p>\n\n\n\n<p>DAMES PROPRES recherche pour la croissance de sa structure :<\/p>\n\n\n\n<p>-Des femmes de m\u00e9nages;<\/p>\n\n\n\n<ul><li>Agents de nettoyages;<\/li><li>Des Cuisiniers; &#8211; Des Assistantes maternelles :<\/li><li>Des Gardiens: Des Jardiniers;<\/li><\/ul>\n\n\n\n<p>Des Chauffeurs:<\/p>\n\n\n\n<ul><li>Coursiers<\/li><\/ul>\n\n\n\n<p>Des Maintenanciers (plomberie, climatisation, \u00e9lectricit\u00e9)<\/p>\n\n\n\n<ul><li>Etc..<\/li><\/ul>\n\n\n\n<p>Merci d&rsquo;envoyer vos CV a dames.propres@gmail.com avec ou sans exp\u00e9rience en mentionnant en objet le nom du poste sollicite et la ville ou vous vous trouvez. Au plus tard le 30\/08\/2022.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RO RES DAMES PRO RES AVIS DE RECRUTEMENT MASSIF AIDES POUR SERVICES DOMESTIQUES \/BUREAUTIQUES H\/F Exp\u00e9rience: 0-1 an Age: 18-40 ans Ville :Douala-Yaound\u00e9 Cameroun Entreprise:&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[21],"tags":[],"villes":[136],"contrats":[234],"diplomes":[162,212],"louma_meta":{"emploi_title":"AVIS DE RECRUTEMENT MASSIF AIDES POUR SERVICES DOMESTIQUES \/BUREAUTIQUES H\/F","emplois_employeur":3046,"emplois_date_publication":"2022-08-03","emplois_heure_publication":"","emplois_date_cloture":"2022-08-31","emplois_heure_cloture":"","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"Ville :Douala-Yaound\u00e9 Cameroun Entreprise: DAMES PROPRES Contact pour postuler: damespropres@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/32714"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=32714"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/32714\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=32714"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=32714"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=32714"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=32714"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=32714"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=32714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}