{"id":32599,"date":"2022-07-29T20:35:34","date_gmt":"2022-07-29T18:35:34","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=32599"},"modified":"2022-07-29T20:35:37","modified_gmt":"2022-07-29T18:35:37","slug":"assistant-commercial-4","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/assistant-commercial-4\/","title":{"rendered":"Assistant Commercial"},"content":{"rendered":"\n<pre class=\"wp-block-code\"><code>Titre du poste : Assistant Commercial,\ndate d'expiration : 2022-08-31,\nentreprise  : LOLnSHOP CAMEROUN Sarl,\nPays : cameroun,\nvilles : Douala,\ncontact pour postuler : projetrh2807@gmail.com\n\n<div>- Etre titulaire d'un BAC ou plus.<\/div> <div>- Langue : Anglais ou fran\u00e7ais (\u00eatre bilingue est un atout).<\/div> <div>- Genre : F\u00e9minin ou masculin.<\/div> <div>&nbsp;<\/div> <div>MISSIONS : - Prospection de nouveaux clients - Fid\u00e9lisation du portefeuille clients -&nbsp;<\/div> <div>- Pr\u00e9sentation des produits et services - N\u00e9gociations de vente - Suivi des objectifs de vente&nbsp;<\/div> <div>- Effectuer le reporting de son activit\u00e9.<\/div> <div>&nbsp;<\/div> <div>COMP\u00c9TENCES\/NOS ATTENTES<\/div> <div>- Parfaite connaissance des produits ou services commercialis\u00e9s.<\/div> <div>- Excellente \u00e9locution et aptitudes \u00e0 la r\u00e9daction et au dialogue.<\/div> <div>- Avoir une bonne capacit\u00e9 d\u2019\u00e9coute.&nbsp;<\/div> <div>- Capacit\u00e9 \u00e0 cr\u00e9er et fid\u00e9liser un r\u00e9seau de clients&nbsp;<\/div> <div>- Sens de l'analyse et de la m\u00e9thode&nbsp;<\/div> <div>- Connaissances des techniques de vente.<\/div> <div>- Avoir le sens de la rigueur et de l\u2019organisation.<\/div> <div>- Savoir utiliser un ordinateur et naviguer sur internet\/r\u00e9seaux sociaux.<\/div> <div> <div>&nbsp;<\/div> <div>Vous etes int\u00e9ress\u00e9? POSTULEZ via projetrh2807@gmail.com ou par whatsapp 670099903.<\/div> <\/div><\/code><\/pre>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[1273],"tags":[],"villes":[135],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"Assistant Commercial","emplois_employeur":3046,"emplois_date_publication":"2022-07-29","emplois_heure_publication":"","emplois_date_cloture":"2022-08-29","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"","emploi_email":"projetrh2807@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/32599"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=32599"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/32599\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=32599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=32599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=32599"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=32599"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=32599"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=32599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}