{"id":32420,"date":"2022-07-26T18:00:31","date_gmt":"2022-07-26T16:00:31","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=32420"},"modified":"2022-07-26T18:00:35","modified_gmt":"2022-07-26T16:00:35","slug":"assistant-e-financier-e-g4-dc","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/assistant-e-financier-e-g4-dc\/","title":{"rendered":"Assistant\/e Financier\/e &#8211; G4 &#8211; DC"},"content":{"rendered":"\n<h1 class=\"wp-block-heading\">Assistant\/e Financier\/e &#8211; G4 &#8211; DC<\/h1>\n\n\n\n<h2 class=\"wp-block-heading\">&nbsp;Bamenda<\/h2>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.impactpool.org\/organizations\/ilo-international-labour-organization\"><img decoding=\"async\" src=\"https:\/\/images.ctfassets.net\/na3uvakhy5ts\/3JMNT7jPj6LmbIvcCvKcHd\/99d707533594d389cfb86920e011593d\/ILO_logo_on_impactpool.png\" alt=\"\" \/><\/a><\/figure>\n\n\n\n<ul><li><strong>Organization:<\/strong>&nbsp;ILO &#8211; International Labour Organization<\/li><li><strong>Location:<\/strong>&nbsp;Bamenda<\/li><li><strong>Grade:<\/strong>&nbsp;GS-4, General Service &#8211; No need for Higher Education &#8211; Locally recruited position<\/li><li><strong>Occupational Groups:<\/strong><ul><li>Operations and Administrations<\/li><li>Administrative support<\/li><\/ul><\/li><li><strong>Closing Date:<\/strong>&nbsp;2022-08-07<\/li><\/ul>\n\n\n\n<p>SAVE JOB<\/p>\n\n\n\n<p><strong>Grade:<\/strong>&nbsp;G4&nbsp;<\/p>\n\n\n\n<p><strong>No. du poste:&nbsp;<\/strong>DC\/YAOUNDE\/G4\/2022\/09<br><strong>Date de publication:&nbsp;25 Juillet 2022<br>Date de cl\u00f4ture (minuit, heure du Cameroun):&nbsp;07Ao\u00fbt 2022<\/strong><\/p>\n\n\n\n<p><strong>Job ID:&nbsp;<\/strong>8868&nbsp;<br><strong>D\u00e9partment:<\/strong>&nbsp;BR-Afrique&nbsp;<br><strong>Unit\u00e9:&nbsp;<\/strong>ETD\/BP-Yaound\u00e9&nbsp;<br><strong>Lieu d&rsquo;affectation:&nbsp;<\/strong>Bamenda&nbsp;&nbsp;&nbsp;<br><strong>Type de contrat:<\/strong>Dur\u00e9e d\u00e9termin\u00e9e&nbsp;<\/p>\n\n\n\n<p><strong>Dur\u00e9e du contract:<\/strong>&nbsp;12 mois renouvelables&nbsp;<\/p>\n\n\n\n<p>Selon l\u2019Article 4.2 (e) du Statut du personnel, le pourvoi des postes vacants dans les projets de coop\u00e9ration technique n\u2019est pas r\u00e9gi dans le cadre de l\u2019Annexe I du Statut du personnel et se fait par choix direct du Directeur g\u00e9n\u00e9ral.<\/p>\n\n\n\n<p>Dans le but de s&rsquo;assurer que la s\u00e9lection directe pour pourvoir le poste vacant est fond\u00e9e sur le meilleur processus d\u00e9cisionnel possible, le BIT invite les candidats int\u00e9ress\u00e9s \u00e0 soumettre leur candidature en ligne avant la date indiqu\u00e9e ci-dessus.<\/p>\n\n\n\n<p>Peuvent soumettre leur candidature:<\/p>\n\n\n\n<ul><li>Les candidats\/tes internes, en accord avec les paragraphes 31 et 32 de l&rsquo;Annexe I du statut du Personnel.<\/li><li>Les candidats\/tes externes*<\/li><\/ul>\n\n\n\n<p>*Le processus de recrutement des services g\u00e9n\u00e9raux (GS) est soumis aux crit\u00e8res sp\u00e9cifiques de recrutement local.&nbsp;Dans ce cadre, le BIT n&rsquo;offrira un contrat qu&rsquo;aux personnes qui sont en possession d&rsquo;un statut de r\u00e9sident et permis de travail valables en R\u00e9publique du Cameroun<\/p>\n\n\n\n<p>Le BIT attache une grande importance \u00e0 la diversit\u00e9 parmi son personnel et accueille favorablement les candidatures de femmes qualifi\u00e9es. Nous encourageons aussi celles de personnes handicap\u00e9es. Si vous ne pouvez pas remplir notre formulaire de candidature en ligne en raison d&rsquo;un handicap, veuillez envoyer un courriel \u00e0&nbsp;<a href=\"mailto:ilojobs@ilo.org\" target=\"_blank\" rel=\"noreferrer noopener\">ilojobs@ilo.org<\/a>.<\/p>\n\n\n\n<p>Les nominations avec des contrats de coop\u00e9ration technique ne conf\u00e8rent pas le droit \u00e0 une carri\u00e8re au BIT ni \u00e0 un renouvellement automatique de contrat ou une conversion pour un engagement d\u2019une autre nature au sein de l&rsquo;Organisation.&nbsp;Un an de contrat \u00e0 dur\u00e9e d\u00e9termin\u00e9e sera accord\u00e9.&nbsp;Par ailleurs, les prolongations de contrats de coop\u00e9ration technique sont conditionn\u00e9es notamment aux \u00e9l\u00e9ments suivants: la disponibilit\u00e9 des fonds, la continuit\u00e9 du besoin des fonctions exerc\u00e9es et des services et une conduite satisfaisants.<\/p>\n\n\n\n<p>*Conditions d&#8217;emploi pour les candidats externes: Conform\u00e9ment \u00e0 la pratique en vigueur au BIT, le\/la candidat\/e ext\u00e9rieur\/e sera normalement recrut\u00e9\/e au premier \u00e9chelon de ce grade.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Introduction<\/strong><\/h2>\n\n\n\n<p>L&rsquo;Organisation Internationale du Travail (OIT) est une Institution sp\u00e9cialis\u00e9e du Syst\u00e8me des Nations Unies qui a pour mandat de promouvoir la justice sociale, \u00e0 travers notamment l\u2019Agenda du Travail D\u00e9cent. L\u2019Equipe d\u2019appui technique de l\u2019OIT au travail d\u00e9cent de l\u2019Afrique Centrale et Bureau de pays pour le Cameroun, Guin\u00e9e Equatoriale et S\u00e3o Tom\u00e9 et Principe, bas\u00e9 \u00e0 Yaound\u00e9 (ETD\/BP Yaound\u00e9), repr\u00e9sente l\u2019OIT au Cameroun.<\/p>\n\n\n\n<p>Le Bureau International du Travail et le Gouvernement du Cameroun ont sign\u00e9 une convention de coop\u00e9ration le 27 d\u00e9cembre 2021 pour la mise la mise en \u0153uvre dans la r\u00e9gion du Nord-Ouest au Cameroun, du Projet de r\u00e9alisation des activit\u00e9s d\u2019appui \u00e0 l\u2019employabilit\u00e9 des jeunes par l\u2019approche HIMO et de cr\u00e9ation d\u2019emplois pour les jeunes dans le cadre du Programme d\u2019Appui au Secteur des Transports \u2013 Phase III : Construction de la Nationale n\u00b011 \u2013 RING ROAD dans la R\u00e9gion du Nord-Ouest.&nbsp;<\/p>\n\n\n\n<p>L\u2019objectif global du projet est de contribuer \u00e0 la cr\u00e9ation d\u2019emplois d\u00e9cents par le d\u00e9senclavement et la r\u00e9habilitation de certaines infrastructures de la r\u00e9gion du Nord-ouest du Cameroun, plus pr\u00e9cis\u00e9ment, dans les d\u00e9partements du Bui, du Donga Mantung et de la Menchum. &nbsp;En effet, les mauvaises conditions d\u2019emplois de la r\u00e9gion sont sources de d\u00e9couragement au sein des populations locales, notamment celles vivant dans des zones rurales enclav\u00e9es. En raison de l\u2019absence d\u2019opportunit\u00e9s \u00e9conomiques, ces populations sont gagn\u00e9es par le d\u00e9couragement et l\u2019oisivet\u00e9. La cons\u00e9quence de ce mal-\u00eatre g\u00e9n\u00e9ralis\u00e9 conduit non seulement aux conduites addictives et \u00e0 la n\u00e9gation des valeurs civiques et morales, mais aussi favorise l\u2019extr\u00e9misme violent dont l\u2019un des corolaires est l\u2019enr\u00f4lement dans les groupes arm\u00e9s qui existent actuellement dans la r\u00e9gion. Ainsi, il est urgent d\u2019agir et d\u2019offrir des opportunit\u00e9s \u00e9conomiques aux jeunes de la r\u00e9gion afin de les \u00e9loigner de ces groupes arm\u00e9s.&nbsp;<\/p>\n\n\n\n<p>D\u00e8s lors, il s\u2019agira de d\u00e9velopper des possibilit\u00e9s socio-\u00e9conomiques de fixation des jeunes, de r\u00e9duction des risques d\u2019enr\u00f4lement dans les groupes arm\u00e9s ainsi que d\u2019am\u00e9lioration de leurs conditions d\u2019activit\u00e9s et de leurs revenus, en prenant avantage de l\u2019opportunit\u00e9 du projet de construction de l\u2019axe routier Bamenda-Ndop-Kumbo-Nkambe -Wum-Bamenda, commun\u00e9ment appel\u00e9 la \u00ab Ring Road \u00bb. Cet objectif sera r\u00e9alis\u00e9 \u00e0 travers l\u2019utilisation des approches \u00e0 Haute Intensit\u00e9 de Main d\u2019Oeuvre (HIMO) au cours de la r\u00e9alisation de certains travaux connexes pr\u00e9vus dans le cadre des travaux de construction de la \u00ab Ring Road.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>section facultatif (si besoin)<\/strong><\/h2>\n\n\n\n<p>L\u2019assistance technique du BIT portera essentiellement sur : (i) la formation des jeunes de la r\u00e9gion du Nord-Ouest en techniques HIMO et d\u2019entretien routier en vue de leur int\u00e9gration dans les Comit\u00e9s des Routes Communales (CRC) existants ou \u00e0 constituer ; (ii) le diagnostic de la situation des CRC, de leur capacit\u00e9 \u00e0 assumer l\u2019entretien ou la r\u00e9habilitation des routes et le renforcement de leurs capacit\u00e9s aux approches HIMO en vue de leur participation effective aux march\u00e9s publics pour l\u2019entretien routier ; (iii) la sensibilisation des administrations locales \u00e0 la probl\u00e9matique de l\u2019entretien post-r\u00e9habilitation et le renforcement de leurs capacit\u00e9s \u00e0 g\u00e9rer les contrats d\u2019entretien routier ; (iv) les analyses de la chaine de valeur agricole de la r\u00e9gion du Nord-Ouest afin de booster la production agricole de mani\u00e8re \u00e0 cr\u00e9er davantage d\u2019emplois pour les jeunes ; (v) la structuration des jeunes en CRC, en groupements d\u2019int\u00e9r\u00eat \u00e9conomique et\/ou coop\u00e9ratives en vue de leur int\u00e9gration dans les maillons de la chaine de valeur identifi\u00e9e ; (vi) le d\u00e9veloppement et mise en \u0153uvre d\u2019une strat\u00e9gie et plan d\u2019action pour le d\u00e9veloppement de la chaine de valeur identifi\u00e9e (vii) le renforcement des comp\u00e9tences des institutions locales d\u2019encadrement des agriculteurs, CRC, GIE, Coop\u00e9ratives des jeunes afin d\u2019am\u00e9liorer l\u2019offre de services aux acteurs de la chaine de valeur.<\/p>\n\n\n\n<p>Le Projet sera bas\u00e9 dans la ville de Bamenda (Cameroun) et se d\u00e9ploiera dans l\u2019ensemble des d\u00e9partements de la r\u00e9gion du Nord-Ouest. L\u2019\u00e9quipe du projet sera compos\u00e9e d\u2019un\/e Coordonnateur\/trice National\/e de projet (CNP), d\u2019un (e) Assistant\/e financier\/\u00e8re et de deux Chauffeurs\/es. Les pr\u00e9sents TDR sont \u00e9labor\u00e9s en vue du recrutement d\u2019un\/e Assistant\/e aux Finances.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Fonctions et responsabilit\u00e9s essentielles<\/strong><\/h2>\n\n\n\n<p>Sous l\u2019autorit\u00e9 du Directeur de l\u2019ETD\/BP Yaound\u00e9 et la coordination du\/de la CNP, l\u2019AF sera en charge des op\u00e9rations administratives et financi\u00e8res du projet, y compris le suivi des activit\u00e9s pr\u00e9vues dans le cadre du projet intitul\u00e9 \u00ab Projet de r\u00e9alisation des activit\u00e9s d\u2019appui \u00e0 l\u2019employabilit\u00e9 des jeunes par l\u2019approche HIMO et de cr\u00e9ation d\u2019emplois pour les jeunes dans le cadre du Programme d\u2019Appui au Secteur des Transports \u2013 Phase III : Construction de la Nationale n\u00b011 \u2013 RING ROAD dans la R\u00e9gion du Nord-Ouest \u00bb, CMR\/20\/02\/BAD.&nbsp;<br>&nbsp;&nbsp; &nbsp;<br>A cet effet, l\u2019Assistant\/e financier\/\u00e8re sera charg\u00e9(e) de :<\/p>\n\n\n\n<p>\u2022&nbsp;&nbsp; &nbsp;Assister le CNP dans l\u2019organisation de tous \u00e9v\u00e8nements dans le cadre du projet (s\u00e9minaires, r\u00e9unions d&rsquo;information, conf\u00e9rences, voyages d&rsquo;\u00e9tudes, expositions, actions m\u00e9diatiques\u2026) ;<\/p>\n\n\n\n<p>\u2022&nbsp;&nbsp; &nbsp;Pr\u00e9parer les budgets des activit\u00e9s du projet, assurer la mise en \u0153uvre comptable et \u00e9tablir les rapports de gestion en fin d&rsquo;activit\u00e9 ;<\/p>\n\n\n\n<p>\u2022&nbsp;&nbsp; &nbsp;Introduire des donn\u00e9es et autres mat\u00e9riels relatifs au Budget dans un syst\u00e8me informatique approuv\u00e9s par le CNP ;&nbsp;<\/p>\n\n\n\n<p>\u2022&nbsp;&nbsp; &nbsp;R\u00e9viser la comptabilit\u00e9 afin de d\u00e9tecter les transactions inscrites dans des postes erron\u00e9s et prendre les mesures de redressement n\u00e9cessaires ;&nbsp;<\/p>\n\n\n\n<p>\u2022&nbsp;&nbsp; &nbsp;Pr\u00e9parer et r\u00e9viser les tableaux (comme les tableaux relatifs au budget) qui contiennent les informations financi\u00e8res sur la base d\u2019informations fournies par le CNP ;&nbsp;<\/p>\n\n\n\n<p>\u2022&nbsp;&nbsp; &nbsp;Extraire des donn\u00e9es en ligne \u00e0 partir de sources diverses ;&nbsp;<\/p>\n\n\n\n<p>\u2022&nbsp;&nbsp; &nbsp;Suivre les transactions en cours ;&nbsp;<\/p>\n\n\n\n<p>\u2022&nbsp;&nbsp; &nbsp;Tenir \u00e0 jour les syst\u00e8mes de classement des dossiers du projet ;<\/p>\n\n\n\n<p>\u2022&nbsp;&nbsp; &nbsp;Recevoir, trier, enregistrer et acheminer les correspondances du projet, y joindre les documents d&rsquo;information n\u00e9cessaires et en assurer le suivi ;<\/p>\n\n\n\n<p>\u2022&nbsp;&nbsp; &nbsp;Classer, traiter les demandes de paiements&nbsp;<\/p>\n\n\n\n<p>\u2022&nbsp;&nbsp; &nbsp;Pr\u00e9parer les factures en fonction des informations re\u00e7ues et s&rsquo;assurer que les documents justificatifs sont complets et conformes ;<\/p>\n\n\n\n<p>\u2022&nbsp;&nbsp; &nbsp;Assurer les approvisionnements et la gestion des fournitures de bureau ; Tenir un inventaire \u00e0 jour des biens acquis dans le cadre du projet ;<\/p>\n\n\n\n<p>\u2022&nbsp;&nbsp; &nbsp;Mettre en place un syst\u00e8me de classement des conventions et contrats pass\u00e9s par le projet ;<\/p>\n\n\n\n<p>\u2022&nbsp;&nbsp; &nbsp;Effectuer toute autre t\u00e2che \u00e0 lui confi\u00e9e par le\/la CNP dans le cadre du Projet.<br>&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Qualifications requises<\/strong><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Formation<\/strong><\/h2>\n\n\n\n<p>Le ou la candidat(e) doit avoir achev\u00e9 ses \u00e9tudes secondaires suivies d\u2019une formation professionnelle en comptabilit\u00e9.&nbsp;<br>&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Exp\u00e9rience<\/strong><\/h2>\n\n\n\n<p>Au moins deux ans d&rsquo;exp\u00e9rience dans les domaines de la gestion financi\u00e8re et administrative ; avoir de bonnes r\u00e9f\u00e9rences en mati\u00e8re d\u2019organisation des ateliers, de communication et des relations publiques.<br>&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Langues<\/strong><\/h2>\n\n\n\n<p>Parfaite ma\u00eetrise de l\u2019anglais (\u00e9crit et parl\u00e9) avec une connaissance pratique du fran\u00e7ais.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Comp\u00e9tences<\/strong><\/h2>\n\n\n\n<p><br>&#8211;&nbsp;&nbsp; &nbsp;Aptitude \u00e0 travailler avec des traitements de textes et des logiciels de feuilles de calculs, notamment l\u2019environnement bureautique Windows (Word, Excel, Access, Power point\u2026).&nbsp;<br>&#8211;&nbsp;&nbsp; &nbsp;Aptitude \u00e0 effectuer des recherches sur Internet.&nbsp;<br>&#8211;&nbsp;&nbsp; &nbsp;Aptitude \u00e0 travailler avec des donn\u00e9es et des documents confidentiels ;<br>&#8211;&nbsp;&nbsp; &nbsp;Facult\u00e9s d\u2019organisation de son propre travail.&nbsp;<br>&#8211;&nbsp;&nbsp; &nbsp;Aptitude \u00e0 s&rsquo;int\u00e9grer au sein d&rsquo;une \u00e9quipe et \u00e0 travailler sous pression. &nbsp;<br>&#8211;&nbsp;&nbsp; &nbsp;Sens des responsabilit\u00e9s et disponibilit\u00e9 ;&nbsp;<br>&#8211;&nbsp;&nbsp; &nbsp;Aisance dans les contacts avec les partenaires et aptitude \u00e0 r\u00e9pondre \u00e0 leurs sollicitations ;<br>&#8211;&nbsp;&nbsp; &nbsp;Aptitude \u00e0 travailler dans un environnement multiculturel et \u00e0 adopter un comportement non discriminatoire et sensible aux consid\u00e9rations de genre.<\/p>\n\n\n\n<p><strong>Processus de recrutement<\/strong><\/p>\n\n\n\n<p>Veuillez noter que tous les candidats doivent remplir un formulaire de demande en ligne. Pour se faire, veuillez vous rendre sur&nbsp;<a href=\"https:\/\/jobs.ilo.org\/?locale=fr_FR\" target=\"_blank\" rel=\"noreferrer noopener\">le site e-Recruitment du BIT<\/a>&nbsp;\u00e0 l&rsquo;adresse suivante :&nbsp;<a href=\"https:\/\/jobs.ilo.org\/?locale=fr_FR\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/jobs.ilo.org\/<\/a>. Le syst\u00e8me fournit les instructions n\u00e9cessaires afin de faciliter la proc\u00e9dure de demande en ligne.<\/p>\n\n\n\n<p><strong>Alerte \u00e0 la fraude<\/strong><\/p>\n\n\n\n<p>Le BIT ne facture aucun frais \u00e0 aucun moment du processus de recrutement, que ce soit au moment de postuler, pour l&rsquo;entretien, la proc\u00e9dure de recrutement proprement dite ou la formation. Les messages \u00e9manant d&rsquo;addresses email diff\u00e9rentes de celles du BIT &#8211;&nbsp;ilo@.org&nbsp;&#8211; ne doivent en aucun cas \u00eatre consid\u00e9r\u00e9es. En outre, le BIT n&rsquo;a pas besoin et ne demande pas de conna\u00eetre les informations relatives au compte bancaire du postulant.<\/p>\n\n\n\n<p><em>We do our best to provide you the most accurate info, but closing dates may be wrong on our site. Please check on the recruiting organization&rsquo;s page for the exact info. Candidates are responsible for complying with deadlines and are encouraged to submit applications well ahead.<\/em><\/p>\n\n\n\n<p>Before applying, please make sure that you have read the requirements for the position and that you qualify.<br><strong>Applications from non-qualifying applicants will most likely be discarded by the recruiting manager.<\/strong><\/p>\n\n\n\n<p>APPLY<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Assistant\/e Financier\/e &#8211; G4 &#8211; DC &nbsp;Bamenda Organization:&nbsp;ILO &#8211; International Labour Organization Location:&nbsp;Bamenda Grade:&nbsp;GS-4, General Service &#8211; No need for Higher Education &#8211; Locally recruited&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[23],"tags":[],"villes":[142],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"Assistant\/e Financier\/e - G4 - DC","emplois_employeur":6083,"emplois_date_publication":"2022-07-26","emplois_heure_publication":"","emplois_date_cloture":"2022-08-19","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"","emploi_email":"https:\/\/jobs.ilo.org\/job\/Bamenda-Assistante-Financiere-G4-DC\/832338901\/"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/32420"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=32420"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/32420\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/6084"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=32420"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=32420"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=32420"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=32420"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=32420"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=32420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}