{"id":32370,"date":"2022-07-26T04:27:18","date_gmt":"2022-07-26T02:27:18","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=32370"},"modified":"2022-07-26T04:27:22","modified_gmt":"2022-07-26T02:27:22","slug":"ingenieur-detude","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/ingenieur-detude\/","title":{"rendered":"INGENIEUR D\u2019ETUDE"},"content":{"rendered":"\n<h1 class=\"wp-block-heading\">INGENIEUR D\u2019ETUDE<\/h1>\n\n\n\n<p>la soci\u00e9t\u00e9 TECTRA Cameroun est \u00e0 la recherche d&rsquo;un ing\u00e9nieur d&rsquo;\u00e9tude pour l&rsquo;un de ses clients dans les villes de Yaound\u00e9 et Douala<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Poste propos\u00e9 :&nbsp;INGENIEUR D\u2019ETUDE<\/h5>\n\n\n\n<p>Date d&rsquo;annonce&nbsp;:&nbsp;19-07-2022<\/p>\n\n\n\n<p>Ville&nbsp;:&nbsp;cameroun<\/p>\n\n\n\n<p>Secteur d&rsquo;activit\u00e9&nbsp;:&nbsp;Ing\u00e9nierie, \u00e9tudes d\u00e9veloppement<\/p>\n\n\n\n<p>Exp\u00e9rience requise&nbsp;:&nbsp;3 \u00e0 5 ans<\/p>\n\n\n\n<p>Niveau d\u2019\u00e9tude demand\u00e9&nbsp;:&nbsp;Bac+5 et plus<\/p>\n\n\n\n<p>Fonction&nbsp;:&nbsp;ing\u00e9nieur<\/p>\n\n\n\n<p>Type de contrat propos\u00e9&nbsp;:&nbsp;CDI<\/p>\n\n\n\n<p>Description&nbsp;:&nbsp;la soci\u00e9t\u00e9 TECTRA Cameroun est \u00e0 la recherche d&rsquo;un ing\u00e9nieur d&rsquo;\u00e9tude pour l&rsquo;un de ses clients dans les villes de Yaound\u00e9 et Douala<\/p>\n\n\n\n<p>D\u00e9tail de l&rsquo;annonce<\/p>\n\n\n\n<p>L\u2019humain est au c\u0153ur de notre m\u00e9tier&nbsp;!<\/p>\n\n\n\n<p>Tectra Cameroun est une soci\u00e9t\u00e9 sp\u00e9cialis\u00e9e dans la mise \u00e0 disposition du personnel temporaire et permanent, ainsi que dans le conseil en Ressources Humaines. Pr\u00e9sent en Afrique, Tectra g\u00e8re plus de 1000 clients actifs multisectoriels et a une force de r\u00e9seaux pr\u00e9sente dans plusieurs pays africains. Tectra Cameroun reste votre compagnon pour un emploi s\u00fbr et fiable.<\/p>\n\n\n\n<p>Pour l\u2019un de ses clients, Tectra Cameroun recherche&nbsp;<strong>un ing\u00e9nieur d\u2019\u00e9tude&nbsp;<\/strong>pour les villes de Yaound\u00e9 et Douala<\/p>\n\n\n\n<p>Comp\u00e9tences&nbsp;:<\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Solides connaissances techniques du domaine dont il rel\u00e8ve.<\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Tr\u00e8s bonnes connaissances de la langue anglaise.<\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;M\u00e9thode, rigueur et sens de l\u2019organisation.<\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Sens de la cr\u00e9ativit\u00e9 et de la communication.<\/p>\n\n\n\n<p>Missions&nbsp;:<\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;\u00c9tudier et valider tous les aspects de faisabilit\u00e9 du projet avec les responsables des structures \u00e9ventuellement int\u00e9ress\u00e9s : fabrication, commercialisation, etc<\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Concevoir et cr\u00e9er des prototypes du produit, en \u00e9tudier toutes les d\u00e9faillances \u00e9ventuelles et apporter les rectifications n\u00e9cessaires.<\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Collaborer si besoin avec des ing\u00e9nieurs d\u2019\u00e9tudes relevant d\u2019autres branches.<\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Assurer la coordination des travaux des \u00e9quipes et veiller \u00e0 ce qu\u2019ils se d\u00e9roulent suivant les crit\u00e8res exig\u00e9s : co\u00fbt, d\u00e9lai, rentabilit\u00e9, respect des normes et r\u00e9glementations, etc.<\/p>\n\n\n\n<p>Profil recherch\u00e9&nbsp;:<\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Ma\u00eetrise des logiciels de mod\u00e9lisation,<\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Fortes connaissances techniques dans le domaine d&rsquo;\u00e9tude,<\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Rigueur absolue dans les calculs et<\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Capacit\u00e9 \u00e0 travailler en \u00e9quipe.<\/p>\n\n\n\n<p>Dossier \u00e0 fournir&nbsp;: CV, CNI, BAC+5 &nbsp;\u00e9cole d&rsquo;ing\u00e9nieurs<\/p>\n\n\n\n<p>Candidature \u00e0 adresser au plus tard le 19\/08\/2022 \u00c0 l\u2019adresse suivante&nbsp;:<strong>&nbsp;ingetu19072022@tectra.cvparser.ma<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>INGENIEUR D\u2019ETUDE la soci\u00e9t\u00e9 TECTRA Cameroun est \u00e0 la recherche d&rsquo;un ing\u00e9nieur d&rsquo;\u00e9tude pour l&rsquo;un de ses clients dans les villes de Yaound\u00e9 et Douala&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[976],"tags":[],"villes":[135],"contrats":[234],"diplomes":[162,212],"louma_meta":{"emploi_title":"INGENIEUR D\u2019ETUDE","emplois_employeur":32336,"emplois_date_publication":"2022-07-26","emplois_heure_publication":"","emplois_date_cloture":"2022-08-19","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"ingetu19072022@tectra.cvparser.ma"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/32370"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=32370"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/32370\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/32337"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=32370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=32370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=32370"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=32370"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=32370"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=32370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}