{"id":32304,"date":"2022-07-24T22:20:03","date_gmt":"2022-07-24T20:20:03","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=32304"},"modified":"2022-07-24T22:20:07","modified_gmt":"2022-07-24T20:20:07","slug":"developpeur-full-stack-java-angular","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/developpeur-full-stack-java-angular\/","title":{"rendered":"D\u00e9veloppeur Full Stack Java \/ Angular"},"content":{"rendered":"\n<pre class=\"wp-block-code\"><code>Titre du poste : D\u00e9veloppeur Full Stack Java \/ Angular,\ndate d'expiration : 2022-08-31,\nentreprise  : softconfig,\nNouvelle entreprise : softconfig, \nPays : cameroun,\nvilles : douala,\ncontact pour postuler : softconfig.digital@gmail.com\n\n<div>Vous avez au minimum 2 ann\u00e9es d\u2019exp\u00e9riences dans le d\u00e9veloppement, vous intervenez sur des projets de d\u00e9veloppement, dans des environnements nouvelles technologies sur des sujets vari\u00e9s et innovants.<\/div> <div>&nbsp;<\/div> <div>Vos missions :<\/div> <div>&nbsp;<\/div> <div style=\"padding-left: 40px\">R\u00e9alisation des d\u00e9veloppements<\/div> <div style=\"padding-left: 40px\">Maintenance corrective et evolutive<\/div> <div style=\"padding-left: 40px\">D\u00e9finition des charges et d\u00e9lais<\/div> <div style=\"padding-left: 40px\">realisation des tests unitaires et d\u2019int\u00e9gration<\/div> <div style=\"padding-left: 40px\">Documentation des diff\u00e9rentes \u00e9tapes du projet<\/div> <div style=\"padding-left: 40px\">Pr\u00e9paration de la mise en production des applications r\u00e9alis\u00e9es<\/div> <div>Maitrise d\u2019une, ou plusieurs, des technologies suivantes :<\/div> <div>&nbsp;<\/div> <div style=\"padding-left: 40px\">JAVA 8+<\/div> <div style=\"padding-left: 40px\">Spring,<\/div> <div style=\"padding-left: 40px\">SpringBoot<\/div> <div style=\"padding-left: 40px\">Microservices<\/div> <div style=\"padding-left: 40px\">Hibernate<\/div> <div style=\"padding-left: 40px\">SQL, noSQL<\/div> <div style=\"padding-left: 40px\">Angular, VueJs<\/div> <div style=\"padding-left: 40px\">Flutter<\/div> <div style=\"padding-left: 40px\">Maven<\/div> <div style=\"padding-left: 40px\">Git<\/div> <div style=\"padding-left: 40px\">REST<\/div> <div style=\"padding-left: 40px\">SOAP<\/div> <div style=\"padding-left: 40px\">MongoDB<\/div> <div style=\"padding-left: 40px\">Docker<\/div> <div style=\"padding-left: 40px\">k8s<\/div> <div style=\"padding-left: 40px\">Agile<\/div> <div style=\"padding-left: 40px\">Script Shell<\/div> <div>&nbsp;<\/div> <div>Envoyer votre CV par mail \u00e0 l'adresse suivante: softconfig.digital@gmail.com<\/div><\/code><\/pre>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[22],"tags":[],"villes":[135],"contrats":[234],"diplomes":[162,212],"louma_meta":{"emploi_title":"D\u00e9veloppeur Full Stack Java \/ Angular","emplois_employeur":3046,"emplois_date_publication":"2022-07-24","emplois_heure_publication":"","emplois_date_cloture":"2022-07-31","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"softconfig.digital@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/32304"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=32304"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/32304\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=32304"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=32304"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=32304"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=32304"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=32304"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=32304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}