{"id":32111,"date":"2022-07-12T17:13:16","date_gmt":"2022-07-12T15:13:16","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=32111"},"modified":"2022-07-12T17:13:21","modified_gmt":"2022-07-12T15:13:21","slug":"un-01-senior-brand-manager-h-f-ref-rcm1922-cdi-base-a-douala","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/un-01-senior-brand-manager-h-f-ref-rcm1922-cdi-base-a-douala\/","title":{"rendered":"UN (01) SENIOR BRAND MANAGER H\/F (R\u00e9f. RCM1922) CDI bas\u00e9 \u00e0 Douala"},"content":{"rendered":"\n<p>BASSAGAL CONSULTING AFRICA recrute, pour un de ses clients produisant et commercialisant des produits de grande consommation :<br>UN (01) SENIOR BRAND MANAGER H\/F (R\u00e9f. RCM1922) CDI bas\u00e9 \u00e0 Douala<br>Rattach\u00e9(e) au Directeur Marketing, vous aurez pour activit\u00e9s principales :<\/p>\n\n\n\n<p><br>\u2022 Commanditer et suivre des \u00e9tudes de march\u00e9 qualitatives et quantitatives pour d\u00e9terminer les meilleures opportunit\u00e9s de d\u00e9veloppement ;<br>\u2022 Assurer une veille concurrentielle et l&rsquo;analyser, afin d\u2019anticiper les tendances du march\u00e9 ;<br>\u2022 Mesurer les degr\u00e9s d\u2019implication et de satisfaction des consommateurs vis-\u00e0-vis de marques ;<br>\u2022 D\u00e9finir un plan et une strat\u00e9gie de d\u00e9veloppement de la marque pour les ann\u00e9es \u00e0 venir et en garantir<br>la coh\u00e9rence ;<br>\u2022 Rassembler les informations li\u00e9es aux marques pour sugg\u00e9rer et aider \u00e0 d\u00e9finir des am\u00e9liorations<br>possibles ;<br>\u2022 Assurer l\u2019interface et la coordination des diff\u00e9rents services impliqu\u00e9s dans le d\u00e9veloppement des<br>marques sous sa responsabilit\u00e9 ;<br>\u2022 Garder allumer la flamme interne et la passion pour ses marques ;<br>\u2022 Superviser la r\u00e9alisation des op\u00e9rations promotionnelles ;<br>\u2022 Contr\u00f4ler les outils de gestion et d\u2019am\u00e9lioration de la performance d\u2019une ou de plusieurs marques.<br>Profil :<br>\u2022 De formation sup\u00e9rieure niveau Bac +3 en Marketing et Vente ou une formation scientifique compl\u00e9ter par une \u00e9cole de communication ;<br>\u2022 Vous justifiez d\u2019une exp\u00e9rience de 03 ans \u00e0 un poste similaire ;<br>\u2022 La ma\u00eetrise du march\u00e9 brassicole et de ses \u00e9volutions, ou au moins compr\u00e9hension des dynamiques<br>des march\u00e9s FMCG est un atout ;<br>\u2022 Ma\u00eetrise de l\u2019anglais en plus du fran\u00e7ais ;<br>\u2022 Capacit\u00e9 d\u2019organisation et de planification ;<br>\u2022 Capacit\u00e9s d\u2019analyse et de synth\u00e8se ;<br>\u2022 Orientation client, vous avez le sens de l\u2019\u00e9coute, le go\u00fbt du contact, sens de la responsabilit\u00e9 et de<br>l\u2019initiative ;<br>\u2022 Travaille en \u00e9quipe et sous pression ;<br>\u2022 Sens de la confidentialit\u00e9.<\/p>\n\n\n\n<p><br>Les candidats int\u00e9ress\u00e9s devraient envoyer leur CV en pr\u00e9cisant en objet la r\u00e9f\u00e9rence RCM1922 \u00e0 : brigitte.ngui@bassagal-consulting.com OU joseph.bassagal@bassagal-consulting.com<br>La date limite de recevabilit\u00e9 des candidatures est fix\u00e9e au 22 juillet 2022. Seuls les candidats shortlist\u00e9s seront contact\u00e9s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BASSAGAL CONSULTING AFRICA recrute, pour un de ses clients produisant et commercialisant des produits de grande consommation :UN (01) SENIOR BRAND MANAGER H\/F (R\u00e9f. RCM1922)&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[1766],"tags":[],"villes":[135],"contrats":[234],"diplomes":[212],"louma_meta":{"emploi_title":"UN (01) SENIOR BRAND MANAGER H\/F (R\u00e9f. RCM1922) CDI bas\u00e9 \u00e0 Douala","emplois_employeur":4772,"emplois_date_publication":"2022-07-12","emplois_heure_publication":"","emplois_date_cloture":"2022-07-31","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"brigitte.ngui@bassagal-consulting.com "},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/32111"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=32111"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/32111\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/4773"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=32111"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=32111"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=32111"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=32111"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=32111"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=32111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}