{"id":32061,"date":"2022-07-11T03:00:37","date_gmt":"2022-07-11T01:00:37","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=32061"},"modified":"2022-07-11T03:00:40","modified_gmt":"2022-07-11T01:00:40","slug":"network-administrator-h-f","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/network-administrator-h-f\/","title":{"rendered":"Network Administrator H\/F"},"content":{"rendered":"\n<p>Network Administrator H\/FLieu<\/p>\n\n\n\n<p>Douala,&nbsp;LittoralPubli\u00e9<\/p>\n\n\n\n<p>6 joursCat\u00e9gorie du poste<\/p>\n\n\n\n<p>Informatique \/ T\u00e9l\u00e9communicationsType de poste<\/p>\n\n\n\n<p>CDI &#8211; temps pleinExp\u00e9rience<\/p>\n\n\n\n<p>Non pr\u00e9cis\u00e9<a href=\"https:\/\/application.careerbuilder1.eu\/apave\/apply\/cb1\/J3S0T75WSZDB3LVYPPS?IPath=TNJob&amp;Job_DID=J3S0T75WSZDB3LVYPPS&amp;SiteID=cbnsv&amp;VID=VX5BD07E50F82D11ECAFDA2BF8D25F83C223113H&amp;sc_cmp1=JS_JobDetails_ApplyNow&amp;TN_DID=TNKD38560K16M285NSH4&amp;language=fr\">Postuler<\/a><\/p>\n\n\n\n<p id=\"shareThisJDP\">Partager cette offre avec<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/platform-cdn.sharethis.com\/img\/facebook.svg\" alt=\"facebook sharing button\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/platform-cdn.sharethis.com\/img\/twitter.svg\" alt=\"twitter sharing button\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/platform-cdn.sharethis.com\/img\/linkedin.svg\" alt=\"linkedin sharing button\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/platform-cdn.sharethis.com\/img\/email.svg\" alt=\"email sharing button\" \/><\/figure>\n\n\n\n<p>Description du posteR\u00e9f\u00e9rence :TEC\/0322\/002678<\/p>\n\n\n\n<p>Type de contrat :&nbsp;CDI<\/p>\n\n\n\n<p>M\u00e9tier\/Sp\u00e9cialit\u00e9 :&nbsp;Informatique \/ T\u00e9l\u00e9com \/ Internet<\/p>\n\n\n\n<p>Localisation g\u00e9ographique :<br>Pays : Cameroun<br>Ville : Douala, R\u00e9gion du Littoral, CM<\/p>\n\n\n\n<p><strong>Notre soci\u00e9t\u00e9 :&nbsp;<\/strong><\/p>\n\n\n\n<p>Acteur majeur du recrutement en Afrique Centrale, Apave International vous propose chaque semaine de nombreuses opportunit\u00e9s de carri\u00e8re au sein d&rsquo;entreprises priv\u00e9es ou publiques et d&rsquo;Institutions Internationales.<\/p>\n\n\n\n<p><strong>Mission :&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Missions Principales:<\/strong><\/p>\n\n\n\n<p><strong>IT<\/strong><\/p>\n\n\n\n<ul><li>Configurer, installer et remplacer les \u00e9quipements r\u00e9seaux tant OFFSHORE qu\u2019en ONSHORE<\/li><li>Assurer l&rsquo;entretien pr\u00e9ventif et curatif des \u00e9quipements r\u00e9seaux (Switches, routeurs, firewall, bornes WIFI, contr\u00f4leurs WIFI\u2026).<\/li><li>Suivre le stock des \u00e9quipements NETWORK<\/li><li>Capacit\u00e9 \u00e0 travailler de fa\u00e7on autonome.<\/li><\/ul>\n\n\n\n<p><strong>QHSE<\/strong><\/p>\n\n\n\n<p>&nbsp; &nbsp; \u2022 Respecter les r\u00e8gles QHSE de l\u2019entreprise<\/p>\n\n\n\n<p><strong>ACTIVITES<\/strong><\/p>\n\n\n\n<p><strong>IT:<\/strong><\/p>\n\n\n\n<ul><li>Suivi du stock network (Faire mensuellement l\u2019\u00e9tat de son stock et lancer les commandes).<\/li><li>C\u00e2bler ou mettre en place les points d\u2019acc\u00e8s aux r\u00e9seaux suivant les normes \u00e9dict\u00e9es par l\u2019IT-HQ.<\/li><li>Elaborer les cahiers de charges des travaux de c\u00e2blage cuivre et fibre optique suivant les recommandations de l\u2019IT-HQ.<\/li><li>Suivre les travaux de c\u00e2blage cuivre et fibre optique de la filiale<\/li><li>Documenter et mettre \u00e0 jour la documentation du r\u00e9seau d\u2019acc\u00e8s.<\/li><li>Tenir en conformit\u00e9 les baies et les locaux techniques de la filiale suivant les recommandations de l\u2019IT-HQ.<\/li><li>Superviser l\u2019ensemble du r\u00e9seau \u00e0 travers l\u2019outil de monitoring (PRTG) en place et fournir un rapport hebdomadaire de supervision.<\/li><li>Acquitter les incidents remont\u00e9s par l\u2019outil de supervision PRTG<\/li><li>Configurer les \u00e9quipements r\u00e9seaux suivant les recommandations de l\u2019IT-HQ.<\/li><li>Installer les \u00e9quipements r\u00e9seaux suivant les recommandations de l\u2019IT-HQ.<\/li><li>Remplacer les \u00e9quipements r\u00e9seaux d\u00e9fectueux ou obsol\u00e8te suivant les recommandations de l\u2019IT-HQ.<\/li><li>Configurer les \u00e9quipements FH suivant les recommandations de l\u2019IT-HQ.<\/li><li>Installer les \u00e9quipements FH suivant les recommandations de l\u2019IT-HQ.<\/li><li>Remplacer les \u00e9quipements FH d\u00e9fectueux ou obsol\u00e8te suivant les recommandations de l\u2019IT-HQ.<\/li><li>Renseigner sur l\u2019outil de suivi des \u00e9quipements (IT-Equipment) le statut de tous les \u00e9quipements du parc (en cours d\u2019installation, install\u00e9s, en panne, retir\u00e9).<\/li><li>Traiter les demandes de service des utilisateurs remont\u00e9es dans l\u2019Intranet.<\/li><li>Assister les usagers dans l&rsquo;utilisation des technologies de communication<\/li><li>R\u00e9diger et faire valider les proc\u00e9dures d\u2019exploitation et de maintenance<\/li><li>R\u00e9aliser les sites survey pour les nouvelles installations network et radios<\/li><li>Ex\u00e9cuter le planning de maintenance pr\u00e9ventif, d\u00e9panner le mat\u00e9riel d\u00e9faillant.<\/li><\/ul>\n\n\n\n<p><strong>QHSE<\/strong><\/p>\n\n\n\n<p><br>&nbsp; &nbsp; &nbsp;\u2022 Appliquer strictement les r\u00e8glements QHSE de la filiale.<br>&nbsp; &nbsp; &nbsp;\u2022 Appliquer les r\u00e8gles m\u00e9tiers (normes et codes) et de s\u00e9curit\u00e9.<br>&nbsp; &nbsp; &nbsp;\u2022 Se conformer aux exigences des Permis de Travail (conformit\u00e9 des EPI, balisage, \u2026).<br>&nbsp; &nbsp; &nbsp;\u2022 Rapporter tout incident et accident..<\/p>\n\n\n\n<p><strong>Profil :&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>NIVEAU THEORIQUE :&nbsp;<\/strong>Dipl\u00f4me ou niveau d\u2019\u00e9tudes : Ing\u00e9nieur de terrain (BAC + 3) ayant au moins 3 ans d\u2019exp\u00e9rience en r\u00e9seaux informatiques<\/p>\n\n\n\n<p><br><strong>NIVEAU PRATIQUE<\/strong>&nbsp;:&nbsp;<br>\u2022<strong>&nbsp;Exp\u00e9rience professionnelle :&nbsp;<\/strong><\/p>\n\n\n\n<p>2&nbsp; &nbsp;\u00e0&nbsp; &nbsp;3&nbsp; &nbsp;ans&nbsp; &nbsp;d\u2019administration&nbsp; &nbsp;des&nbsp;&nbsp;&nbsp; r\u00e9seaux&nbsp;&nbsp;&nbsp; sous&nbsp;&nbsp;&nbsp; l\u2019environnement&nbsp;&nbsp;&nbsp; du&nbsp;&nbsp;&nbsp; mat\u00e9riel&nbsp;&nbsp;&nbsp; CISCO&nbsp;&nbsp;&nbsp; (C3750 ; C2800 ;C3800 ;ASR ;C2601) et protocoles (TCP\/IP, spanning-tree, MAC, vlan, trunking 802.1q,\u2026, Vrf,CIDR, HSRP,VRRP,MPLS, OSPF, BGP, routage statique \u2026) ; de s\u00e9curit\u00e9 JUNIPER &amp; Fortigate , de c\u00e2blage Ethernet et fibre optique. Notions en t\u00e9l\u00e9phonie IP, faisceaux hertzien (PtP et PMP) et transmission par satellite.<\/p>\n\n\n\n<p><strong>Connaissances&nbsp;:<\/strong><\/p>\n\n\n\n<ul><li>C\u00e2blage Ethernet et fibre optique<\/li><li>Les r\u00e9seaux IP (LAN et WAN) &#8211; routage dynamique OSPF\/ BGP, MPLS, vrf,.<\/li><li>Les r\u00e9seaux radio\u00e9lectriques.<\/li><li>La configuration des \u00e9quipements CISCO ; Juniper et Fortigate<\/li><li>L\u2019installation des \u00e9quipements CISCO ; Juniper et Fortigate<\/li><li>La t\u00e9l\u00e9phonie sur IP.<\/li><li>Les protocoles de routage statiques et dynamiques<\/li><li>EXCEL ; Word ; tftp\u2026.<\/li><li>Le d\u00e9placement et le travail dans un local technique.<\/li><\/ul>\n\n\n\n<p><strong>Etre capable de&nbsp;:<\/strong><\/p>\n\n\n\n<ul><li>Lire, analyser et interpr\u00e9ter les alertes \/ \u00e9v\u00e8nements (journal d\u2019\u00e9v\u00e8nements) sur les \u00e9quipements r\u00e9seaux (Switches ; routeurs et firewall).<\/li><li>Lire, analyser et interpr\u00e9ter les alertes \/\u00e9v\u00e8nements (journal d\u2019\u00e9v\u00e8nements) sur les \u00e9quipements de transmission (Radios PtP et PMP).<\/li><li>Poser un diagnostic coh\u00e9rent sur un incident r\u00e9seau et \/ou de transmission<\/li><li>R\u00e9diger un rapport coh\u00e9rent sur un incident<\/li><li>Configurer et mettre en service un \u00e9quipement r\u00e9seau (switch ; routeur ; firewall) et de transmission (radio ptp et PMP).<\/li><li>Charger la configuration ou l\u2019IOS sur un \u00e9quipement r\u00e9seau ou de&nbsp; transmission via tftp.<\/li><li>Organiser et planifier son travail&nbsp;<\/li><li>Escalader un probl\u00e8me qu\u2019il n\u2019arrive pas \u00e0 r\u00e9soudre.<\/li><li>R\u00e9aliser un d\u00e9pannage r\u00e9seau de fa\u00e7on autonome<\/li><li>Pertinent dans l\u2019analyse des incidents&nbsp;<\/li><li>Lire une architecture physique et logique d\u2019un r\u00e9seau.<\/li><\/ul>\n\n\n\n<p><strong>Savoir \u00eatre :<\/strong>&nbsp;<\/p>\n\n\n\n<ul><li>Esprit d\u2019\u00e9quipe<\/li><li>Autonome<\/li><li>Respect des hi\u00e9rarchies et des recommandations.<\/li><li>Esprit de synth\u00e8se.<\/li><li>Sens \u00e9lev\u00e9 d\u2019initiative et d\u2019anticipation.<\/li><li>Grande capacit\u00e9 d\u2019adaptation, ouverture d\u2019esprit.<\/li><li>Dynamisme, R\u00e9activit\u00e9<\/li><li>Rigoureux<\/li><li>Sens du service, r\u00e9sultat et du respect des proc\u00e9dures et des d\u00e9lais.<\/li><li>Communication, sens relationnel et de l\u2019\u00e9coute.<\/li><li>R\u00e9sistance \u00e0 la pression&nbsp;<\/li><li>Curiosit\u00e9 intellectuelle.<\/li><\/ul>\n\n\n\n<p><strong>CONTRAINTES LIEES AU POSTE&nbsp;<\/strong><\/p>\n\n\n\n<p>\u2022 Travail les Week-ends et jours f\u00e9ri\u00e9s.<br>\u2022 Travail sur site offshore et on shore.<br>\u2022 Travail sous pression.<br>\u2022 Joignable 24h\/24.<\/p>\n\n\n\n<p>Niveau d&rsquo;\u00e9tudes : LICENCE \/ BAC+3<\/p>\n\n\n\n<p>Sp\u00e9cialisation :&nbsp;Informatique \/ High Tech \/ Telecoms<\/p>\n\n\n\n<p>Niveau d&rsquo;exp\u00e9rience :&nbsp;Premi\u00e8re exp\u00e9rience (de 1 \u00e0 3 ans)<\/p>\n\n\n\n<p>Langues :&nbsp;<br>Fran\u00e7ais&nbsp;:&nbsp;Bonne pratique<br>Anglais&nbsp;:&nbsp;Bonne pratique<\/p>\n\n\n\n<p>Crit\u00e8res du poste<\/p>\n\n\n\n<p><strong>NIVEAU THEORIQUE :&nbsp;<\/strong>Dipl\u00f4me ou niveau d\u2019\u00e9tudes : Ing\u00e9nieur de terrain (BAC + 3) ayant au moins 3 ans d\u2019exp\u00e9rience en r\u00e9seaux informatiques<\/p>\n\n\n\n<p><br><strong>NIVEAU PRATIQUE<\/strong>&nbsp;:&nbsp;<br>\u2022<strong>&nbsp;Exp\u00e9rience professionnelle :&nbsp;<\/strong><\/p>\n\n\n\n<p>2&nbsp; &nbsp;\u00e0&nbsp; &nbsp;3&nbsp; &nbsp;ans&nbsp; &nbsp;d\u2019administration&nbsp; &nbsp;des&nbsp;&nbsp;&nbsp; r\u00e9seaux&nbsp;&nbsp;&nbsp; sous&nbsp;&nbsp;&nbsp; l\u2019environnement&nbsp;&nbsp;&nbsp; du&nbsp;&nbsp;&nbsp; mat\u00e9riel&nbsp;&nbsp;&nbsp; CISCO&nbsp;&nbsp;&nbsp; (C3750 ; C2800 ;C3800 ;ASR ;C2601) et protocoles (TCP\/IP, spanning-tree, MAC, vlan, trunking 802.1q,\u2026, Vrf,CIDR, HSRP,VRRP,MPLS, OSPF, BGP, routage statique \u2026) ; de s\u00e9curit\u00e9 JUNIPER &amp; Fortigate , de c\u00e2blage Ethernet et fibre optique. Notions en t\u00e9l\u00e9phonie IP, faisceaux hertzien (PtP et PMP) et transmission par satellite.<\/p>\n\n\n\n<p><strong>Connaissances&nbsp;:<\/strong><\/p>\n\n\n\n<ul><li>C\u00e2blage Ethernet et fibre optique<\/li><li>Les r\u00e9seaux IP (LAN et WAN) &#8211; routage dynamique OSPF\/ BGP, MPLS, vrf,.<\/li><li>Les r\u00e9seaux radio\u00e9lectriques.<\/li><li>La configuration des \u00e9quipements CISCO ; Juniper et Fortigate<\/li><li>L\u2019installation des \u00e9quipements CISCO ; Juniper et Fortigate<\/li><li>La t\u00e9l\u00e9phonie sur IP.<\/li><li>Les protocoles de routage statiques et dynamiques<\/li><li>EXCEL ; Word ; tftp\u2026.<\/li><li>Le d\u00e9placement et le travail dans un local technique.<\/li><\/ul>\n\n\n\n<p><strong>Etre capable de&nbsp;:<\/strong><\/p>\n\n\n\n<ul><li>Lire, analyser et interpr\u00e9ter les alertes \/ \u00e9v\u00e8nements (journal d\u2019\u00e9v\u00e8nements) sur les \u00e9quipements r\u00e9seaux (Switches ; routeurs et firewall).<\/li><li>Lire, analyser et interpr\u00e9ter les alertes \/\u00e9v\u00e8nements (journal d\u2019\u00e9v\u00e8nements) sur les \u00e9quipements de transmission (Radios PtP et PMP).<\/li><li>Poser un diagnostic coh\u00e9rent sur un incident r\u00e9seau et \/ou de transmission<\/li><li>R\u00e9diger un rapport coh\u00e9rent sur un incident<\/li><li>Configurer et mettre en service un \u00e9quipement r\u00e9seau (switch ; routeur ; firewall) et de transmission (radio ptp et PMP).<\/li><li>Charger la configuration ou l\u2019IOS sur un \u00e9quipement r\u00e9seau ou de&nbsp; transmission via tftp.<\/li><li>Organiser et planifier son travail&nbsp;<\/li><li>Escalader un probl\u00e8me qu\u2019il n\u2019arrive pas \u00e0 r\u00e9soudre.<\/li><li>R\u00e9aliser un d\u00e9pannage r\u00e9seau de fa\u00e7on autonome<\/li><li>Pertinent dans l\u2019analyse des incidents&nbsp;<\/li><li>Lire une architecture physique et logique d\u2019un r\u00e9seau.<\/li><\/ul>\n\n\n\n<p><strong>Savoir \u00eatre :<\/strong>&nbsp;<\/p>\n\n\n\n<ul><li>Esprit d\u2019\u00e9quipe<\/li><li>Autonome<\/li><li>Respect des hi\u00e9rarchies et des recommandations.<\/li><li>Esprit de synth\u00e8se.<\/li><li>Sens \u00e9lev\u00e9 d\u2019initiative et d\u2019anticipation.<\/li><li>Grande capacit\u00e9 d\u2019adaptation, ouverture d\u2019esprit.<\/li><li>Dynamisme, R\u00e9activit\u00e9<\/li><li>Rigoureux<\/li><li>Sens du service, r\u00e9sultat et du respect des proc\u00e9dures et des d\u00e9lais.<\/li><li>Communication, sens relationnel et de l\u2019\u00e9coute.<\/li><li>R\u00e9sistance \u00e0 la pression&nbsp;<\/li><li>Curiosit\u00e9 intellectuelle.<\/li><\/ul>\n\n\n\n<p><strong>CONTRAINTES LIEES AU POSTE&nbsp;<\/strong><\/p>\n\n\n\n<p>\u2022 Travail les Week-ends et jours f\u00e9ri\u00e9s.<br>\u2022 Travail sur site offshore et on shore.<br>\u2022 Travail sous pression.<br>\u2022 Joignable 24h\/24.<a href=\"https:\/\/application.careerbuilder1.eu\/apave\/apply\/cb1\/J3S0T75WSZDB3LVYPPS?IPath=TNJob&amp;Job_DID=J3S0T75WSZDB3LVYPPS&amp;SiteID=cbnsv&amp;VID=VX5BD07E50F82D11ECAFDA2BF8D25F83C223113H&amp;sc_cmp1=JS_JobDetails_ApplyNow&amp;TN_DID=TNKD38560K16M285NSH4&amp;language=fr\">Postuler<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Network Administrator H\/FLieu Douala,&nbsp;LittoralPubli\u00e9 6 joursCat\u00e9gorie du poste Informatique \/ T\u00e9l\u00e9communicationsType de poste CDI &#8211; temps pleinExp\u00e9rience Non pr\u00e9cis\u00e9Postuler Partager cette offre avec Description du&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[21],"tags":[],"villes":[135],"contrats":[234],"diplomes":[162,212],"louma_meta":{"emploi_title":"Network Administrator H\/F","emplois_employeur":2981,"emplois_date_publication":"2022-07-11","emplois_heure_publication":"","emplois_date_cloture":"2022-07-31","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"https:\/\/application.careerbuilder1.eu\/apave\/apply\/cb1\/J3S0T75WSZDB3LVYPPS?IPath=TNJob&Job_DID=J3S0T75WSZDB3LVYPPS&SiteID=cbnsv&VID=VX5BD07E50F82D11ECAFDA2BF8D25F83C223113H&sc_cmp1=JS_JobDetails_ApplyNow&TN_DID=TNKD38560K16M285NSH4&language=fr"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/32061"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=32061"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/32061\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/2982"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=32061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=32061"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=32061"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=32061"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=32061"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=32061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}