{"id":31754,"date":"2022-06-27T15:40:29","date_gmt":"2022-06-27T13:40:29","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=31754"},"modified":"2022-06-27T15:40:34","modified_gmt":"2022-06-27T13:40:34","slug":"un-directeur-administratif-et-financier","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/un-directeur-administratif-et-financier\/","title":{"rendered":"UN DIRECTEUR ADMINISTRATIF ET FINANCIER"},"content":{"rendered":"\n<p>APPEL A CANDIDATURE POUR LE RECRUTEMENT D\u2019UN DIRECTEUR ADMINISTRATIF ET<br>FINANCIER<\/p>\n\n\n\n<p><br>PATECO GROUP recrute pour des besoins de service un Directeur<br>Administratif et Financier (DAF). En r\u00e9alit\u00e9, il s\u2019agit d\u2019une firme dont le si\u00e8ge<br>social est situ\u00e9 \u00e0 Yaound\u00e9, au lieu-dit Golf. Pr\u00e9sente dans plusieurs secteurs<br>d\u2019activit\u00e9s au Cameroun, le holding comprend en son sein une soci\u00e9t\u00e9 de<br>gardiennage : KORA SECURITY S.A, une Soci\u00e9t\u00e9 de P\u00eache Industrielle :<br>INTERFISH S.A, une Soci\u00e9t\u00e9 Civile Immobili\u00e8re : SCI QATARA ainsi que<br>d\u2019autres projets en cours d\u2019impl\u00e9mentation.<\/p>\n\n\n\n<p><br>MISSIONS<\/p>\n\n\n\n<p><br>Plac\u00e9 sous l\u2019autorit\u00e9 de la Direction g\u00e9n\u00e9rale, le DAF participe \u00e0 l\u2019\u00e9laboration de la<br>strat\u00e9gie financi\u00e8re du groupe et assure la mise en \u0153uvre de celle-ci. En cons\u00e9quence,<br>il traduit les objectifs du Groupe en donn\u00e9es chiffr\u00e9es \u00e0 r\u00e9aliser et d\u00e9finit les moyens<br>financiers, humains et technologiques \u00e0 mettre en \u0153uvre pour r\u00e9aliser ces objectifs.<br><\/p>\n\n\n\n<p>Il se pose \u00e9galement comme conseiller des dirigeants de la structure et est amen\u00e9 \u00e0<br>participer au comit\u00e9 de direction.<\/p>\n\n\n\n<p><br>Il coordonne et supervise les services de la comptabilit\u00e9 et des finances, le service du<br>personnel, l\u2019administration, les services g\u00e9n\u00e9raux. A cet effet il d\u00e9cline pour chaque<br><\/p>\n\n\n\n<p>direction ses objectifs propres et r\u00e9sultats annuels attendus au plan strat\u00e9gique. Il suit<br>r\u00e9guli\u00e8rement via des indicateurs pertinents, le niveau de performance des diff\u00e9rentes<br>directions dans la r\u00e9alisation de leurs objectifs et pr\u00e9conise en cas de besoin des mesures<br>de recadrage.<\/p>\n\n\n\n<p> Il assure par ailleurs le contr\u00f4le et la sauvegarde des actifs du groupe. A<br>ce titre le DAF est tenu d\u2019informer en permanence la Direction G\u00e9n\u00e9rale sur la sant\u00e9 de<br>l\u2019entreprise afin de veiller sur son existence et son d\u00e9veloppement.<\/p>\n\n\n\n<p>I. RESPONSABILITES &amp; ATTRIBUTIONS<\/p>\n\n\n\n<p><br>En tant que responsable de la Direction Administrative et Financi\u00e8re, il supervise aussi<br>bien les services administratifs que les services financiers, \u00e0 cet effet :<br>\u27a2 Il veille au respect des proc\u00e9dures administratives et financi\u00e8res du groupe ;<br>\u27a2 Il coordonne et supervise principalement la comptabilit\u00e9, les d\u00e9clarations<br>comptables et fiscales, la gestion budg\u00e9taire et le reporting dont il participe<br>activement \u00e0 l\u2019\u00e9laboration ;<br>\u27a2 Il est responsable du processus d\u2019\u00e9laboration, de suivi et de contr\u00f4le budg\u00e9taire ;<br>\u27a2 Il est responsable de l\u2019\u00e9laboration des plans de tr\u00e9sorerie et de la gestion<br>quotidienne de la tr\u00e9sorerie ;<br>\u27a2 Il met en place des outils d\u2019aide \u00e0 la d\u00e9cision et les tableaux de bord et s\u2019assure<br>de leur bon fonctionnement ;<br>\u27a2 Il est le garant du respect des obligations l\u00e9gales, administratives et<br>r\u00e9glementaires de l\u2019entreprise. A ce titre il est tenu d\u2019informer et conseiller la<br>Direction en mati\u00e8re d\u2019obligations l\u00e9gales, fiscales et comptables ;<br>\u27a2 Il est responsable de l\u2019ex\u00e9cution des d\u00e9clarations fiscales et comptables<br>mensuelles, ainsi que de la liasse fiscale annuelle ;<br>\u27a2 Il est en charge des relations avec les \u00e9tablissements financiers et les<br>administrations.<\/p>\n\n\n\n<p><br>II. QUALIFICATIONS<\/p>\n\n\n\n<p><br>\u2022 Bac+5 min en Finance\/Audit &amp; Contr\u00f4le de gestion ;<br>\u2022 Exp\u00e9rience d\u2019au moins 10 ans dont 5 ans dans un poste similaire ou dans un<br>cabinet d\u2019audit de premier plan ;<br>\u2022 Ag\u00e9 d\u2019au moins 35 ans et au plus 50 ans \u00e0 la date de candidature ;<br>\u2022 Rigoureux , capable de travailler sous pression, proactif et multit\u00e2che.<br>I<br>\u2022 Bonnes capacit\u00e9s manag\u00e9riales ;<br>\u2022 Ma\u00eetrise parfaite d\u2019une des langues officielles, notamment l\u2019anglais et\/ou<br>l e f r a n \u00e7 a i s (\u00e9crit et parl\u00e9) et bonne assimilation de la seconde ;<br>\u2022 Excellente capacit\u00e9 de relecture des notes de synth\u00e8se, de r\u00e9daction de rapports<br>financiers et de correspondances administratives ;<br>\u2022 Maitrise du Pack Office et des logiciels de gestion avec une capacit\u00e9 de synth\u00e8se<br>et de pr\u00e9paration de rapports et de pr\u00e9sentations ;<\/p>\n\n\n\n<p><br>III. CONTACTS<\/p>\n\n\n\n<ul><li>Disponibilit\u00e9 : D\u00e8s que possible<\/li><li>Date de prise de fonction : 01\/07\/2022<\/li><li>Transmettre 1 CV et 1 Lettre de motivation \u00e0 l\u2019adresse email Korasec@outlook.fr,<br>avec en objet l\u2019intitul\u00e9 du poste.<\/li><li>T\u00e9l\u00e9phone : + 237 6 71 06 60 18<\/li><\/ul>\n\n\n\n<p>I. RESPONSABILITES &amp; ATTRIBUTIONS<\/p>\n\n\n\n<p><br>En tant que responsable de la Direction Administrative et Financi\u00e8re, il supervise aussi<br>bien les services administratifs que les services financiers, \u00e0 cet effet :<br>\u27a2 Il veille au respect des proc\u00e9dures administratives et financi\u00e8res du groupe ;<br>\u27a2 Il coordonne et supervise principalement la comptabilit\u00e9, les d\u00e9clarations<br>comptables et fiscales, la gestion budg\u00e9taire et le reporting dont il participe<br>activement \u00e0 l\u2019\u00e9laboration ;<br>\u27a2 Il est responsable du processus d\u2019\u00e9laboration, de suivi et de contr\u00f4le budg\u00e9taire ;<br>\u27a2 Il est responsable de l\u2019\u00e9laboration des plans de tr\u00e9sorerie et de la gestion<br>quotidienne de la tr\u00e9sorerie ;<br>\u27a2 Il met en place des outils d\u2019aide \u00e0 la d\u00e9cision et les tableaux de bord et s\u2019assure<br>de leur bon fonctionnement ;<br>\u27a2 Il est le garant du respect des obligations l\u00e9gales, administratives et<br>r\u00e9glementaires de l\u2019entreprise. A ce titre il est tenu d\u2019informer et conseiller la<br>Direction en mati\u00e8re d\u2019obligations l\u00e9gales, fiscales et comptables ;<br>\u27a2 Il est responsable de l\u2019ex\u00e9cution des d\u00e9clarations fiscales et comptables<br>mensuelles, ainsi que de la liasse fiscale annuelle ;<br>\u27a2 Il est en charge des relations avec les \u00e9tablissements financiers et les<br>administrations.<\/p>\n\n\n\n<p><br>II. QUALIFICATIONS<\/p>\n\n\n\n<p><br>\u2022 Bac+5 min en Finance\/Audit &amp; Contr\u00f4le de gestion ;<br>\u2022 Exp\u00e9rience d\u2019au moins 10 ans dont 5 ans dans un poste similaire ou dans un<br>cabinet d\u2019audit de premier plan ;<br>\u2022 Ag\u00e9 d\u2019au moins 35 ans et au plus 50 ans \u00e0 la date de candidature ;<br>\u2022 Rigoureux , capable de travailler sous pression, proactif et multit\u00e2che.<br><\/p>\n\n\n\n<p><br>\u2022 Bonnes capacit\u00e9s manag\u00e9riales ;<br>\u2022 Ma\u00eetrise parfaite d\u2019une des langues officielles, notamment l\u2019anglais et\/ou<br>l e f r a n \u00e7 a i s (\u00e9crit et parl\u00e9) et bonne assimilation de la seconde ;<br>\u2022 Excellente capacit\u00e9 de relecture des notes de synth\u00e8se, de r\u00e9daction de rapports<br>financiers et de correspondances administratives ;<br>\u2022 Maitrise du Pack Office et des logiciels de gestion avec une capacit\u00e9 de synth\u00e8se<br>et de pr\u00e9paration de rapports et de pr\u00e9sentations ;<br>III. CONTACTS<\/p>\n\n\n\n<ul><li>Disponibilit\u00e9 : D\u00e8s que possible<\/li><li>Date de prise de fonction : 01\/07\/2022<\/li><li>Transmettre 1 CV et 1 Lettre de motivation \u00e0 l\u2019adresse email Korasec@outlook.fr,<br>avec en objet l\u2019intitul\u00e9 du poste.<\/li><li>T\u00e9l\u00e9phone : + 237 6 71 06 60 18<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>APPEL A CANDIDATURE POUR LE RECRUTEMENT D\u2019UN DIRECTEUR ADMINISTRATIF ETFINANCIER PATECO GROUP recrute pour des besoins de service un DirecteurAdministratif et Financier (DAF). En r\u00e9alit\u00e9,&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[21,23],"tags":[],"villes":[135],"contrats":[234],"diplomes":[162,212],"louma_meta":{"emploi_title":"UN DIRECTEUR ADMINISTRATIF ET FINANCIER","emplois_employeur":3046,"emplois_date_publication":"2022-06-27","emplois_heure_publication":"","emplois_date_cloture":"2022-06-30","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"korasec@outlook.fr"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/31754"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=31754"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/31754\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=31754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=31754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=31754"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=31754"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=31754"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=31754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}