{"id":31736,"date":"2022-06-26T12:16:36","date_gmt":"2022-06-26T10:16:36","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=31736"},"modified":"2022-06-26T12:16:39","modified_gmt":"2022-06-26T10:16:39","slug":"apporteurs-daffaires","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/apporteurs-daffaires\/","title":{"rendered":"Apporteurs d&rsquo;Affaires"},"content":{"rendered":"\n<p>OFFRES D\u2019EMPLOI : NT assurance recherche des<br><strong>Apporteurs d&rsquo;affaires<\/strong><\/p>\n\n\n\n<p><br>Vous \u00eates un(e) jeune sans emploi, Vous \u00eates un(e) \u00e9l\u00e8ve, \u00e9tudiant(e) ou travailleur en temps partiel.<\/p>\n\n\n\n<p><br>Vous voulez rendre vos vacances, temps libres utiles et rentables o\u00f9 arrondir vos fin du mois, Cette offre vous concerne !!!<\/p>\n\n\n\n<p> Nous recherchons des apporteur d&rsquo;affaires libres et dynamiques qui seront renumer\u00e9s par client apport\u00e9 le taux de commission est n\u00e9gociable.<\/p>\n\n\n\n<p><br>Vous avez un ami, un membre de la famille ou tout simplement une connaissance faite le souscrire sa prochaine assurance automobile chez nous et gagnez directement vos commissions<\/p>\n\n\n\n<p><br>18 ans minimum<br>Documents de candidature<br>Curriculum Vitae<br>Ne payer aucun frais pour \u00eatre recrut\u00e9 \u00bb.<br>Envoyer vos dossiers de candidature par mail \u00e0 l\u2019adresse snouma65@gmail.com ou appeler au num\u00e9ro de t\u00e9l\u00e9phone suivant : 691057387 whatsapp<\/p>\n\n\n\n<p><br>Profil du candidat<\/p>\n\n\n\n<p>Conditions de travail : Prime de rendement n\u00e9gociable en fonction des clients apport\u00e9s<\/p>\n","protected":false},"excerpt":{"rendered":"<p>OFFRES D\u2019EMPLOI : NT assurance recherche desApporteurs d&rsquo;affaires Vous \u00eates un(e) jeune sans emploi, Vous \u00eates un(e) \u00e9l\u00e8ve, \u00e9tudiant(e) ou travailleur en temps partiel. Vous&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[343],"tags":[],"villes":[135],"contrats":[234],"diplomes":[212],"louma_meta":{"emploi_title":"Apporteurs d'Affaires","emplois_employeur":3046,"emplois_date_publication":"2022-06-26","emplois_heure_publication":"","emplois_date_cloture":"2022-06-30","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"snouma65@gmail.com "},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/31736"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=31736"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/31736\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=31736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=31736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=31736"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=31736"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=31736"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=31736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}