{"id":31717,"date":"2022-06-25T09:59:33","date_gmt":"2022-06-25T07:59:33","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=31717"},"modified":"2022-06-25T09:59:36","modified_gmt":"2022-06-25T07:59:36","slug":"offre-demploi-agronome-f-h","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/offre-demploi-agronome-f-h\/","title":{"rendered":"Offre d&#8217;emploi: Agronome (F\/H)"},"content":{"rendered":"\n<p>Offre d&#8217;emploi: Agronome (F\/H)<\/p>\n\n\n\n<p>Dans une micro-ferme (2500 m\u00b2) qui produit sous serre en hydroponie et en permaculture, le (la) chef(fe) de culture coordonne, planifie et organise la production mara\u00eech\u00e8re en suivant les orientations donn\u00e9es par la direction.<\/p>\n\n\n\n<p>Missions<\/p>\n\n\n\n<p>Superviser les travaux de cultures auxquels vous participez activement.<\/p>\n\n\n\n<p>Assurez le suivi technique des productions en terme de volume et de qualit\u00e9.<\/p>\n\n\n\n<p> \u2022 Remontez les probl\u00e8mes rencontr\u00e9s et \u00eates force de proposition pour trouver des solutions.<\/p>\n\n\n\n<p>Profil recherch\u00e9<\/p>\n\n\n\n<p>Homme ou femme : le poste convient parfaitement \u00e0 une femme<\/p>\n\n\n\n<p>\u2022 Minimum BAC+3 dans le domaine agricole Exp\u00e9rience en mara\u00eechage<\/p>\n\n\n\n<p>Imp\u00e9rativement habiter ou s&rsquo;installer \u00e0 Ngoumou (non n\u00e9gociable) Travail du lundi au samedi (non n\u00e9gociable)<\/p>\n\n\n\n<p>Aptitudes personnelles<\/p>\n\n\n\n<p>Int\u00e9grit\u00e9 morale<\/p>\n\n\n\n<p>Rigueur<\/p>\n\n\n\n<p>Excellence et sens du travail bien fait<\/p>\n\n\n\n<p>Autonomie<\/p>\n\n\n\n<p>Capacit\u00e9 d&rsquo;adaptation et d&rsquo;apprentissage<\/p>\n\n\n\n<p>Management<\/p>\n\n\n\n<p>\u2022 Interaction permanente et forte avec la direction<\/p>\n\n\n\n<p>Salaires et avantages<\/p>\n\n\n\n<p>70 000 FCFA par mois + prime mensuelle sur r\u00e9sultats<\/p>\n\n\n\n<p>Cong\u00e9s pay\u00e9s<\/p>\n\n\n\n<p>Pour postuler, merci d&rsquo;envoyer votre CV+ Lettre de motivation \u00e0 : osei.ferme@gmail.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Offre d&#8217;emploi: Agronome (F\/H) Dans une micro-ferme (2500 m\u00b2) qui produit sous serre en hydroponie et en permaculture, le (la) chef(fe) de culture coordonne, planifie&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[2993],"tags":[],"villes":[135,136],"contrats":[234],"diplomes":[212],"louma_meta":{"emploi_title":"Offre d'emploi: Agronome (F\/H)","emplois_employeur":3046,"emplois_date_publication":"2022-06-25","emplois_heure_publication":"","emplois_date_cloture":"2022-06-30","emplois_heure_cloture":"","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"osei.ferme@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/31717"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=31717"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/31717\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=31717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=31717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=31717"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=31717"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=31717"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=31717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}