{"id":31585,"date":"2022-06-20T00:31:41","date_gmt":"2022-06-19T22:31:41","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=31585"},"modified":"2022-06-20T00:31:46","modified_gmt":"2022-06-19T22:31:46","slug":"directeur-de-magasin-directeur-des-operations-directeur-commercial-acheteurs-seniors-controleurs-de-gestion","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/directeur-de-magasin-directeur-des-operations-directeur-commercial-acheteurs-seniors-controleurs-de-gestion\/","title":{"rendered":"Directeur de Magasin, Directeur des Op\u00e9rations, Directeur Commercial, Acheteurs Seniors, Contr\u00f4leurs de Gestion"},"content":{"rendered":"\n<pre class=\"wp-block-code\"><code>Titre du poste : Directeur de Magasin, Directeur des Op\u00e9rations, Directeur Commercial, Acheteurs Seniors, Controleurs de Gestion ,\ndate d'expiration : 2022-06-25,\nentreprise  : BASSAGAL CONSULTING AFRICA,\nPays : cameroun,\nvilles : Douala et Yaound\u00e9,\ncontact pour postuler : joseph.bassagal@bassagal-consulting.com ; yannick.billigha@bassagal-consulting.com\n\nDans le cadre de son d\u00e9veloppement, une ENSEIGNE INTERNATIONALE DE LA GRANDE DISTRIBUTION recherche des candidats exp\u00e9riment\u00e9s aux postes suivants :\n \u2022 Directeur de magasin (R\u00e9f. DM0122)\n \u2022 Directeur des op\u00e9rations (R\u00e9f. DO0122) \n\u2022 Directeur commercial (R\u00e9f. RCM0422)\n \u2022 Acheteurs seniors (R\u00e9f. AI0322)\n \u2022 Contr\u00f4leur de gestion (R\u00e9f. CG0222)\n\n Les postes sont bas\u00e9s \u00e0 Douala et Yaound\u00e9 et une exp\u00e9rience dans la grande distribution est souhait\u00e9e. Si vous \u00eates int\u00e9ress\u00e9 (e)s par ce challenge et justifiez d\u2019une exp\u00e9rience av\u00e9r\u00e9e \u00e0 l\u2019un de ces postes, pri\u00e8re d\u2019envoyer votre CV en pr\u00e9cisant la r\u00e9f\u00e9rence \u00e0 l\u2019une des adresses suivantes : joseph.bassagal@bassagal-consulting.com ou yannick.billigha@bassagal-consulting.com \u27a2 La date limite de recevabilit\u00e9 des candidatures est fix\u00e9e au 25 juin 2022 \u27a2 Seuls les candidats shortlist\u00e9s seront contact\u00e9s&nbsp;<\/code><\/pre>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[113],"tags":[],"villes":[135,136],"contrats":[234],"diplomes":[162,212],"louma_meta":{"emploi_title":"Directeur de Magasin, Directeur des Op\u00e9rations, Directeur Commercial, Acheteurs Seniors, Contr\u00f4leurs de Gestion","emplois_employeur":4772,"emplois_date_publication":"2022-06-19","emplois_heure_publication":"","emplois_date_cloture":"2022-06-25","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":" joseph.bassagal@bassagal-consulting.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/31585"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=31585"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/31585\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/4773"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=31585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=31585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=31585"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=31585"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=31585"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=31585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}